{"id":315,"date":"2022-04-02T10:53:40","date_gmt":"2022-04-02T10:53:40","guid":{"rendered":"https:\/\/splineshaft.top\/china-s45c-carbon-steel-forged-spline-shaft-price-with-chrome-plating-surface-treatment-with-ce-certificate-top-quality-good-price\/"},"modified":"2022-04-02T10:53:40","modified_gmt":"2022-04-02T10:53:40","slug":"china-s45c-carbon-steel-forged-spline-shaft-price-with-chrome-plating-surface-treatment-with-ce-certificate-top-quality-good-price","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/pt\/china-s45c-carbon-steel-forged-spline-shaft-price-with-chrome-plating-surface-treatment-with-ce-certificate-top-quality-good-price\/","title":{"rendered":"Eixo estriado forjado em a\u00e7o carbono S45c da China com tratamento de superf\u00edcie cromado e certificado CE. Alta qualidade e bom pre\u00e7o."},"content":{"rendered":"<p>\n<h2>Descri\u00e7\u00e3o do item<\/h2>\n<p>\n<p><p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\n<p>\u00a0<\/p>\n<p>Descri\u00e7\u00e3o do produto<\/p>\n<p>\n<table>\n<colgroup>\n<col \/>\n<col \/><\/colgroup>\n<tbody>\n<tr>\n<td>T\u00edtulo da solu\u00e7\u00e3o<\/td>\n<td>Eixo de a\u00e7o forjado\u00a0<\/td>\n<\/tr>\n<tr>\n<td>Material<\/td>\n<td>A\u00e7o 45# (C45), Q235 (GGP, A53, St33), a\u00e7o carbono, metal com m\u00e9dio teor de carbono,<br \/>a\u00e7o de liga met\u00e1lica inoxid\u00e1vel<\/td>\n<\/tr>\n<tr>\n<td>Toler\u00e2ncia\u00a0<\/td>\n<td>+\/- 0,005 mm\u00a0<\/td>\n<\/tr>\n<tr>\n<td>Padr\u00e3o\u00a0<\/td>\n<td>GB, ATSM, JIS, DIN<\/td>\n<\/tr>\n<tr>\n<td>rem\u00e9dio de calor<\/td>\n<td>Normaliza\u00e7\u00e3o, recozimento, t\u00eampera e revenido,<\/td>\n<\/tr>\n<tr>\n<td>Inspe\u00e7\u00e3o<\/td>\n<td>Teste de composi\u00e7\u00e3o qu\u00edmica, exame ultrass\u00f4nico, teste magn\u00e9tico, teste de resist\u00eancia \u00e0 tra\u00e7\u00e3o.<br \/>\u00a0Teste de impacto, verifica\u00e7\u00e3o de dureza, verifica\u00e7\u00e3o dimensional<\/td>\n<\/tr>\n<tr>\n<td>Embalagem\u00a0<\/td>\n<td>Pacote de transporte adaptado ao transporte mar\u00edtimo ou conforme as necessidades.<\/td>\n<\/tr>\n<tr>\n<td>Tempo de fornecimento<\/td>\n<td>15 a 25 dias, dependendo da quantidade do pedido.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<p><strong>Um programa de inspe\u00e7\u00e3o de qualidade rigoroso pode criar produtos de qualidade superior.<\/strong><\/p>\n<p><strong>Para cada\u00a0<\/strong><strong>Na compra, podemos oferecer relat\u00f3rios de testes qu\u00edmicos de materiais, testes de ultrassom, triagem de dureza e testes de propriedades mec\u00e2nicas.\u00a0<\/strong><strong>Inspe\u00e7\u00e3o de dimens\u00f5es, etc.<\/strong><\/p>\n<p>situa\u00e7\u00f5es de fabrica\u00e7\u00e3o<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p><p>\u00a0<\/p>\n<p>Embalagem e CZPT <\/p>\n<p><p><strong>Para evitar que os produtos acabados enferrujem e sejam danificados durante o transporte, projetaremos e elaboraremos a embalagem adequada de acordo com as necessidades.\u00a0<\/strong><strong>a forma, as dimens\u00f5es e a utiliza\u00e7\u00e3o dos produtos.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p>Perguntas frequentes<\/p>\n<p><p>\u00a0<\/p>\n<h3>P: Voc\u00ea est\u00e1 comprando e vendendo empresas ou produtores?<\/h3>\n<p><p>A: Somos uma unidade de fabrica\u00e7\u00e3o e empresa comercial.<br \/>\u00a0<\/p>\n<p>\n<p>\n<p>\n<h3>P: Qual \u00e9 o seu prazo de entrega (CZPT)?<\/h3>\n<p><p>A: Normalmente, s\u00e3o de 5 a 10 dias se os produtos estiverem em estoque. Caso contr\u00e1rio, s\u00e3o de 15 a 20 dias, dependendo da quantidade.<br \/>\u00a0<\/p>\n<p>\n<p>\n<p>\n<h3>P: Voc\u00eas fornecem amostras? S\u00e3o gratuitas ou t\u00eam custo adicional?<\/h3>\n<p><p>A: Sim, podemos oferecer-lhe a amostra gratuitamente, mas n\u00e3o ter\u00e1 de pagar os custos de envio.<br \/>\u00a0<\/p>\n<p>\n<p>\n<p>\n<h3>P: Quais s\u00e3o as suas condi\u00e7\u00f5es de pagamento?<\/h3>\n<p><p>A: Pagamento = 1000 USD, 30% T\/T em CZPT, saldo antes do envio.<br \/>Caso tenha alguma outra d\u00favida, n\u00e3o hesite em nos contatar atrav\u00e9s dos canais abaixo:<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>Para determinar o tipo, \u00e9 necess\u00e1rio observar o formato do eixo. Independentemente do tipo, o eixo dianteiro \u00e9 id\u00eantico ao eixo secund\u00e1rio. No entanto, o eixo dianteiro \u00e9 maior para permitir que o eixo intermedi\u00e1rio se encaixe dentro dele. Dessa forma, os detritos podem se comprimir como um telesc\u00f3pio durante seu movimento. O eixo dom\u00e9stico pode ter um dos quatro formatos: redondo, retangular, quadrado ou estriado. Os eixos m\u00e9tricos podem ter formato de estrela, sino ou bola de futebol americano.<br \/><img><\/p>","protected":false},"excerpt":{"rendered":"<p>Descri\u00e7\u00e3o do Item Descri\u00e7\u00e3o da Mercadoria T\u00edtulo da Solu\u00e7\u00e3o Eixo de A\u00e7o Forjado Material A\u00e7o 45# (C45), Q235 (GGP, A53, St33), a\u00e7o carbono, a\u00e7o de m\u00e9dio carbono, a\u00e7o liga inoxid\u00e1vel Toler\u00e2ncia +\/- 0,005 mm Padr\u00e3o GB, ATSM, JIS, DIN Tratamento T\u00e9rmico Normaliza\u00e7\u00e3o, recozimento, t\u00eampera e revenido Inspe\u00e7\u00e3o Teste de composi\u00e7\u00e3o qu\u00edmica, exame ultrass\u00f4nico, teste magn\u00e9tico, teste de resist\u00eancia \u00e0 tra\u00e7\u00e3o, teste de impacto, teste de dureza, teste dimensional Embalagem Embalagem adequada para transporte mar\u00edtimo ou em [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1596,1600,1601,811,1605,19,1599,1606,20,761,1094,764,765],"class_list":["post-315","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-carbon-shaft","tag-chrome-shaft","tag-chrome-steel-shaft","tag-forged-shaft","tag-s45c-steel-shaft","tag-shaft","tag-shaft-carbon","tag-shaft-chrome","tag-shaft-price","tag-shaft-steel","tag-spline-shaft","tag-steel-shaft","tag-steel-shaft-price"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}