{"id":1140,"date":"2023-02-24T18:03:09","date_gmt":"2023-02-24T18:03:09","guid":{"rendered":"http:\/\/splineshaft.top\/china-xps-flexible-rubber-coupling-with-flange-flexible-coupling-25a-25as-28as-30a-30as-50a-50as-50ac-160h-140h-25h-30h-40h-45h-50h-with-high-quality\/"},"modified":"2023-02-24T18:03:09","modified_gmt":"2023-02-24T18:03:09","slug":"china-xps-flexible-rubber-coupling-with-flange-flexible-coupling-25a-25as-28as-30a-30as-50a-50as-50ac-160h-140h-25h-30h-40h-45h-50h-with-high-quality","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/pt\/china-xps-flexible-rubber-coupling-with-flange-flexible-coupling-25a-25as-28as-30a-30as-50a-50as-50ac-160h-140h-25h-30h-40h-45h-50h-with-high-quality\/","title":{"rendered":"Acoplamento flex\u00edvel de borracha XPS com flange, fabricado na China, nos modelos 25A, 25AS, 28AS, 30A, 30AS, 50A, 50AS, 50AC, 160H, 140H, 25H, 30H, 40H, 45H e 50H, de alta qualidade."},"content":{"rendered":"<p>Ind\u00fastrias aplic\u00e1veis: Oficinas de repara\u00e7\u00e3o de m\u00e1quinas, servi\u00e7os de projeto<br \/>Local de exposi\u00e7\u00e3o: Nenhum<br \/>Inspe\u00e7\u00e3o de sa\u00edda do filme: Fornecido<br \/>Relat\u00f3rio de Teste de M\u00e1quinas: Fornecido<br \/>Classifica\u00e7\u00e3o de marketing: Mercadoria normal<br \/>Garantia: 1 ano<br \/>Aplica\u00e7\u00e3o: escavadeira<br \/>Embalagem: Saco PP ou caixa<br \/>Quantidade m\u00ednima para encomenda: 1 pe\u00e7a<br \/>Cor: cor do produto<br \/>Envio e prazo de entrega: Dentro de 24h a 48h<\/p>\n<p><strong>Acoplamento de borracha adapt\u00e1vel XPS com flange adapt\u00e1vel 25A 25AS 28AS 30A 30AS 50A 50AS 50AC 160H 140H 25H 30H 40H 45H 50H <\/strong><br \/><table border=\"0\" cellspacing=\"0\" cellpadding=\"0\"><tr align=\"left\"><td>Nome do produto<\/td><td>Acoplamento adapt\u00e1vel<\/td><\/tr><tr align=\"left\"><td>Subst\u00e2ncia<\/td><td>Borracha normal NBR<\/td><\/tr><tr align=\"left\"><td>Marca<\/td><td>XPS <\/td><\/tr><tr align=\"left\"><td>Assegurar<\/td><td>6 meses<\/td><\/tr><tr align=\"left\"><td>Certificados<\/td><td>CE<\/td><\/tr><tr align=\"left\"><td>Vers\u00e1til ou R\u00edgido<\/td><td>Flex\u00edvel<\/td><\/tr><tr align=\"left\"><td>Aplicativo<\/td><td>Escavadeiras\/motor a diesel\/bomba hidr\u00e1ulica<\/td><\/tr><tr align=\"left\"><td>Qualidade superior<\/td><td>Aut\u00eantico e de alt\u00edssima qualidade.<\/td><\/tr><tr align=\"left\"><td>Regular ou n\u00e3o padr\u00e3o<\/td><td>Comum<\/td><\/tr><tr align=\"left\"><td>Constru\u00e7\u00e3o<\/td><td>H\/A\/Bowex\/Equipamentos<\/td><\/tr><tr align=\"left\"><td>MOQ<\/td><td>1 pe\u00e7a<\/td><\/tr><tr align=\"left\"><td>Tempo de envio<\/td><td>Se o produto estiver em estoque, o pagamento integral ser\u00e1 efetuado em at\u00e9 3 dias ap\u00f3s a sua confirma\u00e7\u00e3o.<\/td><\/tr><tr align=\"left\"><td>Embalagem<\/td><td>Saco pl\u00e1stico, caixa de papel\u00e3o para equipamento de transmiss\u00e3o de energia el\u00e9trica industrial, micro-redutor de velocidade YNMRV, caixa de papel\u00e3o, NMRV110 1,1-7,5 kW, equipamento pesado de redu\u00e7\u00e3o de velocidade, micro-redutor com garantia de 1 ano, caixa de madeira, palete<\/td><\/tr><\/table> <strong> <\/strong><br \/><strong> <\/strong><br \/><strong> <\/strong><\/p>\n<p>\n<h2>Abordagens anal\u00edticas para estimar as press\u00f5es de contato em acoplamentos spline<\/h2>\n<p>Um acoplamento estriado \u00e9 um tipo de conex\u00e3o mec\u00e2nica entre dois eixos rotativos. Consiste em duas partes: um acoplador e um acoplamento propriamente dito. Ambas as partes possuem dentes que se encaixam e transferem cargas. No entanto, os acoplamentos estriados s\u00e3o geralmente superdimensionados, o que os torna suscet\u00edveis \u00e0 fadiga e ao comportamento est\u00e1tico. Fen\u00f4menos de desgaste tamb\u00e9m podem causar a falha do acoplamento. Por essa raz\u00e3o, o projeto adequado do acoplamento estriado \u00e9 essencial para alcan\u00e7ar o desempenho ideal.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_2.webp\" alt=\"eixo estriado\" width=\"800\" \/><\/p>\n<h2>Modelagem de um acoplamento spline<\/h2>\n<p>Os acoplamentos spline est\u00e3o se tornando cada vez mais populares na ind\u00fastria aeroespacial, mas operam em um estado ligeiramente desalinhado, causando vibra\u00e7\u00f5es e danos \u00e0s superf\u00edcies de contato. Para solucionar esse problema, este artigo apresenta abordagens anal\u00edticas para estimar as press\u00f5es de contato em um acoplamento spline. Especificamente, este artigo compara abordagens anal\u00edticas com abordagens puramente num\u00e9ricas para demonstrar os benef\u00edcios da abordagem anal\u00edtica.<br \/>Para modelar um acoplamento spline, primeiro voc\u00ea cria a base de conhecimento para o acoplamento spline. A base de conhecimento inclui um grande n\u00famero de valores de especifica\u00e7\u00e3o poss\u00edveis, que est\u00e3o relacionados entre si. Se voc\u00ea modificar uma especifica\u00e7\u00e3o, isso pode gerar um aviso por viola\u00e7\u00e3o de outra. Para que o projeto seja v\u00e1lido, voc\u00ea deve criar um modelo de acoplamento spline que atenda aos valores de especifica\u00e7\u00e3o definidos.<br \/>Ap\u00f3s modelar a geometria, voc\u00ea deve inserir as press\u00f5es de contato dos dois acoplamentos estriados. Em seguida, \u00e9 necess\u00e1rio determinar a posi\u00e7\u00e3o do c\u00edrculo primitivo da estria. Na Figura 2, o centro do acoplamento macho est\u00e1 sobreposto ao da estria f\u00eamea. Por fim, certifique-se de que a dist\u00e2ncia de engrenamento de alinhamento das duas estrias seja a mesma.<br \/>Ap\u00f3s obter os dados necess\u00e1rios para criar um modelo de acoplamento estriado, voc\u00ea pode come\u00e7ar inserindo as especifica\u00e7\u00f5es para o projeto da interface. Com esses dados em m\u00e3os, voc\u00ea precisa escolher se deseja otimizar a estria interna ou a externa. Tamb\u00e9m ser\u00e1 necess\u00e1rio especificar o coeficiente de atrito do dente, que \u00e9 usado para determinar as tens\u00f5es no modelo de acoplamento estriado 20. Al\u00e9m disso, voc\u00ea deve inserir a folga piloto, que \u00e9 a folga entre a ponta 186 de um dente 32 em uma estria e o elemento na estria de acoplamento.<br \/>Ap\u00f3s inserir as especifica\u00e7\u00f5es desejadas para a estria externa, voc\u00ea pode inserir os par\u00e2metros para a estria interna. Por exemplo, voc\u00ea pode inserir o limite do di\u00e2metro externo 154 do encaixe principal 54 e o encaixe secund\u00e1rio 56 da estria interna. Os valores desses par\u00e2metros s\u00e3o exibidos em caixas com c\u00f3digo de cores na tela 80 da GUI de Entradas e Configura\u00e7\u00e3o da Estrias. Ap\u00f3s a inser\u00e7\u00e3o dos par\u00e2metros, ser\u00e1 apresentada uma representa\u00e7\u00e3o geom\u00e9trica do modelo de acoplamento da estria 20.<\/p>\n<h2>Criando um modelo de acoplamento spline 20<\/h2>\n<p>O modelo de acoplamento spline 20 \u00e9 criado por um software de modelagem de produto 10. O software valida o modelo de acoplamento spline comparando-o com uma base de conhecimento de restri\u00e7\u00f5es e rela\u00e7\u00f5es de especifica\u00e7\u00e3o dependentes da configura\u00e7\u00e3o. Esse relat\u00f3rio \u00e9 ent\u00e3o inserido no programa de an\u00e1lise de tens\u00f5es ANSYS. Ele lista as configura\u00e7\u00f5es geom\u00e9tricas e os valores de especifica\u00e7\u00e3o do modelo de acoplamento spline 20 para cada elemento. O modelo de acoplamento spline 20 \u00e9 recriado automaticamente sempre que a configura\u00e7\u00e3o ou as especifica\u00e7\u00f5es de desempenho do modelo de acoplamento spline 20 s\u00e3o modificadas.<br \/>O modelo de acoplamento estriado 20 pode ser configurado usando o software de modelo de produto 10. O usu\u00e1rio especifica o comprimento axial do conjunto de estrias, que pode ser zero ou um comprimento fixo. O usu\u00e1rio tamb\u00e9m insere uma face de acoplamento radial 148, se houver, e seleciona um valor de especifica\u00e7\u00e3o de folga piloto de 14,5 graus ou 30 graus.<br \/>O usu\u00e1rio pode ent\u00e3o usar o mouse 110 para modificar o modelo de acoplamento spline 20. A base de conhecimento de acoplamento spline cont\u00e9m um grande n\u00famero de valores de especifica\u00e7\u00e3o poss\u00edveis e a regra de projeto de acoplamento spline. Se o usu\u00e1rio tentar alterar um modelo de acoplamento spline, o modelo exibir\u00e1 um aviso sobre a viola\u00e7\u00e3o de outra especifica\u00e7\u00e3o. Em alguns casos, a modifica\u00e7\u00e3o pode invalidar o projeto.<br \/>No modelo de acoplamento estriado 20, o usu\u00e1rio insere especifica\u00e7\u00f5es adicionais de requisitos de desempenho. O usu\u00e1rio escolhe os locais onde o torque m\u00e1ximo \u00e9 transferido para as estrias internas e externas 38 e 40. O local de transfer\u00eancia de torque m\u00e1ximo \u00e9 determinado pela configura\u00e7\u00e3o de fixa\u00e7\u00e3o do hardware aos eixos. Ap\u00f3s a sele\u00e7\u00e3o, o usu\u00e1rio pode clicar em \u201cAvan\u00e7ar\u201d para salvar o modelo. Uma pr\u00e9-visualiza\u00e7\u00e3o do modelo de acoplamento estriado 20 \u00e9 exibida.<br \/>O modelo 20 representa um acoplamento estriado. As especifica\u00e7\u00f5es do acoplamento estriado s\u00e3o inseridas na ordem e disposi\u00e7\u00e3o especificadas na tela da interface gr\u00e1fica do usu\u00e1rio (GUI) do modelo 20. Ap\u00f3s a inser\u00e7\u00e3o das especifica\u00e7\u00f5es, o software de modelagem do produto 10 as incorporar\u00e1 ao modelo 20. Esta \u00e9 a \u00faltima etapa na cria\u00e7\u00e3o do modelo de acoplamento estriado.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_2.webp\" alt=\"eixo estriado\" width=\"800\" \/><\/p>\n<h2>Analisando um modelo de acoplamento spline 20<\/h2>\n<p>A an\u00e1lise de um modelo de acoplamento spline consiste em inserir suas especifica\u00e7\u00f5es de configura\u00e7\u00e3o e desempenho. Essas especifica\u00e7\u00f5es podem ser geradas por outro programa de computador. O software de modelagem do produto 10 utiliza ent\u00e3o sua base de conhecimento interna de rela\u00e7\u00f5es e restri\u00e7\u00f5es de especifica\u00e7\u00e3o dependentes da configura\u00e7\u00e3o para criar um modelo param\u00e9trico tridimensional v\u00e1lido 20. Este modelo cont\u00e9m informa\u00e7\u00f5es que descrevem o n\u00famero e os tipos de dentes spline 32, encaixes 34 e ressaltos 36.<br \/>Ao analisar um acoplamento spline, o programa de software 10 incluir\u00e1 valores padr\u00e3o para diversas especifica\u00e7\u00f5es. O modelo de acoplamento spline 20 compreende uma spline interna 38 e uma spline externa 40. Cada uma das splines inclui seu pr\u00f3prio conjunto de par\u00e2metros, como profundidade, largura, comprimento e raios. A spline externa 40 tamb\u00e9m conter\u00e1 seu pr\u00f3prio conjunto de par\u00e2metros, como sua orienta\u00e7\u00e3o.<br \/>Ap\u00f3s a sele\u00e7\u00e3o desses par\u00e2metros, o programa de software realizar\u00e1 diversas an\u00e1lises no modelo de acoplamento estriado 20. O programa 10 calcula as tens\u00f5es nominais e m\u00e1ximas nos mancais dos dentes e a vida \u00fatil \u00e0 fadiga de um acoplamento estriado. Ele tamb\u00e9m determinar\u00e1 a diferen\u00e7a na tor\u00e7\u00e3o entre uma estria interna e uma externa. O arquivo de sa\u00edda da an\u00e1lise ser\u00e1 um relat\u00f3rio contendo os dados de configura\u00e7\u00e3o e especifica\u00e7\u00e3o do modelo. O arquivo de sa\u00edda tamb\u00e9m poder\u00e1 ser utilizado por outros programas de computador para an\u00e1lises adicionais.<br \/>Uma vez definidos esses par\u00e2metros, o usu\u00e1rio insere os crit\u00e9rios de projeto para o modelo de acoplamento estriado 20. Nesta etapa, o usu\u00e1rio especifica os locais de m\u00e1xima transfer\u00eancia de torque para as estrias externa e interna 38. O local de m\u00e1xima transfer\u00eancia de torque depende da configura\u00e7\u00e3o dos componentes acoplados aos eixos. O usu\u00e1rio pode inserir at\u00e9 quatro especifica\u00e7\u00f5es de requisitos de desempenho diferentes para cada estria.<br \/>Os resultados da an\u00e1lise mostram que existem duas fases de acoplamento spline. A primeira fase apresenta um grande aumento na tens\u00e3o e na vibra\u00e7\u00e3o. A segunda fase mostra uma diminui\u00e7\u00e3o nos n\u00edveis de tens\u00e3o e vibra\u00e7\u00e3o. A terceira fase apresenta uma for\u00e7a de engrenamento constante entre 300 N e 320 N. Esse comportamento continua por um per\u00edodo mais longo, at\u00e9 que a fase final entre em contato com a superf\u00edcie.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_2.webp\" alt=\"eixo estriado\" width=\"800\" \/><\/p>\n<h2>Desalinhamento de um acoplamento spline<\/h2>\n<p>Um estudo teve como objetivo investigar a posi\u00e7\u00e3o da for\u00e7a de contato resultante em um acoplamento estriado engatado em dentes sob torque constante e desalinhamento rotativo. O estudo utilizou m\u00e9todos num\u00e9ricos baseados em modelos de Elementos Finitos (MEF). Foram obtidos resultados num\u00e9ricos para condi\u00e7\u00f5es nominais e desalinhamento paralelo. O estudo considerou dois n\u00edveis de desalinhamento \u2013 0,02 mm e 0,08 mm \u2013 com diferentes n\u00edveis de carga.<br \/>Os resultados mostraram que o desalinhamento entre as estrias e os rotores causa uma altera\u00e7\u00e3o na for\u00e7a de engrenamento do sistema de acoplamento estria-rotor. Sua din\u00e2mica \u00e9 governada pela for\u00e7a de engrenamento das estrias. A for\u00e7a de engrenamento de um acoplamento de estrias desalinhado est\u00e1 relacionada aos par\u00e2metros do sistema de acoplamento rotor-estria\u00e7\u00e3o, ao torque transmitido e ao deslocamento de vibra\u00e7\u00e3o din\u00e2mica.<br \/>Apesar da falta de medi\u00e7\u00f5es precisas, o desalinhamento de estrias \u00e9 um problema comum. Esse problema \u00e9 agravado pelo fato de que as estrias geralmente apresentam folga. Essa folga \u00e9 resultado do desalinhamento da estria. Os autores analisaram diversas estrias, variando os di\u00e2metros primitivos e as rela\u00e7\u00f5es comprimento\/di\u00e2metro.<br \/>Um acoplamento estriado \u00e9 um sistema mec\u00e2nico bidimensional com folga positiva. O acoplamento estriado \u00e9 composto por um cubo e um eixo, e possui folgas entre a ponta e a raiz maiores que a folga. Uma folga de forma \u00e9 suficiente para evitar o contato entre a ponta e a raiz do eixo. O torque nas estrias \u00e9 transmitido por atrito.<br \/>Quando um acoplamento estriado est\u00e1 desalinhado, uma for\u00e7a de empuxo com vi\u00e9s de torque \u00e9 gerada. Nessa situa\u00e7\u00e3o, a for\u00e7a pode exceder o torque, fazendo com que o componente perca seu alinhamento. A transmiss\u00e3o bidirecional de torque e empuxo \u00e9 modelada analiticamente neste estudo. A abordagem anal\u00edtica fornece solu\u00e7\u00f5es que podem ser integradas ao processo de projeto. Portanto, da pr\u00f3xima vez que voc\u00ea se deparar com um problema de acoplamento estriado desalinhado, certifique-se de usar uma abordagem anal\u00edtica!<br \/>Neste estudo, o acoplamento estriado \u00e9 analisado em condi\u00e7\u00f5es nominais, sem desalinhamento paralelo. Os valores de rigidez obtidos representam a diferen\u00e7a percentual entre o di\u00e2metro primitivo nominal e o di\u00e2metro de aplica\u00e7\u00e3o da carga. Al\u00e9m disso, a diferen\u00e7a percentual m\u00e1xima no di\u00e2metro primitivo medido \u00e9 de 1,60% sob um torque de 5000 N*m. O outro par\u00e2metro, o \u00e2ngulo primitivo, tamb\u00e9m \u00e9 considerado no c\u00e1lculo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"Acoplamento flex\u00edvel de borracha XPS com flange, fabricado na China, nos modelos 25A, 25AS, 28AS, 30A, 30AS, 50A, 50AS, 50AC, 160H, 140H, 25H, 30H, 40H, 45H e 50H, de alta qualidade. \"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"Acoplamento flex\u00edvel de borracha XPS com flange, fabricado na China, nos modelos 25A, 25AS, 28AS, 30A, 30AS, 50A, 50AS, 50AC, 160H, 140H, 25H, 30H, 40H, 45H e 50H, de alta qualidade. \"><br \/>Editor por czh 2023-02-25<\/p>","protected":false},"excerpt":{"rendered":"<p>Ind\u00fastrias aplic\u00e1veis: Oficinas de reparo de m\u00e1quinas, fun\u00e7\u00f5es de design. Local de showroom: Nenhum. Inspe\u00e7\u00e3o de v\u00eddeo: Fornecida. Relat\u00f3rio de teste de m\u00e1quinas: Fornecido. Tipo de marketing: Mercadoria normal. Garantia: 1 ano. Aplica\u00e7\u00e3o: Escavadeira. Embalagem: Saco PP ou caixa. Quantidade m\u00ednima: 1 pe\u00e7a. Cor: Cor do produto. Envio e prazo de entrega: Dentro de 24h-48h. Acoplamento de borracha adapt\u00e1vel XPS com flange adapt\u00e1vel 25A 25AS 28AS 30A 30AS 50A 50AS 50AC 160H 140H 25H 30H 40H 45H [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2035,129,2741,2742,1688,2743,2418,397],"class_list":["post-1140","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-china-coupling","tag-coupling","tag-flange-coupling","tag-flange-flexible-coupling","tag-flexible-coupling","tag-flexible-flange-coupling","tag-flexible-rubber-coupling","tag-rubber-coupling"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts\/1140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/comments?post=1140"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/posts\/1140\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/media?parent=1140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/categories?post=1140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/pt\/wp-json\/wp\/v2\/tags?post=1140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}