{"id":334,"date":"2022-04-02T11:06:02","date_gmt":"2022-04-02T11:06:02","guid":{"rendered":"https:\/\/splineshaft.top\/china-straight-spline-drive-gear-shaft-for-rice-transplanter-with-ce-certificate-top-quality-good-price\/"},"modified":"2022-04-02T11:06:02","modified_gmt":"2022-04-02T11:06:02","slug":"china-straight-spline-drive-gear-shaft-for-rice-transplanter-with-ce-certificate-top-quality-good-price","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/it\/china-straight-spline-drive-gear-shaft-for-rice-transplanter-with-ce-certificate-top-quality-good-price\/","title":{"rendered":"Albero di trasmissione scanalato dritto per trapiantatrice di riso, prodotto in Cina, con certificato CE, alta qualit\u00e0 e buon prezzo."},"content":{"rendered":"<p>\n<h2>Descrizione dell'articolo<\/h2>\n<p>\n<p><strong>Servizi di esempio<\/strong><br \/>Forniamo campioni gratuiti per la conferma e CZPT si fa carico delle spese di spedizione.<br \/><strong>Servizi OEM<\/strong><br \/>Grazie alla nostra unit\u00e0 produttiva e ai nostri esperti specializzati, accogliamo con piacere anche ordini CZPT. Possiamo progettare e realizzare la soluzione specifica di cui avete bisogno, in base alle vostre esigenze dettagliate.<br \/><strong>Fornitore di servizi post-vendita<\/strong><br \/>I nostri entusiasti e cordiali addetti all'assistenza clienti CZPT sono pronti ad assistervi per qualsiasi domanda o difficolt\u00e0.<\/p>\n<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td>Prodotto<\/td>\n<td>Albero dell'asse con ingranaggio cilindrico\u00a0<\/td>\n<\/tr>\n<tr>\n<td>Materiali<\/td>\n<td>4140,4340,40Cr,42Crmo,42Crmo4<\/td>\n<\/tr>\n<tr>\n<td>Numero OEM<\/td>\n<td>Personalizza<\/td>\n<\/tr>\n<tr>\n<td>Certificazione<\/td>\n<td>ISO\/TS16949<\/td>\n<\/tr>\n<tr>\n<td>Verifica Necessit\u00e0<\/td>\n<td>Polvere magnetica: dare un'occhiata, verifica della durezza, esame dimensionale<\/td>\n<\/tr>\n<tr>\n<td>Colore<\/td>\n<td>Verniciatura, CZPT completo, lavorazione meccanica su tutti i lati<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\">Materiale<\/td>\n<td>Alluminio: serie 5000 (5052\u2026)\/serie 6000 (6061\u2026)\/serie 7000 (7075\u2026)<\/td>\n<\/tr>\n<tr>\n<td>Metallo: acciaio al carbonio, acciaio medio, lega di acciaio, ecc.<\/td>\n<\/tr>\n<tr>\n<td>Acciaio inossidabile: 303\/304\/316, ecc.<\/td>\n<\/tr>\n<tr>\n<td>Rame\/ottone\/bronzo\/rame rosso e cos\u00ec via.<\/td>\n<\/tr>\n<tr>\n<td>Plastica: muscoli dello stomaco, PP, computer, nylon, Delrin (POM), bachelite e cos\u00ec via.<\/td>\n<\/tr>\n<tr>\n<td>Dimensioni<\/td>\n<td>Secondo il disegno o i campioni di CZPT<\/td>\n<\/tr>\n<tr>\n<td>Approccio<\/td>\n<td>Lavorazioni CNC, tornitura, fresatura, stampaggio, rettifica, saldatura, iniezione di filo, riduzione e molte altre.<\/td>\n<\/tr>\n<tr>\n<td>Tolleranza<\/td>\n<td>\u2265+\/-.03mm<\/td>\n<\/tr>\n<tr>\n<td>Terapia della superficie<\/td>\n<td>Sabbiatura, (resistenza), (colorazione), anodizzazione, (cromo, nichel, zinco\u2026), placcatura, verniciatura, verniciatura a polvere, affilatura, annerimento, indurimento, laser, incisione e molti altri.<\/td>\n<\/tr>\n<tr>\n<td>Formati di file<\/td>\n<td>ProE, SolidWorks, UG, CAD, PDF (IGS, XT, STP, STL)<\/td>\n<\/tr>\n<tr>\n<td>Campione<\/td>\n<td>Ottenibile<\/td>\n<\/tr>\n<tr>\n<td>Imballaggio<\/td>\n<td>Protezione con spline, scatola di legno, membrana impermeabile o per ogni esigenza CZPT.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p>\n<p>\n<p>Pi\u00f9 sicuro e compatto da usare: l'albero di estensione della presa di forza \u00e8 completamente analizzato, compatto e pu\u00f2 essere sostituito direttamente senza problemi, rendendolo una risorsa efficiente per la trasmissione di energia. Catene di sicurezza e protezioni in plastica proteggono da possibili pericoli durante il trasporto.<br \/><img><\/p>","protected":false},"excerpt":{"rendered":"<p>Descrizione dell'articolo Servizi di campionaturaForniamo campioni gratuiti per la conferma e CZPT si fa carico delle spese di spedizioneServizi OEMAvendo un proprio stabilimento di produzione e esperti specializzati, accogliamo anche ordini CZPT.Possiamo progettare e produrre la soluzione specifica di cui hai bisogno in base ai tuoi dettagli dettagliatiServizio post-venditaI nostri entusiasti e cordiali rappresentanti del supporto CZPT sono pronti a [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1407,617,440,1410,948,19,620,952,20,1094,1565,462],"class_list":["post-334","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-drive-gear","tag-drive-shaft-top","tag-gear","tag-gear-drive","tag-gear-shaft","tag-shaft","tag-shaft-drive","tag-shaft-gear","tag-shaft-price","tag-spline-shaft","tag-straight-gear","tag-top-gear"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts\/334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}