{"id":1105,"date":"2023-02-21T23:32:39","date_gmt":"2023-02-21T23:32:39","guid":{"rendered":"http:\/\/splineshaft.top\/china-stub-shaft-drive-shaft-coupling\/"},"modified":"2023-02-21T23:32:39","modified_gmt":"2023-02-21T23:32:39","slug":"china-stub-shaft-drive-shaft-coupling","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/it\/china-stub-shaft-drive-shaft-coupling\/","title":{"rendered":"China stub shaft     drive shaft coupling"},"content":{"rendered":"<p>Condizione: Nuovo<br \/>Garanzia: 12 mesi<br \/>Applicable Industries: Creating Content Retailers, Production Plant, Machinery Fix Outlets, Design performs<br \/>Luogo dello showroom: Nessuno<br \/>Ispezione in uscita del film: Presentato<br \/>Machinery Test Report: Supplied<br \/>Marketing Type: Hot Merchandise 2019<br \/>Warranty of main components: 1 12 months<br \/>Core Parts: Bearing, Equipment<br \/>Struttura: Spline<br \/>Substance: 40cr<br \/>Coatings: polybag<br \/>Torque Ability: 25000N.m<br \/>Model Amount: 1924<br \/>Procedura: Lavorazione al tornio CNC + tornio per auto<br \/>High quality: Prime Higher<br \/>Soon after Warranty Service: Video technological assist, On-line assistance, Producing entrance rear car Propeller Shaft Driveshaft Generate Shaft for The united states Euro Japan Korea automobiles CZPT manufacturer Spare elements<br \/>Sede del servizio regionale: Nessuna<br \/>Packaging Specifics: picket box<br \/>Porto: ZheJiang <\/p>\n<p>we have sophisticated manufacturing equipments and rich producing expertise with Benz large vans of propeller shaft,midship shafts,steering column systems,common joint\u2026the product quantity like 1924,2624,571, Personalized large bled cubic decrease energy reducer transaxle T375 and so on.<br \/>We have 8 many years matching expertise with Benz truck in Iran market.<br \/>We know which portion can be simple make problem in potential used.<br \/>The flange yokes, tube yokes, spline shafts, flange hubs processed by unique computerized CNC machines,when positioned to finish grooving,unexciting, Low cost price AC 220V 50HZ 8bar Customizable colour silent Oil cost-free piston air compressor with 30L horizontal tank conclude face this sort of 3 making process.<br \/>The sleeve muffs utilised nylon 11 coating.<\/p>\n<p>\n<h2>Applicazioni dei giunti scanalati<\/h2>\n<p>Un giunto scanalato \u00e8 un metodo estremamente efficace per collegare due o pi\u00f9 componenti. Questi tipi di giunti sono molto efficienti, in quanto combinano il movimento lineare con la rotazione, e la loro efficienza li rende una scelta ideale in numerose applicazioni. Continua a leggere per saperne di pi\u00f9 sulle principali caratteristiche e applicazioni dei giunti scanalati. Potrai anche determinare il funzionamento previsto e l'usura. Puoi facilmente progettare i tuoi giunti seguendo i passaggi descritti di seguito.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_3.webp\" alt=\"albero scanalato\" width=\"800\" \/><\/p>\n<h2>Progettazione ottimale<\/h2>\n<p>Il giunto scanalato svolge un ruolo importante nella trasmissione della coppia. \u00c8 costituito da un mozzo e un albero con scanalature che sono a contatto superficiale senza movimento relativo. Poich\u00e9 sono collegati, la loro velocit\u00e0 angolare \u00e8 la stessa. Le scanalature possono essere progettate con qualsiasi profilo che minimizzi l'attrito. Poich\u00e9 sono a contatto tra loro, il carico non \u00e8 distribuito uniformemente, concentrandosi su una piccola area, il che pu\u00f2 deformare la superficie del mozzo.<br \/>La progettazione ottimale dei giunti scanalati tiene conto di diversi fattori, tra cui il peso, le caratteristiche del materiale e i requisiti prestazionali. Nell'industria aeronautica, il peso \u00e8 un fattore di progettazione importante. Le tabelle SAE e ANSI non considerano il peso nel calcolo dei requisiti prestazionali dei giunti scanalati. Un altro fattore critico \u00e8 lo spazio. I giunti scanalati potrebbero dover essere installati in spazi ristretti o essere soggetti ad altri vincoli di configurazione.<br \/>La progettazione ottimale dei giunti scanalati pu\u00f2 essere caratterizzata da un numero dispari di denti. Tuttavia, non \u00e8 sempre cos\u00ec. Se il diametro esterno della scanalatura supera una certa soglia, il modello di giunto scanalato ottimale potrebbe non essere la scelta migliore per questa applicazione. Per ottimizzare un giunto scanalato per una specifica applicazione, l'utente potrebbe dover considerare il metodo di dimensionamento pi\u00f9 appropriato per la propria applicazione.<br \/>Una volta generato il progetto, il passo successivo consiste nel testare il giunto scanalato risultante. Il sistema deve verificare la presenza di eventuali vincoli di progettazione e convalidare la fattibilit\u00e0 della produzione utilizzando moderne tecniche di fabbricazione. Il modello del giunto scanalato viene quindi esportato in uno strumento di ottimizzazione per ulteriori analisi. Il metodo consente al progettista di modificare facilmente il design di un giunto scanalato e di ridurne il peso.<br \/>Il modello di giunto scanalato 20 include le principali caratteristiche strutturali di un giunto scanalato. Un programma software di modellazione del prodotto 10 memorizza i valori predefiniti per ciascuna delle specifiche del giunto scanalato. Il modello scanalato risultante viene quindi calcolato in conformit\u00e0 con l'algoritmo utilizzato nella presente invenzione. Il software consente al progettista di inserire i raggi, lo spessore e l'orientamento del giunto scanalato.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_3.webp\" alt=\"albero scanalato\" width=\"800\" \/><\/p>\n<h2>Caratteristiche<\/h2>\n<p>Un aspetto importante delle scanalature nei motori aeronautici \u00e8 la distribuzione del carico tra i denti. I ricercatori hanno condotto test sperimentali e analizzato l'effetto delle condizioni di lubrificazione sul comportamento dell'accoppiamento. Successivamente, hanno sviluppato un modello teorico utilizzando un parametro di Ruiz per simulare le effettive condizioni di lavoro degli accoppiamenti a scanalatura. Questo modello spiega il danno da usura causato dagli accoppiamenti a scanalatura considerando l'influenza dell'attrito, del disallineamento e di altre condizioni rilevanti per le prestazioni delle scanalature.<br \/>Per progettare un giunto scanalato, l'utente inserisce innanzitutto i criteri di progettazione per il dimensionamento delle sezioni portanti, inclusa la scanalatura esterna 40 del modello di giunto scanalato 30. Successivamente, l'utente specifica i requisiti prestazionali del margine di coppia, come il limite di snervamento, l'instabilit\u00e0 plastica e l'instabilit\u00e0 per scorrimento viscoso. Il programma software calcola quindi automaticamente le dimensioni e la configurazione delle sezioni portanti e dell'albero. Queste specifiche vengono poi inserite nel programma software di modellazione 10 come valori di specifica.<br \/>Le diverse specifiche di configurazione del giunto scanalato vengono inserite nella schermata GUI 80. Il programma software 10 genera quindi un modello del giunto scanalato memorizzando i valori predefiniti per le varie specifiche. L'utente pu\u00f2 quindi manipolare il modello del giunto scanalato modificandone le diverse specifiche. Il risultato finale sar\u00e0 un progetto CAD che consentir\u00e0 ai progettisti di ottimizzare i giunti scanalati in base alle loro prestazioni e alle specifiche di progettazione.<br \/>Il software per la modellazione di accoppiamento spline valuta continuamente la validit\u00e0 dei modelli di accoppiamento spline per una particolare applicazione. Ad esempio, se un utente immette un segnale di valore dati corrispondente a un segnale di parametro, il software confronta il valore del segnale immesso con il valore corrispondente nella base di conoscenza. Se i valori non rientrano nelle specifiche, viene visualizzato un messaggio di avviso. Una volta completato il confronto, il software per la modellazione di accoppiamento spline genera un report con i risultati.<br \/>Tra i vari fattori di progettazione dei giunti scanalati figurano il peso, le propriet\u00e0 del materiale e i requisiti prestazionali. Il peso \u00e8 uno dei fattori di progettazione pi\u00f9 importanti, soprattutto in ambito aeronautico. Le tabelle ANSI e SAE non tengono conto di questi fattori nel calcolo delle caratteristiche di carico dei giunti scanalati. Anche altri requisiti di progettazione possono limitare la configurazione di un giunto scanalato.<\/p>\n<h2>Applicazioni<\/h2>\n<p>I giunti scanalati sono un tipo di giunto meccanico che collega due alberi rotanti. Le sue due parti si innestano tramite denti che trasferiscono il carico. Sebbene le scanalature siano comunemente sovradimensionate, sono comunque soggette a fatica e comportamento statico. Queste caratteristiche le rendono anche soggette a usura. Pertanto, una progettazione e una selezione adeguate sono fondamentali per ridurre al minimo l'usura delle scanalature. Esistono numerose applicazioni per i giunti scanalati.<br \/>La progettazione delle chiavette si basa sulle dimensioni dell'albero da unire. Ci\u00f2 consente di ottenere la corretta spaziatura delle chiavette. Un innovativo metodo di fresatura permette la formazione di basi coniche senza interferenze, e la radice delle chiavette \u00e8 concentrica con l'asse. Queste caratteristiche consentono elevate velocit\u00e0 di produzione. Le giunzioni scanalate trovano diverse applicazioni in vari settori industriali. Per saperne di pi\u00f9, continuate a leggere.<br \/>La metodologia basata sugli elementi finiti (FE) pu\u00f2 prevedere il tasso di usura dei giunti scanalati includendo l'evoluzione del coefficiente di attrito. Questo metodo pu\u00f2 prevedere l'usura da sfregamento a partire da una semplice geometria rotonda su piana ed \u00e8 stato calibrato con dati sperimentali. Il tasso di usura previsto \u00e8 ragionevole se confrontato con i dati sperimentali. L'evoluzione dell'attrito nei giunti scanalati dipende dalla geometria delle scanalature. \u00c8 inoltre fondamentale considerare le condizioni di lubrificazione delle scanalature.<br \/>L'utilizzo di un giunto scanalato riduce il gioco e garantisce il corretto allineamento dei componenti accoppiati. La forma scanalata dei denti dell'albero trasferisce la rotazione dall'albero scanalato all'elemento scanalato interno, che pu\u00f2 essere un ingranaggio o un altro dispositivo rotante. La resistenza alla base e i requisiti di coppia di un giunto scanalato determinano il tipo di giunto scanalato da utilizzare.<br \/>La base della scanalatura \u00e8 solitamente piatta e presenta una corona su un lato. La scanalatura coronata ha una corona simmetrica sulla linea centrale della larghezza della scanalatura. Man mano che la lunghezza della scanalatura diminuisce verso le estremit\u00e0, i denti diventano pi\u00f9 sottili. Il diametro del dente si misura in passo. Ci\u00f2 significa che la scanalatura maschio ha una base piatta e una scanalatura coronata.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_3.webp\" alt=\"albero scanalato\" width=\"800\" \/><\/p>\n<h2>Prevedibilit\u00e0<\/h2>\n<p>I giunti a mandrino vengono utilizzati nei macchinari rotanti per collegare due alberi. Sono composti da due parti con denti che si innestano tra loro e trasferiscono il carico. I giunti scanalati sono spesso sovradimensionati e soggetti a sollecitazioni statiche e a fatica. Anche i fenomeni di usura rappresentano un problema comune per i giunti scanalati. Per affrontare questi problemi, \u00e8 essenziale comprendere il comportamento e la prevedibilit\u00e0 di questi giunti.<br \/>Il comportamento dinamico degli accoppiamenti tra albero scanalato e rotore \u00e8 spesso poco chiaro, soprattutto se il sistema non \u00e8 integrato con il rotore. Ad esempio, in assenza di disallineamento, la frequenza di risposta principale corrisponde a una velocit\u00e0 di rotazione sull'asse X. All'aumentare del disallineamento, il sistema inizia a vibrare in modi complessi. Inoltre, man mano che le orbite dell'albero si allontanano dall'origine, l'ampiezza di tutte le frequenze aumenta. Pertanto, i risultati della ricerca sono utili per determinare la corretta progettazione e la risoluzione dei problemi dei sistemi rotorici.<br \/>Il modello di accoppiamenti spline disallineati pu\u00f2 essere ottenuto analizzando le relazioni sforzo-compressione tra due coppie di spline. Il modello della forza di ingranamento delle spline \u00e8 una funzione della massa del sistema, della coppia trasmessa e dello spostamento di vibrazione dinamica. Questo modello \u00e8 valido quando lo spostamento di vibrazione dinamica \u00e8 piccolo. Inoltre, il metodo di integrazione a passi CZPT \u00e8 stabile e presenta un'elevata efficienza.<br \/>Le distribuzioni di scorrimento dipendono dallo stato di lubrificazione, dal coefficiente di attrito e dai cicli di carico. Le profondit\u00e0 di usura previste rientrano ampiamente nell'intervallo dei valori misurati. Queste previsioni si basano sulle distribuzioni di scorrimento. La metodologia prevede un aumento dell'usura in condizioni di lubrificazione leggera, ma non in presenza di lubrificazione aggiuntiva. Le condizioni di lubrificazione e il coefficiente di attrito sono i fattori chiave che determinano il comportamento all'usura delle scanalature.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China stub shaft     drive shaft coupling\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China stub shaft     drive shaft coupling\t\"><br \/>Modificato da czh il 22\/02\/2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Condition: NewWarranty: 1 12 monthsApplicable Industries: Creating Content Retailers, Production Plant, Machinery Fix Outlets, Design performsShowroom Place: NoneMovie outgoing-inspection: PresentedMachinery Test Report: SuppliedMarketing Type: Hot Merchandise 2019Warranty of main components: 1 12 monthsCore Parts: Bearing, EquipmentFramework: SplineSubstance: 40crCoatings: polybagTorque Ability: 25000N.mModel Amount: 1924Procedure: CNC Turning Machining+Car LatheHigh quality: Prime HigherSoon after Warranty Service: Video technological [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[19,620],"class_list":["post-1105","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-shaft","tag-shaft-drive"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts\/1105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/comments?post=1105"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/posts\/1105\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/media?parent=1105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/categories?post=1105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/it\/wp-json\/wp\/v2\/tags?post=1105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}