{"id":1185,"date":"2023-05-15T05:46:42","date_gmt":"2023-05-15T05:46:42","guid":{"rendered":"http:\/\/splineshaft.top\/china-manufacturer-germany-58-spline-shaft-for-twin-screw-extruder-machine-drive-shaft-bearing\/"},"modified":"2023-05-15T05:46:42","modified_gmt":"2023-05-15T05:46:42","slug":"china-manufacturer-germany-58-spline-shaft-for-twin-screw-extruder-machine-drive-shaft-bearing","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/fr\/china-manufacturer-germany-58-spline-shaft-for-twin-screw-extruder-machine-drive-shaft-bearing\/","title":{"rendered":"Arbre cannel\u00e9 58 cannelures pour extrudeuse \u00e0 double vis, fabriqu\u00e9 en Chine et en Allemagne. Roulement d'arbre d'entra\u00eenement."},"content":{"rendered":"<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_0_tb_body  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p><h2>Description du produit<\/h2>\n<p>\n<p><p><b>\u00a0Germany 58 Spline Shaft for Twin Screw Extruder machine<\/b><\/p>\n<p><strong>Production description:<\/strong><\/p>\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td>Production name:<\/td>\n<td>Arbre \u00e0 vis<\/td>\n<td>Model Number:<\/td>\n<td><strong>\u00a0Germany 58<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Extrusion equipment:<\/td>\n<td>Maris<\/td>\n<td>Mat\u00e9riel:<\/td>\n<td>1.2343<\/td>\n<\/tr>\n<tr>\n<td>Lieu d'origine<\/td>\n<td>Chine<\/td>\n<td>Application<\/td>\n<td>Twin screw extruder machine<\/td>\n<\/tr>\n<tr>\n<td>Production ability<\/td>\n<td>300m \/\u00a0Per month<\/td>\n<td>Diam\u00e8tre de la vis<\/td>\n<td>57.5mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong><strong>Co-rotating twin screw shafts for<\/strong><\/strong>\u00a0<br \/>-APV\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0-KOBE\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 -OMC<br \/>-Buss\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 -ICMA\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 -Toshiba<br \/>-Clextral\u00a0 \u00a0 \u00a0 -Labtech\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0-USEON<br \/>-Lantai\u00a0 \u00a0 \u00a0 \u00a0 &#8211; others<br \/>-JSW\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 -Leistritz\u00a0\u00a0\u00a0\u00a0<br \/>-Keya\u00a0 \u00a0 \u00a0 \u00a0 \u00a0-Maris<\/p>\n<p><strong>Types of\u00a0\u00a0shaft<\/strong><br \/>Single Keyway\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Square Keyslot\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0High torque key button\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Dual keyslot<br \/>Involute inner spline\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Round keyslot\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Retackle spline\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Client&#8217;s requirements available<\/p>\n<p><strong>We offer a\u00a0broader choice of materials:<\/strong><br \/>\u00a040CrNiMo\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a01.2343\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0WR30<br \/>By working closely with customers in choosing optional materials,we can minimize wear and tear and associated costs.<\/p>\n<p><strong>Our Production Plant<\/p>\n<p><\/strong><\/p>\n<p><strong><strong>FRQ<\/strong><\/strong><br \/>\u00a0<br \/>1.\u00a0Q: Are you a\u00a0factory or trading company?\u00a0<br \/>\u00a0\u2014A : Une usine\u00a0<br \/>2. Q: Where is your factory located? How can I\u00a0visit there?\u00a0<br \/>&#8212;&#8211;A: Our factory is located in\u00a0HangZhou,\u00a0ZheJiang \u00a0Province, China,\u00a0<br \/>1) You can fly to\u00a0HangZhou\u00a0Airport directly. We will pick you up\u00a0when you arrive in the airport;\u00a0<br \/>All our clients, from domestic or abroad, are warmly welcome to visit us!\u00a0<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<br \/>3.Q: What makes you different with others?<br \/>&#8212;-A: 1) Our Excellent Service\u00a0<br \/>\u00a0For a\u00a0quick, no hassle quote just send email to us<br \/>\u00a0We promise to reply with a\u00a0price within 24 hours &#8211;\u00a0sometimes even within the hour.<br \/>\u00a0<br \/>2) Our quick manufacturing time<br \/>For Normal orders, we will promise to produce within 30 working days.<br \/>As a\u00a0manufacturer, we can ensure the delivery time according to the formal contract.<br \/>\u00a0<br \/>\u00a04.Q: How about the delivery time?\u00a0<br \/>&#8212;-A: This depends on the product. Typically standard products are delivered within 30\u00a0days.\u00a0<br \/>\u00a0<\/p>\n<ol>\n<li>\u00a0Q: What is the term of payment?\u00a0<br \/>&#8212;-A: 1) T\/T payment;\u00a0\u00a0\u00a02) LC;\u00a0\u00a0<\/li>\n<\/ol>\n<p>\u00a0<br \/>6.Q: May I\u00a0know the status of my order?<br \/>&#8212;-A: Yes .We will send you information and photos at different production stage of your order. You will get the latest information in time.\u00a0<br \/>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Service apr\u00e8s-vente :<\/th>\n<td>6 Months<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Warranty:<\/th>\n<td>6 Months<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Standard:<\/th>\n<td>GB<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Technics:<\/th>\n<td>Fonderie<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Feature:<\/th>\n<td>Degradable<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Duret\u00e9:<\/th>\n<td>HRC38-42<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 5\/Piece<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <i class=\"ob-icon icon-product\"><\/i>Demande d'\u00e9chantillon\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                        <i class=\"ob-icon icon-fill\"><\/i>Demande personnalis\u00e9e<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Types de splines<\/h2>\n<p>Il existe quatre types de cannelures\u00a0: \u00e0 d\u00e9veloppante, \u00e0 clavette parall\u00e8le, h\u00e9lico\u00efdales et \u00e0 billes. D\u00e9couvrez leurs caract\u00e9ristiques. En cas de doute, n'h\u00e9sitez pas \u00e0 demander un devis. Ces cannelures sont couramment utilis\u00e9es pour la construction de machines sp\u00e9ciales, les r\u00e9parations et d'autres applications. La soci\u00e9t\u00e9 CZPT Manufacturing Company fabrique ces arbres. Sp\u00e9cialis\u00e9e dans ce domaine, elle se tient \u00e0 votre disposition.<\/p>\n<h2>splines en d\u00e9veloppante<\/h2>\n<p>La cannelure en d\u00e9veloppante offre une structure plus rigide et durable, et se d\u00e9cline en diff\u00e9rents diam\u00e8tres et nombres de cannelures. G\u00e9n\u00e9ralement, on utilise comme mati\u00e8res premi\u00e8res l'acier, l'acier au carbone ou le titane. D'autres mat\u00e9riaux, comme la fibre de carbone, peuvent convenir. Cependant, la production de titane \u00e9tant complexe, certains fabricants optent pour d'autres mat\u00e9riaux.<br \/>L'utilisation de cannelures dans les arbres emp\u00eache la s\u00e9paration des pi\u00e8ces en cours de fonctionnement. Ces caract\u00e9ristiques en font un choix id\u00e9al pour la fixation d'assemblages m\u00e9caniques. Les cannelures \u00e0 gorge incurv\u00e9e vers l'int\u00e9rieur ne pr\u00e9sentent pas d'angles vifs et sont donc moins susceptibles de se casser ou de se s\u00e9parer pendant leur fonctionnement. Ces propri\u00e9t\u00e9s leur permettent de r\u00e9sister aux op\u00e9rations \u00e0 grande vitesse, telles que le freinage, l'acc\u00e9l\u00e9ration et la marche arri\u00e8re.<br \/>Une cannelure m\u00e2le est munie d'une face orient\u00e9e vers l'ext\u00e9rieur, et une cannelure femelle est ins\u00e9r\u00e9e par son centre. Les dents de la cannelure m\u00e2le pr\u00e9sentent g\u00e9n\u00e9ralement des extr\u00e9mit\u00e9s chanfrein\u00e9es afin de permettre un d\u00e9gagement au niveau de la zone de transition. Le rayon et la largeur des dents d'une cannelure m\u00e2le sont g\u00e9n\u00e9ralement sup\u00e9rieurs \u00e0 ceux d'une cannelure femelle. Ces sp\u00e9cifications sont d\u00e9finies dans les manuels de conception ANSI ou DIN.<br \/>L'\u00e9paisseur effective d'une dent cannel\u00e9e d\u00e9pend de l'erreur de profil en d\u00e9veloppante et de l'erreur d'h\u00e9lice. L'espacement des dents et des rainures de clavette influe \u00e9galement sur cette \u00e9paisseur. Les cannelures en d\u00e9veloppante d'un arbre cannel\u00e9 sont con\u00e7ues pour que, lors de l'accouplement, au moins 25 % des dents soient en prise, assurant ainsi une r\u00e9partition uniforme de la charge et de l'usure.<\/p>\n<h2>Splines \u00e0 cl\u00e9s parall\u00e8les<\/h2>\n<p>Un arbre cannel\u00e9 parall\u00e8le pr\u00e9sente une h\u00e9lice de rainures de m\u00eame diam\u00e8tre sur sa circonf\u00e9rence. Ces rainures sont g\u00e9n\u00e9ralement parall\u00e8les ou en d\u00e9veloppante. Les cannelures minimisent les concentrations de contraintes dans les articulations fixes et permettent les mouvements lin\u00e9aires et rotatifs. Elles peuvent \u00eatre taill\u00e9es ou lamin\u00e9es \u00e0 froid. Les cannelures lamin\u00e9es \u00e0 froid sont plus r\u00e9sistantes que les cannelures taill\u00e9es et sont souvent utilis\u00e9es dans les applications exigeant une grande r\u00e9sistance, une pr\u00e9cision \u00e9lev\u00e9e et une surface lisse.<br \/>Un arbre cannel\u00e9 \u00e0 clavettes parall\u00e8les pr\u00e9sente des rainures et des clavettes parall\u00e8les \u00e0 son axe. Cette conception est particuli\u00e8rement adapt\u00e9e aux applications o\u00f9 la r\u00e9sistance \u00e0 la charge et la fluidit\u00e9 de mouvement sont primordiales. Un arbre cannel\u00e9 \u00e0 clavettes parall\u00e8les peut \u00eatre fabriqu\u00e9 en aciers alli\u00e9s, des alliages \u00e0 base de fer pouvant contenir du chrome, du nickel, du molybd\u00e8ne, du cuivre ou d'autres \u00e9l\u00e9ments d'alliage.<br \/>Un arbre cannel\u00e9 peut servir \u00e0 transmettre un couple et \u00e0 emp\u00eacher la rotation lorsqu'il est utilis\u00e9 comme guide lin\u00e9aire. Ces arbres poss\u00e8dent un profil carr\u00e9 qui s'embo\u00eete dans des rainures d'une pi\u00e8ce correspondante et transmet ainsi le couple et la rotation. Leur longueur est facilement ajustable et ils sont couramment utilis\u00e9s dans l'a\u00e9rospatiale. Leur fiabilit\u00e9 et leur r\u00e9sistance \u00e0 la fatigue en font un excellent choix pour de nombreuses applications.<br \/>La principale diff\u00e9rence entre un arbre cannel\u00e9 \u00e0 clavettes parall\u00e8les et un arbre clavet\u00e9 r\u00e9side dans la plus grande flexibilit\u00e9 offerte par le premier. L'absence de rainures pr\u00e9serve la capacit\u00e9 de transmission du couple. Les cannelures assurent une r\u00e9partition uniforme de la charge sur les dents, ce qui se traduit par une dur\u00e9e de vie accrue de l'arbre. En agriculture, la dur\u00e9e de vie de l'arbre est primordiale. Les \u00e9quipements agricoles, par exemple, doivent pouvoir fonctionner \u00e0 haute vitesse pendant de longues p\u00e9riodes.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>splines h\u00e9lico\u00efdales en d\u00e9veloppante<\/h2>\n<p>Les cannelures en d\u00e9veloppante sont une conception courante pour les arbres cannel\u00e9s. Ce sont les plus r\u00e9pandues et elles se caract\u00e9risent par un espacement r\u00e9gulier entre leurs dents. Ces derni\u00e8res sont \u00e9galement plus courtes que celles des arbres cannel\u00e9s \u00e0 cannelures parall\u00e8les, ce qui r\u00e9duit la concentration des contraintes. Ces cannelures permettent de transmettre la puissance \u00e0 des engrenages flottants ou fixes et de limiter les concentrations de contraintes dans l'assemblage. Les cannelures en d\u00e9veloppante sont les plus courantes et sont largement utilis\u00e9es dans de nombreuses applications, notamment dans l'automobile et les machines-outils.<br \/>Les arbres \u00e0 cannelures h\u00e9lico\u00efdales en d\u00e9veloppante sont id\u00e9aux pour les applications impliquant un mouvement axial et une rotation. Ils permettent l'engagement et le d\u00e9sengagement d'un accouplement \u00e0 faces parall\u00e8les. Cette conception autorise \u00e9galement un diam\u00e8tre sup\u00e9rieur \u00e0 celui d'un arbre \u00e0 cannelures parall\u00e8les. Il en r\u00e9sulte un r\u00e9ducteur \u00e0 haut rendement. Outre leur robustesse, les cannelures peuvent aussi \u00eatre utilis\u00e9es pour d'autres applications impliquant la transmission de couple et d'\u00e9nergie.<br \/>Un nouveau mod\u00e8le statistique permet de d\u00e9terminer le nombre de dents en prise pour une charge donn\u00e9e. Ces cannelures se caract\u00e9risent par un ajustement serr\u00e9 au niveau des diam\u00e8tres principaux, assurant ainsi la concentricit\u00e9 de l'arbre \u00e0 la cannelure femelle. La cannelure m\u00e2le pr\u00e9sente des extr\u00e9mit\u00e9s chanfrein\u00e9es pour le d\u00e9gagement avec la zone de transition. Les manuels de conception ANSI et DIN sp\u00e9cifient les diff\u00e9rentes classes d'ajustement.<br \/>La conception des cannelures h\u00e9lico\u00efdales \u00e0 d\u00e9veloppante est similaire \u00e0 celle des engrenages\u00a0; leurs ar\u00eates ou dents s\u2019embo\u00eetent dans les rainures correspondantes d\u2019une pi\u00e8ce en prise. Ce syst\u00e8me permet de transmettre le couple et la rotation \u00e0 la pi\u00e8ce en prise tout en maintenant l\u2019alignement des deux composants. Diff\u00e9rents types de cannelures sont utilis\u00e9s selon les applications. La hauteur des dents peut varier d\u2019une cannelure \u00e0 l\u2019autre.<\/p>\n<h2>Cannelures \u00e0 billes en d\u00e9veloppante<\/h2>\n<p>L'utilisation de cannelures permet un engr\u00e8nement r\u00e9gulier entre l'arbre et le moyeu sur toute la circonf\u00e9rence de l'arbre. Gr\u00e2ce \u00e0 l'espacement constant des dents, la charge transmissible est uniforme et leur position reste toujours la m\u00eame, quelle que soit la longueur de l'arbre. Que l'arbre serve \u00e0 transmettre un couple ou de la puissance, les cannelures constituent un excellent choix. Elles offrent une r\u00e9sistance maximale et permettent un mouvement lin\u00e9aire ou rotatif.<br \/>Il existe trois types principaux de cannelures\u00a0: h\u00e9lico\u00efdales, \u00e0 couronne et \u00e0 billes. Les cannelures \u00e0 couronne pr\u00e9sentent des rainures \u00e9quidistantes. Elles poss\u00e8dent des c\u00f4t\u00e9s en d\u00e9veloppante et des c\u00f4t\u00e9s parall\u00e8les. Les cannelures h\u00e9lico\u00efdales utilisent des dents en d\u00e9veloppante et sont souvent employ\u00e9es sur des arbres de petit diam\u00e8tre. Les cannelures \u00e0 billes contiennent un roulement \u00e0 billes \u00e0 l'int\u00e9rieur de l'arbre cannel\u00e9 afin de faciliter la rotation et de minimiser la concentration des contraintes dans les articulations fixes.<br \/>Les deux types de cannelures sont class\u00e9s selon les classes d'ajustement ANSI. Les cannelures \u00e0 fond arrondi poss\u00e8dent des dents qui s'engr\u00e8nent le long de l'axe longitudinal de rotation. Les cannelures \u00e0 fond plat ont des dents similaires, mais sont con\u00e7ues pour optimiser la r\u00e9sistance lors d'une utilisation de courte dur\u00e9e. Ces deux types de cannelures sont essentiels pour garantir un alignement correct de l'arbre et \u00e9viter tout d\u00e9salignement.<br \/>Le coefficient de frottement du moyeu est un ph\u00e9nom\u00e8ne complexe. Lorsque le moyeu est excentr\u00e9, le centre se d\u00e9place de fa\u00e7on pr\u00e9visible mais irr\u00e9guli\u00e8re. De plus, m\u00eame lorsque l'arbre est centr\u00e9, le centre peut osciller entre une position centr\u00e9e et une position excentr\u00e9e. Pour compenser ce ph\u00e9nom\u00e8ne, le couple doit \u00eatre suffisant pour maintenir l'arbre dans son axe, quel que soit l'angle de rotation. Bien que les cannelures droites offrent un centrage similaire, elles pr\u00e9sentent des facteurs de charge li\u00e9s au d\u00e9salignement plus faibles.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Arbres clavet\u00e9s<\/h2>\n<p>Les arbres cannel\u00e9s poss\u00e8dent des dents ou des cr\u00eates qui s'embo\u00eetent pour transmettre le couple. Moins hautes que les engrenages \u00e0 d\u00e9veloppante, les cannelures assurent une transmission de couple uniforme. Elles permettent \u00e9galement des variations de couple et de rotation, et am\u00e9liorent la r\u00e9sistance \u00e0 l'usure. Outre leur durabilit\u00e9, les arbres cannel\u00e9s sont tr\u00e8s utilis\u00e9s dans l'industrie a\u00e9rospatiale, o\u00f9 ils offrent une fiabilit\u00e9 et une dur\u00e9e de vie accrues.<br \/>Les arbres clavet\u00e9s sont disponibles en diff\u00e9rents mat\u00e9riaux, longueurs et diam\u00e8tres. Utilis\u00e9s dans les applications d'entra\u00eenement de forte puissance, ils offrent un couple et des vitesses de rotation plus \u00e9lev\u00e9s. Le couple plus important qu'ils produisent contribue \u00e0 transmettre la puissance \u00e0 la bo\u00eete de vitesses. Cependant, leur durabilit\u00e9 est inf\u00e9rieure \u00e0 celle des arbres cannel\u00e9s, raison pour laquelle ces derniers sont g\u00e9n\u00e9ralement pr\u00e9f\u00e9r\u00e9s dans ces applications. Bien que plus co\u00fbteux, les arbres cannel\u00e9s sont tout aussi efficaces en mati\u00e8re de transmission du couple.<br \/>Les arbres clavet\u00e9s parall\u00e8les pr\u00e9sentent des profils et des cannelures distincts et sont utilis\u00e9s dans des applications exigeant une grande pr\u00e9cision. Les arbres clavet\u00e9s \u00e0 cannelures roul\u00e9es (35%) sont plus r\u00e9sistants que les arbres \u00e0 cannelures taill\u00e9es et sont utilis\u00e9s lorsque la pr\u00e9cision est essentielle. Ces cannelures pr\u00e9sentent \u00e9galement une finition lisse, ce qui les rend particuli\u00e8rement adapt\u00e9es aux applications de pr\u00e9cision. Elles fonctionnent aussi parfaitement avec les engrenages et autres syst\u00e8mes m\u00e9caniques n\u00e9cessitant une transmission de couple pr\u00e9cise.<br \/>L'acier au carbone est un autre mat\u00e9riau utilis\u00e9 pour les arbres cannel\u00e9s. Il est reconnu pour sa mall\u00e9abilit\u00e9, et sa faible teneur en carbone contribue \u00e0 un fonctionnement fiable. Cependant, si vous recherchez un mat\u00e9riau plus durable, privil\u00e9giez l'acier ferreux. Ce type d'acier contient des m\u00e9taux tels que le nickel, le chrome et le molybd\u00e8ne. Il est important de noter que l'acier au carbone n'est pas le seul mat\u00e9riau \u00e0 consid\u00e9rer.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"Arbre cannel\u00e9 58 cannelures pour extrudeuse \u00e0 double vis, fabriqu\u00e9 en Chine et en Allemagne. Roulement d&#039;arbre d&#039;entra\u00eenement.\t\t\t\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"Arbre cannel\u00e9 58 cannelures pour extrudeuse \u00e0 double vis, fabriqu\u00e9 en Chine et en Allemagne. Roulement d&#039;arbre d&#039;entra\u00eenement.\t\t\t\t\"><br \/>editor by CX 2023-05-15<\/p>","protected":false},"excerpt":{"rendered":"<p>Description du produit\u00a0: Arbre cannel\u00e9 Germany 58 pour extrudeuse bivis. Description du produit\u00a0: Nom du produit\u00a0: Arbre cannel\u00e9. Num\u00e9ro de mod\u00e8le\u00a0: Germany 58. \u00c9quipement d'extrusion\u00a0: Maris. Mat\u00e9riau\u00a0: 1.2343. Lieu d'origine\u00a0: Chine. Application\u00a0: Extrudeuse bivis. Capacit\u00e9 de production\u00a0: 300\u00a0m\/mois. Diam\u00e8tre de la vis\u00a0: 57,5\u00a0mm. Arbres \u00e0 double vis corotatifs pour\u00a0: APV, KOBE [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[598,1653,1756,2607,1408,1757,1654,1760,2763,713,715,1761,716,717,1115,1413,1655,1766,2764,1119,1120,1121,1619,19,620,2013,1094,1768,1769,1770,1771,2765],"class_list":["post-1185","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-china-machine","tag-china-screw-extruder","tag-china-screw-machine","tag-china-screw-manufacturer","tag-drive-screw","tag-extruder-machine","tag-extruder-screw","tag-extruder-twin-screw","tag-germany-machine","tag-machine","tag-machine-china-manufacturer","tag-machine-extruder","tag-machine-manufacturer","tag-machine-shaft","tag-manufacturer-screw","tag-screw-drive","tag-screw-extruder","tag-screw-machine","tag-screw-machine-manufacturer","tag-screw-manufacturer","tag-screw-screw","tag-screw-screw-screw","tag-screw-shaft","tag-shaft","tag-shaft-drive","tag-shaft-screw","tag-spline-shaft","tag-twin-screw","tag-twin-screw-china","tag-twin-screw-extruder","tag-twin-screw-extruder-machine","tag-twin-screw-manufacturer"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1185\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/media?parent=1185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/categories?post=1185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/tags?post=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}