{"id":1180,"date":"2023-05-08T07:34:48","date_gmt":"2023-05-08T07:34:48","guid":{"rendered":"http:\/\/splineshaft.top\/china-wholesaler-hydraulic-auger-omp-400-hydraulic-motor-drive-shaft-center-bearing\/"},"modified":"2023-05-08T07:34:48","modified_gmt":"2023-05-08T07:34:48","slug":"china-wholesaler-hydraulic-auger-omp-400-hydraulic-motor-drive-shaft-center-bearing","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/fr\/china-wholesaler-hydraulic-auger-omp-400-hydraulic-motor-drive-shaft-center-bearing\/","title":{"rendered":"China wholesaler Hydraulic Auger Omp-400 Hydraulic Motor   drive shaft center bearing"},"content":{"rendered":"<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_0_tb_body  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p><h2>Description du produit<\/h2>\n<p>\n<p><p><b>hydraulic auger omp-400 hydraulic motor<\/b><\/p>\n<p>HXIHU (WEST LAKE) DIS.U OMPW of OMPW50,OMPW80,OMPW100,OMPW125,OMPW160,OMPW200,OMPW250,OMPW315,OMPW400 hydraulic wheel motor<\/p>\n<p>1. Compact in design with spool valving motor and geroler<\/p>\n<p>2. Interchangeable with Danfos, CZPT and M+S etc.<\/p>\n<p>3. Widely applicable for machinery like forklifts, lawn mowers, lifts, loaders and excavators etc.<\/p>\n<p>4. Shaft diameter: 25 MM. Thread: 1\/2&#8243; BSP<\/p>\n<p>5. Very competitive price<\/p>\n<p>6. 1 year of warranty<\/p>\n<p>7. Imported high pressure capacity shaft seal design<\/p>\n<p>8. Design and manufacturing of the spline and drives give the motor durability<\/p>\n<p>9. Wide variety of mounting flanges, shafts,ports and speed provides design flexibility<\/p>\n<p>10. Direction of shaft rotation and speed can be controlled easily and smoothly<\/p>\n<p>11. Best combination of high efficiency and ecnomy in medium duty applications.<\/p>\n<p>\u00a0<\/p>\n<p>Technical Specifications<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td>\n<p>Part\u00a0no.<\/p>\n<\/td>\n<td>\n<p>Displace. ml\/r<\/p>\n<\/td>\n<td>\n<p>Max.\u00a0cont.\u00a0press. bar<\/p>\n<\/td>\n<td>\n<p>Max.\u00a0cont.\u00a0<\/p>\n<p>rpm<\/p>\n<\/td>\n<td>\n<p>Max.\u00a0cont.\u00a0torque<\/p>\n<p>N.m<\/p>\n<\/td>\n<td>\n<p>Max.\u00a0cont.\u00a0power<\/p>\n<p>Kw<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW050<\/p>\n<\/td>\n<td>\n<p>48,6<\/p>\n<\/td>\n<td>\n<p>140<\/p>\n<\/td>\n<td>\n<p>1230<\/p>\n<\/td>\n<td>\n<p>9.3<\/p>\n<\/td>\n<td>\n<p>10.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW080<\/p>\n<\/td>\n<td>\n<p>77.8<\/p>\n<\/td>\n<td>\n<p>140<\/p>\n<\/td>\n<td>\n<p>770<\/p>\n<\/td>\n<td>\n<p>15.0<\/p>\n<\/td>\n<td>\n<p>10.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW100<\/p>\n<\/td>\n<td>\n<p>97,3<\/p>\n<\/td>\n<td>\n<p>140<\/p>\n<\/td>\n<td>\n<p>615<\/p>\n<\/td>\n<td>\n<p>19.0<\/p>\n<\/td>\n<td>\n<p>11,0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW125<\/p>\n<\/td>\n<td>\n<p>125.0<\/p>\n<\/td>\n<td>\n<p>140<\/p>\n<\/td>\n<td>\n<p>480<\/p>\n<\/td>\n<td>\n<p>24.0<\/p>\n<\/td>\n<td>\n<p>10.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW160<\/p>\n<\/td>\n<td>\n<p>155.7<\/p>\n<\/td>\n<td>\n<p>140<\/p>\n<\/td>\n<td>\n<p>385<\/p>\n<\/td>\n<td>\n<p>30.0<\/p>\n<\/td>\n<td>\n<p>10.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW200<\/p>\n<\/td>\n<td>\n<p>194,6<\/p>\n<\/td>\n<td>\n<p>115<\/p>\n<\/td>\n<td>\n<p>310<\/p>\n<\/td>\n<td>\n<p>30.0<\/p>\n<\/td>\n<td>\n<p>8.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW250<\/p>\n<\/td>\n<td>\n<p>242,3<\/p>\n<\/td>\n<td>\n<p>90<\/p>\n<\/td>\n<td>\n<p>250<\/p>\n<\/td>\n<td>\n<p>30.0<\/p>\n<\/td>\n<td>\n<p>6.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW315<\/p>\n<\/td>\n<td>\n<p>306,1<\/p>\n<\/td>\n<td>\n<p>75<\/p>\n<\/td>\n<td>\n<p>195<\/p>\n<\/td>\n<td>\n<p>30.0<\/p>\n<\/td>\n<td>\n<p>5.0<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>OMPW400<\/p>\n<\/td>\n<td>\n<p>389,2<\/p>\n<\/td>\n<td>\n<p>60<\/p>\n<\/td>\n<td>\n<p>155<\/p>\n<\/td>\n<td>\n<p>30.0<\/p>\n<\/td>\n<td>\n<p>4.0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<p>HXIHU (WEST LAKE) DIS.U\u00a0TECHNOLOGY\u00a0,\u00a0a\u00a0hydraulic\u00a0company,\u00a0has\u00a0quickly\u00a0innovated\u00a0and\u00a0improved\u00a0all\u00a0aspects\u00a0of\u00a0its\u00a0products\u00a0and\u00a0services.\u00a0It\u00a0is\u00a0one\u00a0of\u00a0the\u00a0very\u00a0famous\u00a0hydraulic\u00a0motors\u00a0manufacturers\u00a0in\u00a0China,\u00a0and\u00a0it\u00a0already\u00a0has\u00a0a\u00a0good\u00a0position\u00a0in\u00a0the\u00a0Chinese\u00a0market.\u00a0Influenced\u00a0by\u00a0the\u00a0acquisition\u00a0of\u00a0Danfos,\u00a0it\u00a0is\u00a0upgrading\u00a0its\u00a0industrial\u00a0chain\u00a0and\u00a0expanding\u00a0its\u00a0business\u00a0scope.\u00a0While\u00a0improving\u00a0technology,\u00a0they\u00a0also\u00a0minimize\u00a0profits,\u00a0form\u00a0price\u00a0and\u00a0quality\u00a0advantages,\u00a0and\u00a0are\u00a0committed\u00a0to\u00a0developing\u00a0the\u00a0most\u00a0cost-effective\u00a0hydraulic\u00a0and\u00a0other\u00a0related\u00a0products\u00a0in\u00a0the\u00a0market,\u00a0so\u00a0as\u00a0to\u00a0enhance\u00a0the\u00a0market\u00a0competitiveness\u00a0of\u00a0hyd\u00a0motor\u00a0and\u00a0strive\u00a0for\u00a0good\u00a0in\u00a0the\u00a0international\u00a0market.\u00a0reputation\u00a0and\u00a0achievements!<\/p>\n<p>If\u00a0you\u00a0are\u00a0a\u00a0hydraulic\u00a0importer\u00a0or\u00a0distributor,\u00a0please\u00a0contact\u00a0us\u00a0to\u00a0discuss\u00a0cooperation.<\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Taper:<\/th>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Usage:<\/th>\n<td>Mining Excavator<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Transmission:<\/th>\n<td>Hydraulic Transmission<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Drive Type:<\/th>\n<td>Electric Drive<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Certification :<\/th>\n<td>CE, ISO9001: 2000<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Condition:<\/th>\n<td>Nouveau<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                        <i class=\"ob-icon icon-fill\"><\/i>Demande personnalis\u00e9e<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Approches analytiques pour l'estimation des pressions de contact dans les accouplements cannel\u00e9s<\/h2>\n<p>Un accouplement cannel\u00e9 est un type de liaison m\u00e9canique entre deux arbres rotatifs. Il se compose de deux parties\u00a0: un coupleur et un accouplement. Ces deux parties comportent des dents qui s'engr\u00e8nent et transmettent les charges. Cependant, les accouplements cannel\u00e9s sont g\u00e9n\u00e9ralement surdimensionn\u00e9s, ce qui les rend sensibles \u00e0 la fatigue et aux contraintes statiques. L'usure peut \u00e9galement entra\u00eener leur d\u00e9faillance. C'est pourquoi une conception appropri\u00e9e est essentielle pour obtenir des performances optimales.<\/p>\n<h2>Mod\u00e9lisation d'un accouplement spline<\/h2>\n<p>Les accouplements cannel\u00e9s sont de plus en plus utilis\u00e9s dans l'industrie a\u00e9rospatiale, mais leur fonctionnement avec un l\u00e9ger d\u00e9faut d'alignement engendre des vibrations et endommage les surfaces de contact. Pour rem\u00e9dier \u00e0 ce probl\u00e8me, cet article propose des m\u00e9thodes analytiques d'estimation des pressions de contact dans un accouplement cannel\u00e9. Plus pr\u00e9cis\u00e9ment, il compare ces m\u00e9thodes analytiques \u00e0 des m\u00e9thodes purement num\u00e9riques afin de d\u00e9montrer les avantages de l'approche analytique.<br \/>Pour mod\u00e9liser un accouplement spline, il faut d'abord cr\u00e9er sa base de connaissances. Celle-ci comprend un grand nombre de valeurs de sp\u00e9cification possibles, interd\u00e9pendantes. Toute modification d'une sp\u00e9cification peut entra\u00eener une violation d'une autre. Pour que la conception soit valide, le mod\u00e8le d'accouplement spline doit respecter les valeurs de sp\u00e9cification d\u00e9finies.<br \/>Apr\u00e8s avoir mod\u00e9lis\u00e9 la g\u00e9om\u00e9trie, vous devez saisir les pressions de contact des deux accouplements cannel\u00e9s. Ensuite, vous devez d\u00e9terminer la position du cercle primitif de la cannelure. Sur la figure 2, le centre de l'accouplement m\u00e2le est superpos\u00e9 \u00e0 celui de la cannelure femelle. Enfin, vous devez vous assurer que la distance d'engr\u00e8nement des deux cannelures est identique.<br \/>Une fois les donn\u00e9es n\u00e9cessaires \u00e0 la cr\u00e9ation d'un mod\u00e8le d'accouplement cannel\u00e9 recueillies, vous pouvez commencer par saisir les sp\u00e9cifications de conception de l'interface. Vous devrez ensuite choisir d'optimiser la cannelure interne ou externe. Il vous faudra \u00e9galement sp\u00e9cifier le coefficient de frottement des dents, utilis\u00e9 pour d\u00e9terminer les contraintes dans le mod\u00e8le d'accouplement cannel\u00e9 20. Enfin, vous devrez saisir le jeu de guidage, c'est-\u00e0-dire le jeu entre l'extr\u00e9mit\u00e9 186 d'une dent 32 d'une cannelure et l'\u00e9l\u00e9ment de la cannelure correspondante.<br \/>Apr\u00e8s avoir saisi les sp\u00e9cifications souhait\u00e9es pour la cannelure externe, vous pouvez entrer les param\u00e8tres de la cannelure interne. Par exemple, vous pouvez indiquer la limite du diam\u00e8tre ext\u00e9rieur 154 de l'enclenchement principal 54 et l'enclenchement secondaire 56 de la cannelure interne. Les valeurs de ces param\u00e8tres s'affichent dans des cases color\u00e9es sur l'\u00e9cran 80 de l'interface graphique \u00ab\u00a0Entr\u00e9es et configuration de la cannelure\u00a0\u00bb. Une fois les param\u00e8tres saisis, une repr\u00e9sentation g\u00e9om\u00e9trique du mod\u00e8le d'accouplement de la cannelure 20 s'affiche.<\/p>\n<h2>Cr\u00e9ation d'un mod\u00e8le de couplage spline 20<\/h2>\n<p>Le mod\u00e8le d'accouplement spline 20 est cr\u00e9\u00e9 par le logiciel de mod\u00e9lisation de produits 10. Ce logiciel valide le mod\u00e8le d'accouplement spline par rapport \u00e0 une base de connaissances contenant les contraintes et relations de sp\u00e9cification d\u00e9pendantes de la configuration. Ce rapport est ensuite int\u00e9gr\u00e9 au logiciel d'analyse des contraintes ANSYS. Il r\u00e9pertorie les configurations g\u00e9om\u00e9triques du mod\u00e8le d'accouplement spline 20 ainsi que les valeurs de sp\u00e9cification pour chaque \u00e9l\u00e9ment. Le mod\u00e8le d'accouplement spline 20 est automatiquement recr\u00e9\u00e9 \u00e0 chaque modification de ses sp\u00e9cifications de configuration ou de performance.<br \/>Le mod\u00e8le d'accouplement cannel\u00e9 20 peut \u00eatre configur\u00e9 \u00e0 l'aide du logiciel de mod\u00e9lisation de produit 10. L'utilisateur sp\u00e9cifie la longueur axiale de l'empilement de cannelures, qui peut \u00eatre nulle ou fixe. Il saisit \u00e9galement la face d'accouplement radiale 148, le cas \u00e9ch\u00e9ant, et s\u00e9lectionne une valeur de jeu de guidage de 14,5\u00b0 ou 30\u00b0.<br \/>L'utilisateur peut ensuite utiliser la souris (110) pour modifier le mod\u00e8le de couplage spline (20). La base de connaissances relative au couplage spline contient un grand nombre de valeurs de sp\u00e9cification possibles ainsi que la r\u00e8gle de conception du couplage spline. Si l'utilisateur tente de modifier un mod\u00e8le de couplage spline, un avertissement signalant une violation d'une autre sp\u00e9cification s'affiche. Dans certains cas, la modification peut invalider la conception.<br \/>Dans le mod\u00e8le d'accouplement cannel\u00e9 20, l'utilisateur saisit des sp\u00e9cifications de performance suppl\u00e9mentaires. Il choisit les emplacements de transmission du couple maximal pour les cannelures internes et externes 38 et 40. L'emplacement de transmission du couple maximal est d\u00e9termin\u00e9 par la configuration de fixation des \u00e9l\u00e9ments de fixation aux arbres. Une fois cette option s\u00e9lectionn\u00e9e, l'utilisateur peut cliquer sur \u00ab\u00a0Suivant\u00a0\u00bb pour enregistrer le mod\u00e8le. Un aper\u00e7u de l'accouplement cannel\u00e9 20 s'affiche.<br \/>Le mod\u00e8le 20 repr\u00e9sente un accouplement cannel\u00e9. Les sp\u00e9cifications de l'accouplement sont saisies dans l'ordre et la disposition indiqu\u00e9s sur l'interface graphique du mod\u00e8le 20. Une fois ces sp\u00e9cifications saisies, le logiciel de mod\u00e9lisation du produit 10 les int\u00e8gre au mod\u00e8le 20. Il s'agit de la derni\u00e8re \u00e9tape de la cr\u00e9ation du mod\u00e8le d'accouplement cannel\u00e9.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Analyse d'un mod\u00e8le de couplage spline 20<\/h2>\n<p>L'analyse d'un mod\u00e8le d'accouplement cannel\u00e9 consiste \u00e0 saisir ses sp\u00e9cifications de configuration et de performance. Ces sp\u00e9cifications peuvent \u00eatre g\u00e9n\u00e9r\u00e9es par un autre logiciel. Le logiciel de mod\u00e9lisation du produit 10 utilise ensuite sa base de connaissances interne, qui recense les relations et contraintes li\u00e9es \u00e0 la configuration, pour cr\u00e9er un mod\u00e8le param\u00e9trique tridimensionnel valide 20. Ce mod\u00e8le contient des informations d\u00e9crivant le nombre et le type de dents 32, d'enclenchements 34 et d'\u00e9paulement 36 de l'accouplement cannel\u00e9.<br \/>Lors de l'analyse d'un accouplement spline, le logiciel 10 int\u00e8gre des valeurs par d\u00e9faut pour diff\u00e9rentes sp\u00e9cifications. Le mod\u00e8le d'accouplement spline 20 comprend une spline interne 38 et une spline externe 40. Chaque spline poss\u00e8de ses propres param\u00e8tres, tels que sa profondeur, sa largeur, sa longueur et ses rayons. La spline externe 40 poss\u00e8de \u00e9galement ses propres param\u00e8tres, notamment son orientation.<br \/>Apr\u00e8s la s\u00e9lection de ces param\u00e8tres, le logiciel effectuera diverses analyses sur le mod\u00e8le d'accouplement cannel\u00e9 20. Le logiciel 10 calculera les contraintes nominales et maximales sur les appuis de dents, ainsi que la dur\u00e9e de vie en fatigue de l'accouplement. Il d\u00e9terminera \u00e9galement la diff\u00e9rence de torsion entre une cannelure interne et une cannelure externe. Le fichier de sortie de l'analyse sera un rapport contenant les donn\u00e9es de configuration et de sp\u00e9cification du mod\u00e8le. Ce fichier pourra \u00e9galement \u00eatre utilis\u00e9 par d'autres logiciels pour des analyses compl\u00e9mentaires.<br \/>Une fois ces param\u00e8tres d\u00e9finis, l'utilisateur saisit les crit\u00e8res de conception du mod\u00e8le d'accouplement cannel\u00e9 20. \u00c0 cette \u00e9tape, il sp\u00e9cifie les emplacements de transmission de couple maximale pour les cannelures externe et interne 38. L'emplacement de transmission de couple maximale d\u00e9pend de la configuration des \u00e9l\u00e9ments fix\u00e9s aux arbres. L'utilisateur peut saisir jusqu'\u00e0 quatre sp\u00e9cifications de performance diff\u00e9rentes pour chaque cannelure.<br \/>L'analyse r\u00e9v\u00e8le deux phases d'accouplement des splines. La premi\u00e8re phase se caract\u00e9rise par une forte augmentation des contraintes et des vibrations. La seconde phase montre une diminution de ces deux param\u00e8tres. La troisi\u00e8me phase se traduit par une force d'engr\u00e8nement constante comprise entre 300 N et 320 N. Ce comportement se maintient jusqu'\u00e0 l'engagement final avec la surface.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>D\u00e9salignement d'un accouplement cannel\u00e9<\/h2>\n<p>Une \u00e9tude a \u00e9t\u00e9 men\u00e9e afin d'examiner la position de la force de contact r\u00e9sultante dans un accouplement cannel\u00e9 en prise avec des dents soumises \u00e0 un couple constant et \u00e0 un d\u00e9faut d'alignement rotatif. Cette \u00e9tude a utilis\u00e9 des m\u00e9thodes num\u00e9riques bas\u00e9es sur la m\u00e9thode des \u00e9l\u00e9ments finis (MEF). Elle a produit des r\u00e9sultats num\u00e9riques pour des conditions nominales et un d\u00e9faut d'alignement parall\u00e8le. L'\u00e9tude a consid\u00e9r\u00e9 deux niveaux de d\u00e9faut d'alignement \u2013 \u200b\u200b0,02 mm et 0,08 mm \u2013 avec diff\u00e9rents niveaux de charge.<br \/>Les r\u00e9sultats ont montr\u00e9 que le d\u00e9faut d'alignement entre les cannelures et les rotors induit une modification de la force d'engr\u00e8nement du syst\u00e8me d'accouplement cannelure-rotor. La dynamique de ce syst\u00e8me est r\u00e9gie par la force d'engr\u00e8nement des cannelures. La force d'engr\u00e8nement d'un accouplement cannelure d\u00e9salign\u00e9 d\u00e9pend des param\u00e8tres du syst\u00e8me d'accouplement rotor-cannelure, du couple transmis et du d\u00e9placement vibratoire dynamique.<br \/>Malgr\u00e9 l'absence de mesures pr\u00e9cises, le d\u00e9faut d'alignement des cannelures est un probl\u00e8me courant. Ce probl\u00e8me est aggrav\u00e9 par le jeu inh\u00e9rent aux cannelures, jeu qui r\u00e9sulte du d\u00e9faut d'alignement. Les auteurs ont analys\u00e9 plusieurs cannelures, en faisant varier le diam\u00e8tre primitif et le rapport longueur\/diam\u00e8tre.<br \/>Un accouplement cannel\u00e9 est un syst\u00e8me m\u00e9canique bidimensionnel pr\u00e9sentant un jeu positif. Il est compos\u00e9 d'un moyeu et d'un arbre, et les jeux entre les extr\u00e9mit\u00e9s des cannelures sont sup\u00e9rieurs au jeu angulaire. Un jeu de forme suffisant emp\u00eache le contact entre les cong\u00e9s de raccordement. Le couple sur les cannelures est transmis par frottement.<br \/>Lorsqu'un accouplement cannel\u00e9 est d\u00e9salign\u00e9, une force de pouss\u00e9e, modul\u00e9e par le couple, est g\u00e9n\u00e9r\u00e9e. Dans ce cas, cette force peut exc\u00e9der le couple, entra\u00eenant le d\u00e9salignement du composant. La transmission bidirectionnelle du couple et de la pouss\u00e9e est mod\u00e9lis\u00e9e analytiquement dans cette \u00e9tude. L'approche analytique fournit des solutions int\u00e9grables au processus de conception. Ainsi, face \u00e0 un probl\u00e8me d'accouplement cannel\u00e9 d\u00e9salign\u00e9, privil\u00e9giez une approche analytique\u00a0!<br \/>Dans cette \u00e9tude, l'accouplement cannel\u00e9 est analys\u00e9 dans des conditions nominales, sans d\u00e9faut d'alignement parall\u00e8le. Les valeurs de rigidit\u00e9 obtenues correspondent \u00e0 la diff\u00e9rence en pourcentage entre le diam\u00e8tre primitif nominal et le diam\u00e8tre d'application de la charge. De plus, la diff\u00e9rence maximale en pourcentage du diam\u00e8tre primitif mesur\u00e9 est de 1,60% sous un couple de 5\u00a0000\u00a0N\u00b7m. L'angle d'h\u00e9lice est \u00e9galement pris en compte dans le calcul.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China wholesaler Hydraulic Auger Omp-400 Hydraulic Motor   drive shaft center bearing\t\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China wholesaler Hydraulic Auger Omp-400 Hydraulic Motor   drive shaft center bearing\t\t\"><br \/>editor by CX 2023-05-08<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description hydraulic auger omp-400 hydraulic motor HXIHU (WEST LAKE) DIS.U OMPW of OMPW50,OMPW80,OMPW100,OMPW125,OMPW160,OMPW200,OMPW250,OMPW315,OMPW400 hydraulic wheel motor 1. Compact in design with spool valving motor and geroler 2. Interchangeable with Danfos, CZPT and M+S etc. 3. Widely applicable for machinery like forklifts, lawn mowers, lifts, loaders and excavators etc. 4. Shaft diameter: 25 MM. Thread: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2757,2758,1737,430,1702,131,2759,2760,2158,2761,2159,268,1704,1741,456,1520,19,620,1521,970],"class_list":["post-1180","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-auger-hydraulic","tag-auger-shaft","tag-china-hydraulic-motor","tag-china-motor","tag-drive-motor-shaft","tag-hydraulic","tag-hydraulic-auger","tag-hydraulic-auger-motor","tag-hydraulic-drive","tag-hydraulic-drive-auger","tag-hydraulic-drive-motor","tag-motor","tag-motor-drive","tag-motor-hydraulic","tag-motor-motor","tag-motor-shaft","tag-shaft","tag-shaft-drive","tag-shaft-motor","tag-shaft-wholesaler"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/comments?post=1180"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1180\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/media?parent=1180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/categories?post=1180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/tags?post=1180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}