{"id":1174,"date":"2023-04-24T02:06:10","date_gmt":"2023-04-24T02:06:10","guid":{"rendered":"http:\/\/splineshaft.top\/china-high-quality-oem-cnc-machinery-pinion-shaft-drive-main-shaft-oem-forging-steel-transmission-spline-shaft-differential-drive-shaft\/"},"modified":"2023-04-24T02:06:10","modified_gmt":"2023-04-24T02:06:10","slug":"china-high-quality-oem-cnc-machinery-pinion-shaft-drive-main-shaft-oem-forging-steel-transmission-spline-shaft-differential-drive-shaft","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/fr\/china-high-quality-oem-cnc-machinery-pinion-shaft-drive-main-shaft-oem-forging-steel-transmission-spline-shaft-differential-drive-shaft\/","title":{"rendered":"China high quality OEM CNC Machinery Pinion Shaft Drive Main Shaft OEM Forging Steel Transmission Spline Shaft   differential drive shaft"},"content":{"rendered":"<div class=\"et_pb_column et_pb_column_3_4 et_pb_column_0_tb_body  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_post_content et_pb_post_content_0_tb_body\">\n<p><h2>Description du produit<\/h2>\n<p>\n<p><h2>OEM CNC Machinery Pinion Shaft Drive Main Shaft OEM Forging Steel Transmission Spline Shaft<\/h2>\n<p>We have the completed machining equipment,including horizontal lathe,vertical lathe,CNC boring and milling machine,CNC boring machine,deep hole drilling and boring machine, gear hobbing machine,gear teeth grinding machine,grinding machine,etc.<\/p>\n<p>Strictly quality inspection system can produce high quality productsFor each order,we can provide report for material chemical components testing,UT testing,hardness,mechanical property testing(impact testing,yield strength testing,tensile strength testing),size inspection,etc.<\/p>\n<p><u><b>Description du produit\u00a0<\/b><\/u><\/p>\n<p>\n<table border=\"1\" cellpadding=\"1\" cellspacing=\"1\">\n<tbody>\n<tr>\n<td>Article<\/td>\n<td>Arbre<\/td>\n<\/tr>\n<tr>\n<td>Application<\/td>\n<td>Grues, voies ferr\u00e9es, machines mini\u00e8res, machines hydrauliques, pi\u00e8ces de rechange, etc.<\/td>\n<\/tr>\n<tr>\n<td>Conception<\/td>\n<td>Peut \u00eatre r\u00e9alis\u00e9 sur demande du client, sur mesure, selon le design du client<\/td>\n<\/tr>\n<tr>\n<td>Mat\u00e9riel<\/td>\n<td>Stainless Steel, Carbon\u00a0Steel or Alloy Steel, such as 45#, 65# SAE4140, SAE4150, SAE4160, 42CrMo, stainless steel 410, stainless steel 304, or other required steel<\/td>\n<\/tr>\n<tr>\n<td>Taille<\/td>\n<td>Diameter 10mm to 1000mm. Length max.in 6000mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p><strong>Our company advantage:<\/strong>\u00a0<br \/>1.\u00a0Advanced\u00a0inspection\u00a0equipment\u00a0for\u00a0rigorous\u00a0quality\u00a0and\u00a0control\u00a0and\u00a0precise\u00a0specification.<br \/>2.\u00a0We\u00a0are\u00a0a\u00a0direct\u00a0manufacturer,\u00a0have\u00a0lots\u00a0of\u00a0experience\u00a0for\u00a0packing\u00a0machine\u00a0parts\u00a0and\u00a0medical\u00a0parts.<br \/>3.\u00a0Customizing\u00a0inspection\u00a0report,\u00a0providing\u00a0the\u00a0material\u00a0certification.<br \/>4.\u00a0All\u00a0sorts\u00a0of\u00a0drawing\u00a0formats\u00a0are\u00a0available.\u00a0For\u00a0example:\u00a0PRO\/E,\u00a0solid\u00a0works,\u00a0Ci-matron,\u00a0Auto\u00a0CAD\u00a0and\u00a0so\u00a0on.<br \/>5.\u00a0Young\u00a0manage\u00a0team\u00a0with\u00a0efficient\u00a0productivity,\u00a0quick\u00a0response\u00a0and\u00a0modern\u00a0business\u00a0concept.<br \/><b>Processus de fabrication<\/b><br \/>*Free forged or module forged<br \/>*Rough machining process, to remove the surface forged oxidized black leather.<br \/>*100% Ultrasonic Test ASTMA388<br \/>*Heat Treatment according to request, Normalized, Quenched, Tempered&#8230;.<br \/>*Hardness test<br \/>*Finishing Process to the dimensional state required by the drawing.<br \/>*100% Magnetic Test ASTM E709 and 100% dimensional test<br \/>*Painting or oil protecting<br \/>*Packing with boxes<\/p>\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td>Avantages<\/td>\n<td colspan=\"6\">\u00bbReliable Forging\/CNC Machining service<br \/>\u00bbGood machining quality<br \/>\u00bbReasonable Pricing provided<br \/>\u00bbCompetitive shipping cost service<br \/>\u00bbMOQ 1PCS and small quantity order accepted<br \/>\u00bbProfessional engineering service when any modification required<br \/>\u00bbAny turnkey assembly or customized package requirements, we&#8217;ll meet your demands!<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\">Demande de devis<\/td>\n<td colspan=\"6\" rowspan=\"3\">Customer Inquiry \u2192Engineering Communication \u2192Cost Analysis \u2192Sales Analysis \u2192<br \/>Quote to Customer<br \/>\u00bb 1 \u00e0 3 jours ouvrables seulement<br \/>\u00bb Submit RFQ with complete commercial terms<\/td>\n<\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr>\n<td rowspan=\"4\">Fabrication d'\u00e9chantillons<\/td>\n<td colspan=\"6\" rowspan=\"4\">Sample Order \u2192 Engineering Review \u2192 Sample Plan to Customer \u2192 Sample Status Tracking \u2192 Submit Samples with Doc.<br \/>\u00bb Tooling L\/T: 2-4 weeks, Sample L\/T: 1 week<br \/>\u00bb Continuous Sample Status Tracking<br \/>\u00bb Complete Documents for sample approval<\/td>\n<\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr>\n<td rowspan=\"4\">Order Management<\/td>\n<td colspan=\"6\" rowspan=\"4\">CRM System \u2192 Open Order Confirm \u2192 Logistic Arrangement.<br \/>\u00bb Production L\/T: 4-8 weeks<br \/>\u00bb Weekly Open Order Confirm<br \/>\u00bb Preferred 3PL Service to Customers<\/td>\n<\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr>\n<td rowspan=\"3\">Contr\u00f4le de qualit\u00e9<\/td>\n<td colspan=\"6\" rowspan=\"3\">Certifications : RoHS, ISO9001:2008, SGS.<br \/>IQC \u2192 IPQC \u2192 OQC\/FQC \u2192 Quality Complain Feedback \u2192 Audit &amp; Training.<br \/>\u00bb Plant Audit and Qualified by world famous company<br \/>\u00bb Strict Quality Management Procedure with Traceability<\/td>\n<\/tr>\n<tr><\/tr>\n<tr><\/tr>\n<tr>\n<td rowspan=\"2\">Application<\/td>\n<td colspan=\"6\" rowspan=\"2\">\u00bbAerospace<br \/>\u00bbMarine<br \/>\u00bbMotorbike<br \/>\u00bbAutomotive<br \/>\u00bbPhotoGear<br \/>\u00bbEDC Tools<br \/>\u00bb lighting fittings<br \/>\u00bbMedical equipment<br \/>\u00bbTelecommunication<br \/>\u00bbElectrical &amp; Electronics<br \/>\u00bbFire detection system, etc.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>In\u00a0order\u00a0to\u00a0ensure\u00a0the\u00a0quality\u00a0of\u00a0the\u00a0orders,our\u00a0independent\u00a0QC\u00a0members\u00a0to\u00a0carry\u00a0out\u00a0strict\u00a0inspection\u00a0at\u00a0each\u00a0<br \/>stage:<br \/>*Raw Material Quality Control: Chemical Composition Analysis, Mechanical Performance Test<br \/>*Production Process Quality Control: Full-size inspection for the 1st part, Critical size process inspection, SPC process monitoring<br \/>*Lab ability: CMM, OGP, XRF, Roughness meter, Profiler, Automatic optical inspector<br \/>*Quality system: ISO9001<\/p>\n<p>FAQ :\u00a0<\/p>\n<p>1) How can I place order?<\/p>\n<p>A: You can contact us by email about your order details, or place order on line.<\/p>\n<p>\u00a0<\/p>\n<p>2) How can I pay you?<\/p>\n<p>A: After you confirm our PI. we will request you to arrange payment by T\/T.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>3) What&#8217;s the order procedure?<\/p>\n<p>A: First we discuss order details, production details by email or TM. Then we issue you an PI for your confirmation. You will be requested to do pre-paid full payment or 30% deposit before we go into production. After we get the deposit, we start to process the order. We usually need 4-8 weeks if we don&#8217;t have the items in stock. Before production has been finished, we will contact you for shipment details, start to prepare the shipment for you, and the balance payment should be settled before delivery.<\/p>\n<p>\u00a0<\/p>\n<p>4) How do you take care when your clients received defective products?<\/p>\n<p>A: replacement. If there are some defective items, we usually credit to our customer or replace them in next shipment.<\/p>\n<p>\u00a0<\/p>\n<p>5) How do you check all the goods in the production line?<\/p>\n<p>A: We have spot inspection and finished product inspection. We check the goods when they go into next step production procedure. And all the goods will be tested after welding, assure 100% no leaking problems.<\/p>\n<p><b>\u00a0 \u00a0 \u00a0Trade:<\/b><br \/>\u00a0 \u00a0 \u00a0Your inquiry will be replied within 12 hours.<br \/>\u00a0 \u00a0 \u00a0Well-trained &amp; experienced sales can reply your inquiries in English.<br \/>\u00a0 \u00a0 \u00a0During working time, E-mail will be replied to you within 2 hours<br \/>\u00a0 \u00a0 \u00a0OEM &amp; ODM projects are highly welcomed. We have strong R&amp;D team.<br \/>\u00a0 \u00a0 \u00a0The order will be produced exactly according to order details and proofed samples.<br \/>\u00a0 \u00a0 \u00a0Our QC will submitinspection report before shipment.<br \/>\u00a0 \u00a0 \u00a0Your business relationship with us will be confidential to any third party.<br \/>\u00a0 \u00a0 \u00a0Good after-sale service.\u00a0<\/p>\n<p><strong><em>If there&#8217;s anything we could help, please feel free to contact us.<\/em><\/strong><br \/>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">\n                                Frais d'exp\u00e9dition :<\/p>\n<div class=\"freight-tips help-tips J-help\">\n                                    <i class=\"ob-icon icon-problem\"><\/i><\/p>\n<div class=\"tips tips-system J-tips\">\n<div class=\"tips-con\">\n<p>Frais de transport estim\u00e9s par unit\u00e9.<\/p>\n<p>                                            <span class=\"arrow arrow-top\"><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"arrow arrow-in\"><\/span><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n                                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/th>\n<td>\n                                \u00c0 n\u00e9gocier\n                            <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Mat\u00e9riel:<\/th>\n<td>Acier au carbone<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Charger:<\/th>\n<td>Arbre de transmission<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Rigidit\u00e9 et flexibilit\u00e9 :<\/th>\n<td>Rigidit\u00e9 \/ Essieu rigide<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"attr-line\"><\/div>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 1\/Pi\u00e8ce<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                                <i class=\"ob-icon icon-product\"><\/i>Commander un \u00e9chantillon<\/p><\/div>\n<div class=\"sample-order-desc\">laser cutting parts<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><\/p>\n<p>                                        <i class=\"ob-icon icon-fill\"><\/i>Demande personnalis\u00e9e<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Applications des accouplements cannel\u00e9s<\/h2>\n<p>Un accouplement cannel\u00e9 est un moyen tr\u00e8s efficace de relier deux composants ou plus. Ce type d'accouplement est particuli\u00e8rement performant, car il combine mouvement lin\u00e9aire et rotation, ce qui en fait un choix judicieux pour de nombreuses applications. Poursuivez votre lecture pour en savoir plus sur les principales caract\u00e9ristiques et applications des accouplements cannel\u00e9s. Vous pourrez \u00e9galement d\u00e9terminer leur fonctionnement et leur usure pr\u00e9vus. Vous pouvez facilement concevoir vos propres accouplements en suivant les \u00e9tapes d\u00e9crites ci-dessous.<\/p>\n<h2>Conception optimale<\/h2>\n<p>L'accouplement cannel\u00e9 joue un r\u00f4le important dans la transmission du couple. Il se compose d'un moyeu et d'un arbre dont les cannelures sont en contact et sans mouvement relatif. Du fait de leur liaison, leur vitesse angulaire est identique. Les cannelures peuvent \u00eatre con\u00e7ues avec n'importe quel profil minimisant le frottement. Le contact entre les cannelures entra\u00eene une r\u00e9partition in\u00e9gale de la charge, qui se concentre sur une petite surface, pouvant d\u00e9former le moyeu.<br \/>La conception optimale des accouplements cannel\u00e9s tient compte de plusieurs facteurs, notamment le poids, les caract\u00e9ristiques des mat\u00e9riaux et les exigences de performance. Dans l'industrie a\u00e9ronautique, le poids est un facteur de conception important. Les tableaux SAE et ANSI ne prennent pas en compte le poids lors du calcul des exigences de performance des accouplements cannel\u00e9s. L'encombrement est un autre facteur critique. Les accouplements cannel\u00e9s peuvent devoir \u00eatre install\u00e9s dans des espaces restreints ou \u00eatre soumis \u00e0 d'autres contraintes de configuration.<br \/>La conception optimale des accouplements cannel\u00e9s peut se caract\u00e9riser par un nombre impair de dents. Cependant, ce n'est pas toujours le cas. Si le diam\u00e8tre ext\u00e9rieur de la cannelure d\u00e9passe un certain seuil, le mod\u00e8le d'accouplement cannel\u00e9 optimal peut ne pas convenir \u00e0 l'application. Pour optimiser un accouplement cannel\u00e9 pour une application sp\u00e9cifique, l'utilisateur devra peut-\u00eatre choisir la m\u00e9thode de dimensionnement la plus appropri\u00e9e.<br \/>Une fois la conception g\u00e9n\u00e9r\u00e9e, l'\u00e9tape suivante consiste \u00e0 tester l'accouplement cannel\u00e9 obtenu. Le syst\u00e8me doit v\u00e9rifier l'absence de contraintes de conception et valider sa faisabilit\u00e9 \u00e0 l'aide des techniques de fabrication modernes. Le mod\u00e8le d'accouplement cannel\u00e9 r\u00e9sultant est ensuite export\u00e9 vers un outil d'optimisation pour une analyse plus approfondie. Cette m\u00e9thode permet au concepteur de modifier facilement la conception d'un accouplement cannel\u00e9 et d'en r\u00e9duire le poids.<br \/>Le mod\u00e8le d'accouplement cannel\u00e9 20 comprend les principales caract\u00e9ristiques structurelles d'un accouplement cannel\u00e9. Un logiciel de mod\u00e9lisation de produit 10 stocke les valeurs par d\u00e9faut de chaque sp\u00e9cification de l'accouplement. Le mod\u00e8le de cannelure r\u00e9sultant est ensuite calcul\u00e9 conform\u00e9ment \u00e0 l'algorithme utilis\u00e9 dans la pr\u00e9sente invention. Le logiciel permet au concepteur de saisir les rayons, l'\u00e9paisseur et l'orientation de l'accouplement.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Caract\u00e9ristiques<\/h2>\n<p>Un aspect important des cannelures de moteurs a\u00e9ronautiques r\u00e9side dans la r\u00e9partition de la charge entre les dents. Les chercheurs ont men\u00e9 des essais exp\u00e9rimentaux et analys\u00e9 l'influence des conditions de lubrification sur le comportement de l'accouplement. Ils ont ensuite \u00e9labor\u00e9 un mod\u00e8le th\u00e9orique, bas\u00e9 sur le param\u00e8tre de Ruiz, afin de simuler les conditions de fonctionnement r\u00e9elles des accouplements cannel\u00e9s. Ce mod\u00e8le explique l'usure caus\u00e9e par ces accouplements en prenant en compte l'influence du frottement, du d\u00e9faut d'alignement et d'autres facteurs affectant les performances des cannelures.<br \/>Pour concevoir un accouplement cannel\u00e9, l'utilisateur saisit d'abord les crit\u00e8res de dimensionnement des \u00e9l\u00e9ments porteurs, notamment la cannelure externe 40 du mod\u00e8le d'accouplement cannel\u00e9 30. Il sp\u00e9cifie ensuite les exigences de performance relatives \u00e0 la marge de couple, telles que la limite d'\u00e9lasticit\u00e9, le flambage plastique et le flambage par fluage. Le logiciel calcule alors automatiquement les dimensions et la configuration des \u00e9l\u00e9ments porteurs et de l'arbre. Ces sp\u00e9cifications sont ensuite int\u00e9gr\u00e9es au logiciel de mod\u00e9lisation 10 en tant que valeurs de sp\u00e9cification.<br \/>Les diff\u00e9rentes configurations d'accouplements splines sont saisies sur l'\u00e9cran 80 de l'interface graphique. Le logiciel 10 g\u00e9n\u00e8re ensuite un mod\u00e8le d'accouplement spline en enregistrant les valeurs par d\u00e9faut de ces configurations. L'utilisateur peut alors manipuler ce mod\u00e8le en modifiant ses diff\u00e9rentes sp\u00e9cifications. Le r\u00e9sultat final est une conception assist\u00e9e par ordinateur permettant aux concepteurs d'optimiser les accouplements splines en fonction de leurs performances et des sp\u00e9cifications de conception.<br \/>Le logiciel de mod\u00e9lisation des couplages splines \u00e9value en continu la validit\u00e9 des mod\u00e8les de couplage spline pour une application donn\u00e9e. Par exemple, lorsqu'un utilisateur saisit une valeur de donn\u00e9es correspondant \u00e0 un signal de param\u00e8tre, le logiciel compare cette valeur \u00e0 la valeur correspondante dans la base de connaissances. Si les valeurs sont hors sp\u00e9cifications, un message d'avertissement s'affiche. Une fois la comparaison termin\u00e9e, le logiciel g\u00e9n\u00e8re un rapport contenant les r\u00e9sultats.<br \/>La conception des accouplements cannel\u00e9s d\u00e9pend de plusieurs facteurs, notamment le poids, les propri\u00e9t\u00e9s des mat\u00e9riaux et les performances requises. Le poids est un facteur primordial, en particulier dans le domaine a\u00e9ronautique. Les tables ANSI et SAE ne prennent pas en compte ces facteurs lors du calcul des caract\u00e9ristiques de charge des accouplements cannel\u00e9s. D'autres contraintes de conception peuvent \u00e9galement limiter la configuration d'un accouplement cannel\u00e9.<\/p>\n<h2>Applications<\/h2>\n<p>Les accouplements cannel\u00e9s sont un type d'assemblage m\u00e9canique reliant deux arbres rotatifs. Leurs deux parties s'engr\u00e8nent par des dents qui transmettent la charge. Bien que les cannelures soient g\u00e9n\u00e9ralement surdimensionn\u00e9es, elles restent sensibles \u00e0 la fatigue et aux contraintes statiques. Ces propri\u00e9t\u00e9s les rendent \u00e9galement sujettes \u00e0 l'usure. Par cons\u00e9quent, une conception et une s\u00e9lection appropri\u00e9es sont essentielles pour minimiser l'usure des cannelures. Les accouplements cannel\u00e9s trouvent de nombreuses applications.<br \/>La conception d'un accouplement cannel\u00e9 repose sur le diam\u00e8tre de l'arbre \u00e0 assembler. Ceci permet un espacement optimal des clavettes. Une m\u00e9thode innovante de taillage par fraise-m\u00e8re permet la r\u00e9alisation de bases coniques sans interf\u00e9rence, et le pied des clavettes est concentrique \u00e0 l'axe. Ces caract\u00e9ristiques garantissent des cadences de production \u00e9lev\u00e9es. Les accouplements cannel\u00e9s trouvent de nombreuses applications dans divers secteurs industriels. Pour en savoir plus, poursuivez votre lecture.<br \/>La m\u00e9thodologie par \u00e9l\u00e9ments finis permet de pr\u00e9dire le taux d'usure des accouplements cannel\u00e9s en int\u00e9grant l'\u00e9volution du coefficient de frottement. Cette m\u00e9thode, qui permet de pr\u00e9dire l'usure par frottement \u00e0 partir d'une g\u00e9om\u00e9trie simple de surface plane, a \u00e9t\u00e9 calibr\u00e9e \u00e0 l'aide de donn\u00e9es exp\u00e9rimentales. Le taux d'usure pr\u00e9dit est coh\u00e9rent avec les donn\u00e9es exp\u00e9rimentales. L'\u00e9volution du frottement dans les accouplements cannel\u00e9s d\u00e9pend de la g\u00e9om\u00e9trie des cannelures. Il est \u00e9galement crucial de prendre en compte les conditions de lubrification des cannelures.<br \/>L'utilisation d'un accouplement cannel\u00e9 r\u00e9duit le jeu et assure un alignement pr\u00e9cis des composants assembl\u00e9s. La cannelure de l'arbre transmet la rotation de l'arbre cannel\u00e9 \u00e0 l'\u00e9l\u00e9ment cannel\u00e9 interne, qui peut \u00eatre un engrenage ou un autre dispositif rotatif. La r\u00e9sistance \u00e0 la racine et le couple requis pour l'accouplement cannel\u00e9 d\u00e9terminent le type d'accouplement \u00e0 utiliser.<br \/>La base de la cannelure est g\u00e9n\u00e9ralement plate et pr\u00e9sente une couronne sur une face. La cannelure couronn\u00e9e poss\u00e8de une couronne sym\u00e9trique au centre de sa largeur. Plus la longueur de la cannelure diminue vers ses extr\u00e9mit\u00e9s, plus ses dents s'amincissent. Le diam\u00e8tre des dents est mesur\u00e9 en pas. Ainsi, la cannelure m\u00e2le poss\u00e8de une base plate et une cannelure couronn\u00e9e.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_3.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Pr\u00e9visibilit\u00e9<\/h2>\n<p>Les accouplements \u00e0 broches sont utilis\u00e9s dans les machines tournantes pour relier deux arbres. Ils sont compos\u00e9s de deux parties dent\u00e9es qui s'engr\u00e8nent et transmettent la charge. Les accouplements cannel\u00e9s sont g\u00e9n\u00e9ralement surdimensionn\u00e9s et sujets aux contraintes statiques et \u00e0 la fatigue. L'usure est \u00e9galement un probl\u00e8me courant. Pour rem\u00e9dier \u00e0 ces probl\u00e8mes, il est essentiel de comprendre le comportement et la pr\u00e9visibilit\u00e9 de ces accouplements.<br \/>Le comportement dynamique des accouplements cannelure-rotor est souvent difficile \u00e0 appr\u00e9hender, notamment lorsque le syst\u00e8me n'est pas int\u00e9gr\u00e9 au rotor. Par exemple, en l'absence de d\u00e9faut d'alignement, la fr\u00e9quence de r\u00e9ponse principale correspond \u00e0 une vitesse de rotation selon l'axe X. \u00c0 mesure que le d\u00e9faut d'alignement augmente, le syst\u00e8me se met \u00e0 vibrer de mani\u00e8re complexe. De plus, lorsque les orbites de l'arbre s'\u00e9loignent de l'origine, l'amplitude de toutes les fr\u00e9quences augmente. Les r\u00e9sultats de recherche sont donc pr\u00e9cieux pour la conception et le d\u00e9pannage des syst\u00e8mes rotoriques.<br \/>Le mod\u00e8le des accouplements splines d\u00e9salign\u00e9s peut \u00eatre obtenu en analysant les relations contrainte-compression entre deux paires de splines. Le mod\u00e8le de force d'engr\u00e8nement des splines d\u00e9pend de la masse du syst\u00e8me, du couple transmis et du d\u00e9placement d\u00fb aux vibrations dynamiques. Ce mod\u00e8le est valable pour de faibles d\u00e9placements dus aux vibrations dynamiques. Par ailleurs, la m\u00e9thode d'int\u00e9gration par \u00e9tapes CZPT est stable et tr\u00e8s efficace.<br \/>La distribution du glissement d\u00e9pend de l'\u00e9tat de lubrification, du coefficient de frottement et du nombre de cycles de charge. Les profondeurs d'usure pr\u00e9dites correspondent bien aux valeurs mesur\u00e9es. Ces pr\u00e9dictions sont bas\u00e9es sur la distribution du glissement. La m\u00e9thodologie pr\u00e9dit une usure accrue en conditions de lubrification l\u00e9g\u00e8re, mais pas en cas de lubrification renforc\u00e9e. L'\u00e9tat de lubrification et le coefficient de frottement sont les facteurs cl\u00e9s qui d\u00e9terminent le comportement \u00e0 l'usure des cannelures.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China high quality OEM CNC Machinery Pinion Shaft Drive Main Shaft OEM Forging Steel Transmission Spline Shaft   differential drive shaft\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China high quality OEM CNC Machinery Pinion Shaft Drive Main Shaft OEM Forging Steel Transmission Spline Shaft   differential drive shaft\"><br \/>editor by CX 2023-04-24<\/p>","protected":false},"excerpt":{"rendered":"<p>Product Description OEM CNC Machinery Pinion Shaft Drive Main Shaft OEM Forging Steel Transmission Spline Shaft We have the completed machining equipment,including horizontal lathe,vertical lathe,CNC boring and milling machine,CNC boring machine,deep hole drilling and boring machine, gear hobbing machine,gear teeth grinding machine,grinding machine,etc. Strictly quality inspection system can produce high quality productsFor each order,we can [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10,1787,560,2054,1985,750,12,13,15,1986,1841,1850,754,691,1604,19,566,620,761,1094,764,2494,755],"class_list":["post-1174","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-china-machinery","tag-cnc-drive-shaft","tag-cnc-shaft","tag-differential-shaft","tag-drive-main-shaft","tag-drive-shaft-oem","tag-machinery","tag-machinery-china","tag-machinery-machinery","tag-main-drive-shaft","tag-main-shaft","tag-main-transmission-shaft","tag-oem-shaft","tag-pinion","tag-pinion-shaft","tag-shaft","tag-shaft-cnc","tag-shaft-drive","tag-shaft-steel","tag-spline-shaft","tag-steel-shaft","tag-transmission-main-drive-shaft","tag-transmission-shaft"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1174\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/categories?post=1174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/tags?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}