{"id":1124,"date":"2023-02-24T00:02:44","date_gmt":"2023-02-24T00:02:44","guid":{"rendered":"http:\/\/splineshaft.top\/china-voe11709101-transmission-dp50-drive-shaft-carraro-original-spare-universal-joint-assembly-9187120051-alc-drive-shaft-shop\/"},"modified":"2023-02-24T00:02:44","modified_gmt":"2023-02-24T00:02:44","slug":"china-voe11709101-transmission-dp50-drive-shaft-carraro-original-spare-universal-joint-assembly-9187120051-alc-drive-shaft-shop","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/fr\/china-voe11709101-transmission-dp50-drive-shaft-carraro-original-spare-universal-joint-assembly-9187120051-alc-drive-shaft-shop\/","title":{"rendered":"China voe11709101 transmission dp50 drive shaft carraro original spare universal joint assembly 9187120051 alc     drive shaft shop"},"content":{"rendered":"<p>Probl\u00e8me : Nouveau<br \/>Garantie : 1 an<br \/>Applicable Industries: Accommodations, Garment Stores, Developing Material Stores, Manufacturing Plant, Machinery Fix Stores, Food &amp; Beverage Manufacturing unit, Farms, Cafe, Property Use, Retail, Foods Store, Printing Stores, Development works\u00a0, Energy &amp; Mining, Meals &amp; Beverage Outlets, Marketing Company<br \/>Weight (KG): 38.five<br \/>Emplacement en salle d'exposition\u00a0: Aucun<br \/>Inspection vid\u00e9o en ligne avant d\u00e9part\u00a0: Pr\u00e9sent\u00e9e<br \/>Rapport de v\u00e9rification de l'\u00e9quipement\u00a0: Fourni<br \/>Marketing and advertising Variety: New Item 2571<br \/>Garantie des facteurs essentiels : 1 an civil<br \/>Main Elements: Bearing, Spline pair<br \/>Framework: Adaptable<br \/>Content: 40Cr\/forty five#<br \/>Rev\u00eatements : peinture<br \/>Torque Capability: a hundred sixty five alc<\/FONT><font>The sliding sleeve of the telescopic travel shaft is coated with nylon to increase put on resistance and toughness, and at the same time engage in a position of corrosion safety for the spline. Utilized in development machinery processing crops, vehicle producers, OEMs, developing materials shops, manufacturing vegetation, equipment repair retailers, and so on.<\/font> Product specifications <table><tr><td colspan=\"1\" rowspan=\"1\">Product variety<\/td><td colspan=\"1\" rowspan=\"1\">Couple maximal (Nm)<\/td><td colspan=\"1\" rowspan=\"1\">Diam\u00e8tre de rotation (mm)<\/td><td colspan=\"1\" rowspan=\"1\">Couple nominal (Nm)<\/td><td colspan=\"1\" rowspan=\"1\">Universal joint size(mm)<\/td><td colspan=\"1\" rowspan=\"1\">Diam\u00e8tre du tube d'arbre (mm)<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">BJ212<\/td><td colspan=\"1\" rowspan=\"1\">1600<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8100<\/td><td colspan=\"1\" rowspan=\"1\">1000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a630\u00d7 Higher Efficiency WEG IE4 Motor IP55 Large-obligation CZPT Bearings 116psi 189psi 8Bar 13Bar One Stage Air Compressor Machine 88<\/td><td colspan=\"1\" rowspan=\"1\">\u00d850<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">BJ130<\/td><td colspan=\"1\" rowspan=\"1\">2500<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8110<\/td><td colspan=\"1\" rowspan=\"1\">2700<\/td><td colspan=\"1\" rowspan=\"1\">\u03a632\u00d793<\/td><td colspan=\"1\" rowspan=\"1\">\u00d863,5<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">NJ130<\/td><td colspan=\"1\" rowspan=\"1\">3200<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8118<\/td><td colspan=\"1\" rowspan=\"1\">2500<\/td><td colspan=\"1\" rowspan=\"1\">\u03a635\u00d798<\/td><td colspan=\"1\" rowspan=\"1\">\u00d876<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">EQ140<\/td><td colspan=\"1\" rowspan=\"1\">6500<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8142<\/td><td colspan=\"1\" rowspan=\"1\">4100<\/td><td colspan=\"1\" rowspan=\"1\">\u03a639\u00d7118<\/td><td colspan=\"1\" rowspan=\"1\">\u00d889<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">EQ153<\/td><td colspan=\"1\" rowspan=\"1\">9000<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8169<\/td><td colspan=\"1\" rowspan=\"1\">6000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a647\u00d7140<\/td><td colspan=\"1\" rowspan=\"1\">\u00d889<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">0125<\/td><td colspan=\"1\" rowspan=\"1\">16500<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8156<\/td><td colspan=\"1\" rowspan=\"1\">10000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a652\u00d7133<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8100<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">0082<\/td><td colspan=\"1\" rowspan=\"1\">21000<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8168<\/td><td colspan=\"1\" rowspan=\"1\">15000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a657\u00d7144<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8110<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">395<\/td><td colspan=\"1\" rowspan=\"1\">27000<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8178<\/td><td colspan=\"1\" rowspan=\"1\">17000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a657\u00d7152<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8120<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">656<\/td><td colspan=\"1\" rowspan=\"1\">44000<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8198<\/td><td colspan=\"1\" rowspan=\"1\">25000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a668\u00d7 RG series gearbox for tractor pto 165<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8140<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Y165E1<\/td><td colspan=\"1\" rowspan=\"1\">52500<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8210<\/td><td colspan=\"1\" rowspan=\"1\">30000<\/td><td colspan=\"1\" rowspan=\"1\">\u03a668\u00d7193<\/td><td colspan=\"1\" rowspan=\"1\">\u00d8150<\/td><\/tr><\/table> Details Photos Item Characteristics Recommend Items Business Profile Product packaging FAQ <font>Q: Are you a trading firm or a manufacturer?ST: We are a factory. We are a skilled manufacturer for 20 years&#8217; expertise, specializing in producing different sequence of Cardan shafts. We source Cardan shafts for the wholesalers, dealers, and end-customers from distinct nations around the world. Q: How extended is your shipping time?ST: Usually it is 5-10 times if we have the existing product. Or it will be 30-60 times if we require to open a new model, in accordance to your type.Q: Can you do OEM? And what is your min buy?ST: Sure, totally we can do. Our min get is 1 established. Most of our merchandise are Custom-made. Every single buy from our factory, we always create soon after our drawing confirmed. So we failed to have stock. And Because we are dependent on the final consumer confirmed drawings production, so ahead of this, the customer has any needs that can be altered.Q: How does your manufacturing facility do regarding good quality control?ST: For us, good quality is a priority. We always pay out higher interest to good quality handle from the starting to the stop:1) First of all, we have a specialized QC section to handle the top quality, and we also accept the third formal government to examine our product ahead of shipping and delivery.2) Secondly, we have all in depth records for nonconformity goods, then we will make a summary according to these documents, keep away from it occurs once more.3) Thirdly, We do notice the relevant codes of conduct &amp; rules from federal government in the atmosphere, human rights facets, like no young children labor, no prisoner labor, and so on.Q: How could I know if the merchandise satisfies my machine or not?ST: Make sure you explain to me which product you are interested in, or recommend us the principal sizes, this sort of as the diameter of throughout assembly, complete size, and the swing diameter of flange, 2571 Polaris SPORTSMAN 570 EPS then we can provide you our drawings in accordance to your ask for, or make sure you suggest us the model you are utilizing now<\/font><font>.<\/font><\/p>\n<p>\n<h2>Fonctions des paliers \u00e0 arbre cannel\u00e9<\/h2>\n<p>Les arbres cannel\u00e9s sont les paliers les plus courants pour les machines-outils. Ils sont fabriqu\u00e9s dans une grande vari\u00e9t\u00e9 de mat\u00e9riaux, notamment des m\u00e9taux et des non-m\u00e9taux comme le Delrin et le nylon. Leur conception vise souvent \u00e0 r\u00e9duire la d\u00e9formation. Le profil des dents se d\u00e9forme avec le temps, l'arbre \u00e9tant utilis\u00e9 sur une longue p\u00e9riode. Les arbres cannel\u00e9s sont disponibles dans une vaste gamme de mat\u00e9riaux et de longueurs.<\/p>\n<h2>Fonctions<\/h2>\n<p>Les arbres cannel\u00e9s sont utilis\u00e9s dans de nombreuses applications et industries. Ils constituent un dispositif anti-rotation efficace et un moyen fiable de transmettre le couple. D'autres types d'arbres existent, notamment les arbres clavet\u00e9s, mais les cannelures restent les plus pratiques pour la transmission du couple. Cet article pr\u00e9sente les fonctions des cannelures et explique pourquoi elles repr\u00e9sentent un choix optimal. Vous trouverez ci-dessous quelques exemples d'applications et d'industries o\u00f9 les cannelures sont utilis\u00e9es.<br \/>Les arbres cannel\u00e9s peuvent \u00eatre de diff\u00e9rents types, selon l'application et le syst\u00e8me m\u00e9canique concern\u00e9. Les diff\u00e9rences entre ces types r\u00e9sident notamment dans la conception des dents, la r\u00e9sistance globale, la transmission de la concentricit\u00e9 de rotation, la capacit\u00e9 de glissement et la tol\u00e9rance au d\u00e9salignement. Vous trouverez ci-dessous quelques exemples de cannelures, ainsi que certains de leurs avantages. Les diff\u00e9rences entre ces types ne sont pas exclusives\u00a0; chaque type pr\u00e9sente des avantages et des inconv\u00e9nients sp\u00e9cifiques.<br \/>Un arbre cannel\u00e9 est un arbre cylindrique comportant des dents ou des rainures correspondant \u00e0 une position angulaire pr\u00e9cise. Ceci permet \u00e0 l'arbre de transmettre un couple tout en maintenant une correspondance angulaire entre les rainures. Un arbre cannel\u00e9 est d\u00e9fini comme un \u00e9l\u00e9ment cylindrique pr\u00e9sentant plusieurs rainures usin\u00e9es sur sa circonf\u00e9rence. Ces rainures, r\u00e9guli\u00e8rement espac\u00e9es, forment une s\u00e9rie de clavettes. Ces caract\u00e9ristiques conf\u00e8rent \u00e0 l'arbre une forme arrondie et lui permettent de s'embo\u00eeter parfaitement dans un \u00e9l\u00e9ment cylindrique cannel\u00e9.<br \/>Bien que les cannelures soient principalement utilis\u00e9es pour raccourcir ou allonger des arbres, elles peuvent \u00e9galement servir \u00e0 fixer des assemblages m\u00e9caniques. Une cannelure \u00e0 d\u00e9veloppante de cercle poss\u00e8de une gorge plus large que les autres. De ce fait, un arbre cannel\u00e9 r\u00e9siste \u00e0 la s\u00e9paration en fonctionnement. Elles constituent un choix id\u00e9al pour les applications o\u00f9 la d\u00e9formation est un facteur critique.<br \/>La r\u00e9partition de la charge de torsion radiale d'un arbre cannel\u00e9 est uniforme, sauf en cas d'utilisation d'un engrenage conique. Cette charge est r\u00e9partie uniform\u00e9ment et ne g\u00e9n\u00e8re pas de concentration de charge significative. Un mauvais alignement des cannelures peut entra\u00eener une rupture rapide de l'assemblage, provoquant une usure importante par frottement. Plusieurs articles traitent de ce sujet plus en d\u00e9tail.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Types<\/h2>\n<p>Il existe de nombreux types d'arbres cannel\u00e9s. Chaque type pr\u00e9sente une h\u00e9lice de rainures r\u00e9guli\u00e8rement espac\u00e9es sur sa surface ext\u00e9rieure. Ces rainures sont soit parall\u00e8les, soit en d\u00e9veloppante. Leur forme permet leur assemblage avec des engrenages et la conversion de mouvements rotatifs et lin\u00e9aires. Les cannelures sont souvent lamin\u00e9es \u00e0 froid ou taill\u00e9es. Ces derni\u00e8res offrent une r\u00e9sistance sup\u00e9rieure. Ces types d'arbres sont couramment utilis\u00e9s dans des applications exigeant une r\u00e9sistance, une pr\u00e9cision et une r\u00e9gularit\u00e9 \u00e9lev\u00e9es.<br \/>Une autre diff\u00e9rence entre les arbres cannel\u00e9s internes et externes r\u00e9side dans leur fabrication. Les premiers sont en bois, tandis que les seconds sont en acier ou en alliage m\u00e9tallique. La fabrication des arbres cannel\u00e9s consiste \u00e0 usiner des rainures dans la surface du mat\u00e9riau. Ces deux proc\u00e9d\u00e9s sont co\u00fbteux et requi\u00e8rent un savoir-faire sp\u00e9cialis\u00e9. Le principal avantage des arbres cannel\u00e9s est leur grande polyvalence.<br \/>En g\u00e9n\u00e9ral, les arbres cannel\u00e9s sont utilis\u00e9s dans les machines o\u00f9 la rotation est transmise \u00e0 un \u00e9l\u00e9ment cannel\u00e9 interne. Cet \u00e9l\u00e9ment peut \u00eatre un engrenage ou tout autre dispositif rotatif. Ces types d'arbres sont souvent assembl\u00e9s en un moyeu. Le nettoyage et la lubrification sont essentiels \u00e0 la dur\u00e9e de vie de ces composants. Si vous les utilisez quotidiennement, il est important de les inspecter r\u00e9guli\u00e8rement.<br \/>Les cannelures couronn\u00e9es sont g\u00e9n\u00e9ralement en d\u00e9veloppante. Leurs dents forment une spirale. Elles sont utilis\u00e9es pour les arbres de petit diam\u00e8tre car elles augmentent leur r\u00e9sistance. Les cannelures en d\u00e9veloppante sont \u00e9galement utilis\u00e9es sur les entra\u00eenements d'instruments et les arbres de vannes. Les normes de denture sont d\u00e9finies par la SAE. Les deux types de cannelures peuvent \u00e9galement comporter un roulement \u00e0 billes pour les couples \u00e9lev\u00e9s. La diff\u00e9rence entre les deux types r\u00e9side dans le nombre de dents sur l'arbre.<br \/>Les cannelures internes pr\u00e9sentent de nombreux avantages par rapport aux cannelures externes. Par exemple, un arbre \u00e0 cannelures internes peut \u00eatre fabriqu\u00e9 \u00e0 l'aide d'une meule plut\u00f4t que d'une machine CNC. Ce proc\u00e9d\u00e9 est \u00e9galement plus pr\u00e9cis et plus \u00e9conomique. De plus, il permet un cycle de fabrication plus court, ce qui est essentiel pour le cannelage des machines \u00e0 grande vitesse. Enfin, il stabilise la phase relative entre la cannelure et le filetage.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>M\u00e9thodes de fabrication<\/h2>\n<p>Plusieurs m\u00e9thodes permettent de fabriquer un arbre cannel\u00e9. Les arbres cannel\u00e9s et clavet\u00e9s sont constitu\u00e9s de deux pi\u00e8ces distinctes mises en forme de mani\u00e8re synchronis\u00e9e afin de transmettre le couple uniform\u00e9ment. Le laminage \u00e0 chaud est une m\u00e9thode, tandis que le laminage \u00e0 froid utilise de basses temp\u00e9ratures pour former le m\u00e9tal. Ces deux m\u00e9thodes am\u00e9liorent les propri\u00e9t\u00e9s m\u00e9caniques, l'\u00e9tat de surface et la pr\u00e9cision. L'avantage du laminage \u00e0 froid r\u00e9side dans son faible co\u00fbt.<br \/>Le formage \u00e0 froid est une m\u00e9thode parmi d'autres, au m\u00eame titre que l'usinage et l'assemblage. Ce proc\u00e9d\u00e9 unique permet de donner \u00e0 la cannelure la forme souhait\u00e9e. La forme obtenue offre une surface de contact et une r\u00e9sistance \u00e0 la torsion maximales. Les cannelures standard sont disponibles en dimensions standard, mais des longueurs sur mesure peuvent \u00e9galement \u00eatre command\u00e9es. CZPT propose divers \u00e9quipements auxiliaires, tels que des manchons d'accouplement et des bagues \u00e0 bride.<br \/>Le forgeage \u00e0 froid est une autre m\u00e9thode. Ce proc\u00e9d\u00e9 permet de produire de longs arbres cannel\u00e9s utilis\u00e9s dans les h\u00e9lices automobiles. Apr\u00e8s le fraisage de la partie cannel\u00e9e, celle-ci est usin\u00e9e sur une machine \u00e0 tailler les pignons. L'\u00e9crouissage renforce la r\u00e9sistance \u00e0 la base de la cannelure. Ce proc\u00e9d\u00e9 peut \u00eatre utilis\u00e9 pour les roulements, les engrenages et d'autres composants m\u00e9caniques. Vous trouverez ci-dessous les m\u00e9thodes de fabrication des arbres cannel\u00e9s.<br \/>Les cannelures parall\u00e8les sont la m\u00e9thode de fabrication d'arbres cannel\u00e9s la plus simple. Elles sont g\u00e9n\u00e9ralement soud\u00e9es \u00e0 l'arbre, tandis que les cannelures en d\u00e9veloppante sont r\u00e9alis\u00e9es en m\u00e9tal ou en mat\u00e9riaux non m\u00e9talliques. Les cannelures sont disponibles dans une grande vari\u00e9t\u00e9 de longueurs et de mat\u00e9riaux. Le proc\u00e9d\u00e9 est g\u00e9n\u00e9ralement compl\u00e9t\u00e9 par une op\u00e9ration de fraisage. La pi\u00e8ce est mise en rotation pour cr\u00e9er la surface cannel\u00e9e.<br \/>Les cannelures sont des rainures internes ou externes pratiqu\u00e9es dans un arbre cannel\u00e9. Elles fonctionnent de concert avec les rainures de clavette pour transmettre le couple. Les cannelures m\u00e2les et femelles sont utilis\u00e9es dans les engrenages. Elles s'embo\u00eetent parfaitement pour assurer un alignement angulaire pr\u00e9cis. Les cannelures en d\u00e9veloppante pr\u00e9sentent une surface de contact plus importante et sont donc plus r\u00e9sistantes que les cannelures externes. De plus, elles permettent un embo\u00eetement pr\u00e9cis de l'arbre dans un \u00e9l\u00e9ment cylindrique rainur\u00e9.<br \/>Il existe diverses autres m\u00e9thodes de fabrication d'arbres cannel\u00e9s. Parmi celles-ci, on peut citer le brochage et le fa\u00e7onnage, deux techniques d'usinage de pr\u00e9cision. Le brochage utilise un outil m\u00e9tallique muni de dents de plus en plus grandes pour enlever de la mati\u00e8re et cr\u00e9er des rainures et des trous \u00e0 la surface du mat\u00e9riau. Cependant, ce proc\u00e9d\u00e9 est co\u00fbteux et exige un savoir-faire particulier.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_2.webp\" alt=\"arbre cannel\u00e9\" width=\"800\" \/><\/p>\n<h2>Applications<\/h2>\n<p>L'arbre cannel\u00e9 est un composant m\u00e9canique de forme h\u00e9lico\u00efdale, form\u00e9 par l'espacement r\u00e9gulier des cannelures dans un anneau circulaire. Ces cannelures peuvent \u00eatre \u00e0 c\u00f4t\u00e9s parall\u00e8les ou en d\u00e9veloppante. Elles minimisent la concentration des contraintes dans les articulations fixes et peuvent \u00eatre utilis\u00e9es pour des mouvements rotatifs et lin\u00e9aires. Dans certains cas, les cannelures sont roul\u00e9es plut\u00f4t que taill\u00e9es. Cette derni\u00e8re m\u00e9thode offre une meilleure durabilit\u00e9 et est souvent privil\u00e9gi\u00e9e dans les applications exigeant une r\u00e9sistance \u00e9lev\u00e9e, une grande pr\u00e9cision et un \u00e9tat de surface lisse.<br \/>Les arbres cannel\u00e9s sont g\u00e9n\u00e9ralement fabriqu\u00e9s en acier au carbone. Cet acier alli\u00e9, \u00e0 faible teneur en carbone, est facile \u00e0 travailler. L'acier au carbone est un excellent choix pour les cannelures gr\u00e2ce \u00e0 sa mall\u00e9abilit\u00e9. En g\u00e9n\u00e9ral, un acier au carbone de haute qualit\u00e9 assure un mouvement r\u00e9gulier. Il existe \u00e9galement des alliages d'acier contenant du nickel, du chrome, du cuivre et d'autres m\u00e9taux. En cas de doute sur le mat\u00e9riau le plus adapt\u00e9 \u00e0 votre application, vous pouvez consulter un tableau des cannelures.<br \/>Les cannelures sont des composants m\u00e9caniques polyvalents. Faciles \u00e0 usiner et \u00e0 ajuster, elles peuvent \u00eatre internes ou externes, avec des dents positionn\u00e9es \u00e0 intervalles r\u00e9guliers de part et d'autre de l'arbre. Ceci permet \u00e0 l'arbre de s'engager dans le moyeu sur toute sa circonf\u00e9rence. La capacit\u00e9 de charge est \u00e9galement accrue gr\u00e2ce \u00e0 la pr\u00e9sence de plusieurs points de contact constants avec le moyeu. C'est pourquoi elles sont largement utilis\u00e9es dans les syst\u00e8mes de mouvement rotatif et lin\u00e9aire.<br \/>Les arbres cannel\u00e9s sont utilis\u00e9s dans de nombreux secteurs industriels. CZPT Inc. propose des arbres cannel\u00e9s standard et sur mesure pour diverses applications. Lors du choix d'un arbre cannel\u00e9 pour une application sp\u00e9cifique, tenez compte des composants avec lesquels il est accoupl\u00e9, des exigences de couple et des dimensions. Ces trois facteurs vous permettront de choisir l'arbre cannel\u00e9 id\u00e9al pour votre \u00e9quipement rotatif. Vous serez pleinement satisfait du r\u00e9sultat\u00a0!<br \/>Il existe de nombreux types de cannelures et leurs applications sont innombrables. Elles transmettent le couple et corrigent les d\u00e9fauts d'alignement angulaire entre les pi\u00e8ces, et permettent \u00e9galement la rotation axiale des composants assembl\u00e9s. De ce fait, les cannelures sont un \u00e9l\u00e9ment essentiel des machines et sont utilis\u00e9es dans une vaste gamme d'applications. On retrouve ce type d'arbre dans divers types de machines, des appareils m\u00e9nagers aux machines industrielles. Ainsi, la prochaine fois que vous chercherez un arbre cannel\u00e9, assurez-vous d'en choisir un.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China voe11709101 transmission dp50 drive shaft carraro original spare universal joint assembly 9187120051 alc     drive shaft shop\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China voe11709101 transmission dp50 drive shaft carraro original spare universal joint assembly 9187120051 alc     drive shaft shop\t\"><br \/>\u00c9dit\u00e9 par czh le 24 f\u00e9vrier 2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Problem: NewWarranty: 1 YearApplicable Industries: Accommodations, Garment Stores, Developing Material Stores, Manufacturing Plant, Machinery Fix Stores, Food &amp; Beverage Manufacturing unit, Farms, Cafe, Property Use, Retail, Foods Store, Printing Stores, Development works\u00a0, Energy &amp; Mining, Meals &amp; Beverage Outlets, Marketing CompanyWeight (KG): 38.fiveShowroom Spot: NoneOnline video outgoing-inspection: PresentedEquipment Check Report: ProvidedMarketing and advertising Variety: New [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1457,1106,19,620,1107,755,1070,635],"class_list":["post-1124","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-joint-shaft","tag-original-shaft","tag-shaft","tag-shaft-drive","tag-shaft-original","tag-transmission-shaft","tag-universal-joint","tag-universal-shaft"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/comments?post=1124"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/posts\/1124\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/media?parent=1124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/categories?post=1124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/fr\/wp-json\/wp\/v2\/tags?post=1124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}