{"id":1082,"date":"2023-02-21T04:02:54","date_gmt":"2023-02-21T04:02:54","guid":{"rendered":"http:\/\/splineshaft.top\/china-shaft-steel-pneumatic-core-expansion-expanding-inflating-air-shaft-drive-shaft-coupler\/"},"modified":"2023-02-21T04:02:54","modified_gmt":"2023-02-21T04:02:54","slug":"china-shaft-steel-pneumatic-core-expansion-expanding-inflating-air-shaft-drive-shaft-coupler","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/es\/china-shaft-steel-pneumatic-core-expansion-expanding-inflating-air-shaft-drive-shaft-coupler\/","title":{"rendered":"Eje neum\u00e1tico de acero de China con n\u00facleo expandible para inflado y expansi\u00f3n, acoplador de eje de transmisi\u00f3n."},"content":{"rendered":"<p>Problema: Nuevo<br \/>Garant\u00eda: No disponible<br \/>Industrias aplicables: Hoteles, tiendas de ropa, tiendas de materiales de construcci\u00f3n, plantas de fabricaci\u00f3n, minoristas de reparaci\u00f3n de equipos, unidades de fabricaci\u00f3n de alimentos y bebidas, granjas, cafeter\u00edas, uso residencial, comercio minorista, tiendas de alimentos, imprentas, obras de construcci\u00f3n, energ\u00eda y miner\u00eda, minoristas de alimentos y bebidas, otros, empresas de publicidad<br \/>Peso (KG): 30<br \/>Ubicaci\u00f3n de las salas de exposici\u00f3n: Egipto, Canad\u00e1, Turqu\u00eda, Italia, Francia, Alemania, Per\u00fa, Arabia Saudita, Indonesia, Rusia, Espa\u00f1a, Tailandia, Chile, Emiratos \u00c1rabes Unidos, Colombia, Bangladesh, Sud\u00e1frica, Kazajist\u00e1n, Uzbekist\u00e1n, Tayikist\u00e1n<br \/>Inspecci\u00f3n de salida de la pel\u00edcula: Ofrecida<br \/>Informe de examen del equipo: Suministrado<br \/>Variedad de comercializaci\u00f3n: Nuevo art\u00edculo 2571<br \/>Garant\u00eda de las piezas principales: 1 a\u00f1o<br \/>Factores principales: Rodamiento<br \/>Composici\u00f3n: Spline<br \/>Contenido: Great-ZQZ<br \/>Recubrimientos: N\u00cdQUEL<br \/>Certificaci\u00f3n: CE\/ISO9001\/ROHS<br \/>Alta calidad: Inspecci\u00f3n 100%<br \/>Detalles del embalaje: Caja Picket<\/p>\n<p> Especificaci\u00f3n <table><tr><td colspan=\"1\" rowspan=\"1\">art\u00edculo<\/td><td colspan=\"1\" rowspan=\"1\">valor<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Condici\u00f3n<\/td><td colspan=\"1\" rowspan=\"1\">Nuevo<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Garant\u00eda<\/td><td colspan=\"1\" rowspan=\"1\">Indisponible<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Industrias aplicables<\/td><td colspan=\"1\" rowspan=\"1\">Hoteles, tiendas de ropa, tiendas de materiales de construcci\u00f3n, planta de producci\u00f3n, talleres de reparaci\u00f3n de equipos, unidad de fabricaci\u00f3n de alimentos y bebidas, granjas, cafeter\u00eda, uso dom\u00e9stico, venta minorista, tienda de alimentos, imprentas, obras de construcci\u00f3n, energ\u00eda y miner\u00eda, alimentos y 140KW 16M3MIN 15BAR di\u00e9sel m\u00f3vil miner\u00eda doble estacionario fijo PM VSD compresor de aire de velocidad variable a largo plazo tiendas de bebidas, otros, organizaci\u00f3n de publicidad y marketing<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Peso (KG)<\/td><td colspan=\"1\" rowspan=\"1\">30<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">\u00c1rea de exposici\u00f3n<\/td><td colspan=\"1\" rowspan=\"1\">Egipto, Canad\u00e1, Turqu\u00eda, Italia, Francia, Alemania, Per\u00fa, Arabia Saudita, Indonesia, Rusia, Espa\u00f1a, Tailandia, Chile, Emiratos \u00c1rabes Unidos, Colombia, Bangladesh, Sud\u00e1frica, Kazajist\u00e1n, Uzbekist\u00e1n, Tayikist\u00e1n<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Inspecci\u00f3n de salida por v\u00eddeo<\/td><td colspan=\"1\" rowspan=\"1\">Proporcion\u00f3<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Maquinaria. Eche un vistazo al informe.<\/td><td colspan=\"1\" rowspan=\"1\">Proporcion\u00f3<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Tipo de marketing<\/td><td colspan=\"1\" rowspan=\"1\">Art\u00edculo nuevo 2571<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Garant\u00eda de los componentes principales<\/td><td colspan=\"1\" rowspan=\"1\">1 a\u00f1o<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Componentes principales<\/td><td colspan=\"1\" rowspan=\"1\">Cojinete<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Estructura<\/td><td colspan=\"1\" rowspan=\"1\">Ranura<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Material<\/td><td colspan=\"1\" rowspan=\"1\">NICE-ZQZ<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Recubrimientos<\/td><td colspan=\"1\" rowspan=\"1\">N\u00cdQUEL<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Lugar de origen<\/td><td colspan=\"1\" rowspan=\"1\">Porcelana<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><\/td><td colspan=\"1\" rowspan=\"1\">ZHangZhoug<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">T\u00edtulo de la marca<\/td><td colspan=\"1\" rowspan=\"1\">LINDO<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Proceso de dar un t\u00edtulo<\/td><td colspan=\"1\" rowspan=\"1\">CE\/ISO9001\/ROHS<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Calidad<\/td><td colspan=\"1\" rowspan=\"1\">Inspecci\u00f3n 100%<\/td><\/tr><\/table> Embalaje, env\u00edo y entrega Perfil de la empresa Wood BOX HangZhou Nice Equipment CO., LTD. es una empresa reconocida que se especializa en la producci\u00f3n, planificaci\u00f3n y construcci\u00f3n de una variedad de maquinaria para la formaci\u00f3n de soluciones de papel, maquinaria de impresi\u00f3n de papel y equipos de troquelado de papel. La empresa ha acumulado una gran cantidad de conocimientos de producci\u00f3n y sus herramientas son ampliamente elogiadas por numerosas empresas y usuarios especializados tanto a nivel nacional como internacional. Pensamos en el rendimiento general de las herramientas desde el punto de vista del cliente, brindamos a los clientes soluciones de calidad sustancial que ahorran energ\u00eda, reducen el consumo, la generaci\u00f3n eficiente, la actualizaci\u00f3n y el retrabajo, y proporcionamos un muy buen sistema para motivar a los clientes a aumentar su efectividad. Con el esp\u00edritu de mejora continua de la calidad de la soluci\u00f3n, la t\u00e9cnica del proveedor y la innovaci\u00f3n constante, la empresa servir\u00e1 sinceramente al mercado y a los clientes, y se convertir\u00e1 en un amigo confiable de los clientes. Con ingenier\u00eda de producci\u00f3n l\u00edder, una l\u00ednea de productos rica y completa y servicios de posventa expertos, la organizaci\u00f3n contin\u00faa ofreciendo a los compradores productos y servicios de alta calidad Preguntas frecuentes 1. \u00bfQui\u00e9nes somos? Estamos ubicados principalmente en ZHangZhoug, China, comenzamos en 2571, ofrecemos al sudeste asi\u00e1tico (14.00%), Asia oriental (12.00%), Europa del Este (9.00%), Am\u00e9rica del Sur (8.00%), Am\u00e9rica Central (8.00%), \u00c1frica (7.00%), Am\u00e9rica del Norte nosotros (6.00%), Europa del Norte (6.00%), Asia del Sur (6.00%), Medio Oriente (5.00%), Arrancador de bater\u00eda de coche de 24000 mAh 12 V 3000 A con compresor de aire, arrancador de bater\u00eda de coche de emergencia, arrancador de rebote de autom\u00f3vil Europa Occidental (5.00%), Europa del Sur (5.00%), Mercado Nacional (5.00%), Ocean\u00eda (4.00%). Hay entre 51 y 100 personas en nuestro lugar de trabajo. 2. \u00bfC\u00f3mo podemos asegurar la alta calidad? Siempre una muestra de pregeneraci\u00f3n antes de la producci\u00f3n en masa. Siempre una inspecci\u00f3n final antes del env\u00edo. 3. \u00bfQu\u00e9 puede comprar de nosotros? M\u00e1quina de bolsas de papel, Dispositivo de vasos de papel, Dispositivo de cuencos de papel, Dispositivo de tapas de papel, M\u00e1quina de loncheras de papel. 4. \u00bfPor qu\u00e9 deber\u00eda comprarnos a nosotros y no a otros proveedores? Tenemos 20 a\u00f1os de experiencia en dise\u00f1o y desarrollo, un s\u00f3lido equipo t\u00e9cnico y un excelente equipo de atenci\u00f3n al cliente para ofrecer a los clientes servicios integrales y eficaces. 5. \u00bfQu\u00e9 soluciones podemos ofrecer? T\u00e9rminos de env\u00edo y entrega aceptados: FOB, CFR, CIF, EXW, FAS, CIP, FCA, CPT, DEQ, DDP, DDU, Express Delivery, DAF, DES; Forex de pago aceptado: USD, EUR, JPY, CAD, AUD, HKD, GBP, CNY, CHF Tipo de pago aceptado: T\/T, L\/C, D\/PD\/A, MoneyGram, Tarjeta de cr\u00e9dito, PayPal, Western Union, Ingresos, Escrow Idiomas hablados: ingl\u00e9s, chino, espa\u00f1ol, japon\u00e9s, alem\u00e1n, \u00e1rabe, franc\u00e9s, ruso, coreano, 530 cfm 13 Bar Compresor de aire de tornillo di\u00e9sel port\u00e1til con ruedas para plataforma de perforaci\u00f3n italiano<\/p>\n<p>\n<h2>M\u00e9todos anal\u00edticos para estimar las presiones de contacto en acoplamientos spline.<\/h2>\n<p>Un acoplamiento estriado es un tipo de conexi\u00f3n mec\u00e1nica entre dos ejes giratorios. Consta de dos partes: un acoplador y un acoplamiento. Ambas partes tienen dientes que se acoplan y transfieren cargas. Sin embargo, los acoplamientos estriados suelen estar sobredimensionados, lo que los hace susceptibles a la fatiga y al desgaste est\u00e1tico. El desgaste tambi\u00e9n puede provocar su fallo. Por ello, un dise\u00f1o adecuado del acoplamiento estriado es esencial para lograr un rendimiento \u00f3ptimo.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_2.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>Modelado de un acoplamiento de spline<\/h2>\n<p>Los acoplamientos estriados son cada vez m\u00e1s populares en la industria aeroespacial, pero operan con una ligera desalineaci\u00f3n, lo que provoca vibraciones y da\u00f1os en las superficies de contacto. Para solucionar este problema, este art\u00edculo propone m\u00e9todos anal\u00edticos para estimar las presiones de contacto en un acoplamiento estriado. En concreto, se comparan los m\u00e9todos anal\u00edticos con los m\u00e9todos puramente num\u00e9ricos para demostrar las ventajas del enfoque anal\u00edtico.<br \/>Para modelar un acoplamiento spline, primero se crea la base de conocimiento correspondiente. Esta base de conocimiento incluye una gran cantidad de valores de especificaci\u00f3n posibles, que est\u00e1n interrelacionados. Si se modifica una especificaci\u00f3n, puede generarse una advertencia por incumplimiento de otra. Para que el dise\u00f1o sea v\u00e1lido, se debe crear un modelo de acoplamiento spline que cumpla con los valores de especificaci\u00f3n especificados.<br \/>Una vez modelada la geometr\u00eda, debe introducir las presiones de contacto de los dos acoplamientos estriados. A continuaci\u00f3n, debe determinar la posici\u00f3n del c\u00edrculo primitivo del estriado. En la Figura 2, el centro del acoplamiento macho se superpone al del estriado hembra. Finalmente, debe asegurarse de que la distancia de alineaci\u00f3n de los dos estriados sea la misma.<br \/>Una vez que tenga los datos necesarios para crear un modelo de acoplamiento de estr\u00edas, puede comenzar ingresando las especificaciones para el dise\u00f1o de la interfaz. Con estos datos, debe elegir si optimizar la estr\u00eda interna o la externa. Tambi\u00e9n deber\u00e1 especificar el coeficiente de fricci\u00f3n del diente, que se utiliza para determinar las tensiones en el modelo de acoplamiento de estr\u00edas 20. Asimismo, debe ingresar la holgura piloto, que es la holgura entre la punta 186 de un diente 32 en una estr\u00eda y la caracter\u00edstica en la estr\u00eda de acoplamiento.<br \/>Tras introducir las especificaciones deseadas para la ranura externa, puede introducir los par\u00e1metros para la ranura interna. Por ejemplo, puede introducir el l\u00edmite de di\u00e1metro exterior 154 del acoplamiento principal 54 y el acoplamiento secundario 56 de la ranura interna. Los valores de estos par\u00e1metros se muestran en recuadros codificados por colores en la pantalla GUI de Entradas y Configuraci\u00f3n de Ranuras 80. Una vez introducidos los par\u00e1metros, se mostrar\u00e1 una representaci\u00f3n geom\u00e9trica del modelo de acoplamiento de ranuras 20.<\/p>\n<h2>Creaci\u00f3n de un modelo de acoplamiento de spline 20<\/h2>\n<p>El modelo de acoplamiento spline 20 se crea mediante un programa de software de modelado de producto 10. El software valida el modelo de acoplamiento spline compar\u00e1ndolo con una base de conocimientos de restricciones y relaciones de especificaci\u00f3n dependientes de la configuraci\u00f3n. Este informe se introduce en el programa analizador de esfuerzos ANSYS. En \u00e9l se enumeran las configuraciones geom\u00e9tricas del modelo de acoplamiento spline 20 y los valores de especificaci\u00f3n para cada caracter\u00edstica. El modelo de acoplamiento spline 20 se recrea autom\u00e1ticamente cada vez que se modifican su configuraci\u00f3n o las especificaciones de rendimiento.<br \/>El modelo de acoplamiento estriado 20 se puede configurar mediante el programa de software de modelado de producto 10. El usuario especifica la longitud axial del conjunto de estr\u00edas, que puede ser cero o una longitud fija. Asimismo, introduce una cara de acoplamiento radial 148, si la hay, y selecciona un valor de especificaci\u00f3n de holgura piloto de 14,5 grados o 30 grados.<br \/>El usuario puede utilizar el rat\u00f3n (110) para modificar el modelo de acoplamiento spline (20). La base de conocimientos del acoplamiento spline contiene una gran cantidad de valores de especificaci\u00f3n posibles y la regla de dise\u00f1o correspondiente. Si el usuario intenta modificar el modelo, este mostrar\u00e1 una advertencia sobre una posible infracci\u00f3n de otra especificaci\u00f3n. En algunos casos, la modificaci\u00f3n podr\u00eda invalidar el dise\u00f1o.<br \/>En el modelo de acoplamiento estriado 20, el usuario introduce especificaciones adicionales de rendimiento. Selecciona las ubicaciones donde se transfiere el par m\u00e1ximo para las estr\u00edas internas y externas 38 y 40. La ubicaci\u00f3n de transferencia de par m\u00e1ximo viene determinada por la configuraci\u00f3n de fijaci\u00f3n de los componentes a los ejes. Una vez seleccionada esta opci\u00f3n, el usuario puede hacer clic en \u00abSiguiente\u00bb para guardar el modelo. Se muestra una vista previa del modelo de acoplamiento estriado 20.<br \/>El modelo 20 representa un acoplamiento estriado. Las especificaciones del acoplamiento estriado se introducen en el orden y la disposici\u00f3n indicados en la pantalla de la interfaz gr\u00e1fica de usuario (GUI) del modelo 20. Una vez introducidas las especificaciones, el programa de software 10 las incorporar\u00e1 al modelo 20. Este es el \u00faltimo paso en la creaci\u00f3n del modelo de acoplamiento estriado.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_2.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>An\u00e1lisis de un modelo de acoplamiento de splines 20<\/h2>\n<p>El an\u00e1lisis de un modelo de acoplamiento spline consiste en introducir sus especificaciones de configuraci\u00f3n y rendimiento. Estas especificaciones pueden generarse mediante otro programa inform\u00e1tico. El software de modelado de producto 10 utiliza entonces su base de conocimientos interna sobre relaciones y restricciones de especificaciones dependientes de la configuraci\u00f3n para crear un modelo param\u00e9trico tridimensional v\u00e1lido 20. Este modelo contiene informaci\u00f3n que describe el n\u00famero y los tipos de dientes spline 32, puntos de anclaje 34 y hombro 36.<br \/>Al analizar un acoplamiento de spline, el programa inform\u00e1tico 10 incluye valores predeterminados para diversas especificaciones. El modelo de acoplamiento de spline 20 consta de un spline interno 38 y un spline externo 40. Cada spline incluye su propio conjunto de par\u00e1metros, como profundidad, anchura, longitud y radios. El spline externo 40 tambi\u00e9n contiene su propio conjunto de par\u00e1metros, como su orientaci\u00f3n.<br \/>Tras seleccionar estos par\u00e1metros, el programa inform\u00e1tico realizar\u00e1 diversos an\u00e1lisis sobre el modelo de acoplamiento estriado 20. El programa 10 calcula las tensiones nominales y m\u00e1ximas de apoyo de los dientes, as\u00ed como la vida \u00fatil por fatiga del acoplamiento estriado. Tambi\u00e9n determinar\u00e1 la diferencia en la torsi\u00f3n entre un estriado interno y uno externo. El archivo de salida del an\u00e1lisis ser\u00e1 un informe que contendr\u00e1 la configuraci\u00f3n del modelo y los datos de especificaci\u00f3n. Este archivo tambi\u00e9n podr\u00e1 ser utilizado por otros programas inform\u00e1ticos para an\u00e1lisis posteriores.<br \/>Una vez configurados estos par\u00e1metros, el usuario introduce los criterios de dise\u00f1o para el modelo de acoplamiento estriado 20. En este paso, especifica las ubicaciones de m\u00e1xima transferencia de par para las estr\u00edas 38, tanto externas como internas. La ubicaci\u00f3n de m\u00e1xima transferencia de par depende de la configuraci\u00f3n de los componentes acoplados a los ejes. El usuario puede introducir hasta cuatro especificaciones de requisitos de rendimiento diferentes para cada estr\u00eda.<br \/>Los resultados del an\u00e1lisis muestran dos fases de acoplamiento de las splines. La primera fase presenta un gran aumento de la tensi\u00f3n y la vibraci\u00f3n. La segunda fase muestra una disminuci\u00f3n tanto de la tensi\u00f3n como de la vibraci\u00f3n. La tercera fase muestra una fuerza de engranaje constante de entre 300 N y 320 N. Este comportamiento se mantiene durante un per\u00edodo prolongado, hasta que la fase final se acopla con la superficie.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_2.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>Desalineaci\u00f3n de un acoplamiento spline<\/h2>\n<p>Un estudio tuvo como objetivo investigar la posici\u00f3n de la fuerza de contacto resultante en un acoplamiento estriado que engrana dientes bajo un par constante y una desalineaci\u00f3n rotacional. El estudio emple\u00f3 m\u00e9todos num\u00e9ricos basados \u200b\u200ben modelos de elementos finitos (MEF). Se obtuvieron resultados num\u00e9ricos para condiciones nominales y desalineaci\u00f3n paralela. El estudio consider\u00f3 dos niveles de desalineaci\u00f3n \u20140,02 mm y 0,08 mm\u2014 con diferentes niveles de carga.<br \/>Los resultados mostraron que la desalineaci\u00f3n entre las estr\u00edas y los rotores provoca un cambio en la fuerza de engranaje del sistema de acoplamiento estr\u00eda-rotor. Su din\u00e1mica est\u00e1 regida por la fuerza de engranaje de las estr\u00edas. La fuerza de engranaje de un acoplamiento estr\u00eda desalineado est\u00e1 relacionada con los par\u00e1metros del sistema de acoplamiento rotor-estr\u00eda, el par de transmisi\u00f3n y el desplazamiento de vibraci\u00f3n din\u00e1mica.<br \/>A pesar de la falta de mediciones precisas, la desalineaci\u00f3n de las estr\u00edas es un problema com\u00fan. Este problema se agrava por el hecho de que las estr\u00edas suelen presentar holgura. Esta holgura es consecuencia de la desalineaci\u00f3n de la estr\u00eda. Los autores analizaron varias estr\u00edas con diferentes di\u00e1metros de paso y relaciones longitud\/di\u00e1metro.<br \/>Un acoplamiento estriado es un sistema mec\u00e1nico bidimensional con juego positivo. Consta de un cubo y un eje, y presenta holguras entre la punta y la ra\u00edz mayores que el juego. Una holgura de forma es suficiente para evitar el contacto entre los radios de curvatura de la punta y la ra\u00edz. El par de torsi\u00f3n en las estr\u00edas se transmite por fricci\u00f3n.<br \/>Cuando un acoplamiento estriado se desalinea, se genera una fuerza de empuje con predominio de par. En tal caso, la fuerza puede superar el par, provocando que el componente pierda su alineaci\u00f3n. En este estudio, la transmisi\u00f3n bidireccional de par y empuje se modela anal\u00edticamente. El enfoque anal\u00edtico proporciona soluciones que pueden integrarse en el proceso de dise\u00f1o. Por lo tanto, la pr\u00f3xima vez que se enfrente a un problema de acoplamiento estriado desalineado, \u00a1no olvide utilizar un enfoque anal\u00edtico!<br \/>En este estudio, se analiza el acoplamiento estriado en condiciones nominales sin desalineaci\u00f3n paralela. Los valores de rigidez obtenidos corresponden a la diferencia porcentual entre el di\u00e1metro primitivo nominal y el di\u00e1metro de aplicaci\u00f3n de la carga. Adem\u00e1s, la diferencia porcentual m\u00e1xima en el di\u00e1metro primitivo medido es de 1,60% bajo un par de torsi\u00f3n de 5000 N\u00b7m. El \u00e1ngulo primitivo tambi\u00e9n se considera en el c\u00e1lculo.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"Eje neum\u00e1tico de acero de China con n\u00facleo expandible para inflado y expansi\u00f3n, acoplador de eje de transmisi\u00f3n.\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"Eje neum\u00e1tico de acero de China con n\u00facleo expandible para inflado y expansi\u00f3n, acoplador de eje de transmisi\u00f3n.\t\"><br \/>Editor por czh 21\/02\/2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Problema: NuevoGarant\u00eda: No disponibleIndustrias aplicables: Hoteles, Tiendas de ropa, Tiendas de materiales de construcci\u00f3n, Plantas de fabricaci\u00f3n, Minoristas de reparaci\u00f3n de equipos, Unidades de fabricaci\u00f3n de alimentos y bebidas, Granjas, Cafeter\u00edas, Uso residencial, Comercio minorista, Tiendas de alimentos, Imprentas, Obras de construcci\u00f3n, Energ\u00eda y miner\u00eda, Minoristas de alimentos y bebidas, Otros, Empresas de publicidadPeso (KG): 30Ubicaci\u00f3n de la sala de exposici\u00f3n: Egipto, Canad\u00e1, Turqu\u00eda, Italia, Francia, Alemania, Per\u00fa, Arabia Saudita, Indonesia, Rusia, [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1691,1615,2130,19,620,761,764],"class_list":["post-1082","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-air-shaft","tag-core-shaft","tag-expanding-air-shaft","tag-shaft","tag-shaft-drive","tag-shaft-steel","tag-steel-shaft"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}