{"id":1080,"date":"2023-02-21T03:02:22","date_gmt":"2023-02-21T03:02:22","guid":{"rendered":"http:\/\/splineshaft.top\/china-sf08-customized-precision-motor-shaft-non-standard-cnc-machining-core-stainless-steel-micro-toy-drive-shaft-bushing\/"},"modified":"2023-02-21T03:02:22","modified_gmt":"2023-02-21T03:02:22","slug":"china-sf08-customized-precision-motor-shaft-non-standard-cnc-machining-core-stainless-steel-micro-toy-drive-shaft-bushing","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/es\/china-sf08-customized-precision-motor-shaft-non-standard-cnc-machining-core-stainless-steel-micro-toy-drive-shaft-bushing\/","title":{"rendered":"China SF08 Customized Precision Motor Shaft Non-Standard Cnc Machining Core Stainless Steel Micro Toy     drive shaft bushing"},"content":{"rendered":"<p>Situaci\u00f3n: Nueva<br \/>Garant\u00eda: 1 a\u00f1o<br \/>Relevant Industries: Resorts, Garment Retailers, Creating Material Outlets, Producing Plant, Equipment Fix Stores, Food &amp; Beverage Factory, Farms, Restaurant, House Use, Retail, Meals Shop, Printing Stores, Development works\u00a0, Strength &amp; Mining, Meals &amp; Beverage Retailers, Promoting Business<br \/>Excess weight (KG): five<br \/>Espacio en la sala de exposici\u00f3n: Ninguno<br \/>Movie outgoing-inspection: Not Offered<br \/>Machinery Examination Report: Not Obtainable<br \/>Publicidad y marketing Ordenar por: Nuevo producto 2571<br \/>Warranty of core parts: Not Available<br \/>Elementos principales: PLC, motor, cojinete, caja de engranajes, motor, dep\u00f3sito de presi\u00f3n, equipo, bomba<br \/>Construction: Worm<br \/>Material: steel<br \/>Recubrimientos: N\u00cdQUEL<br \/>Capacidad de torsi\u00f3n: 3600 N<br \/>Design Variety: HTX-Shaft<br \/>Software: Engranajes industriales<br \/>Merchandise identify: Shaft Collar<br \/>Process: Forging+machining+heating Treatment method<br \/>Name: Stainless Steel Cnc Machining Shaft<br \/>Kind: Machining Solutions<br \/>Area Treatment method: Chrome Plating<br \/>Top quality: Substantial Precision<br \/>Dimension: Clients Drawings<br \/>Certificaci\u00f3n: ISO9001<br \/>Shade: Customzied<br \/>Packaging Details: Paper roll,PP Bag, Fabric Bag, Blister box, Carton, Crated Box, Playwood , Tray and so on, ODM packing is satisfactory!<br \/>Port: HangZhou, hongkong<\/p>\n<p>OEM Skilled Custom CNC Milling Provider Aluminum Stainless Steel Components Mountain Bicycle Electrical Scooter Factors Organization Profile <table><tr><td colspan=\"1\" rowspan=\"1\">Company Identify:<\/td><td colspan=\"1\" rowspan=\"1\">HangZhou CZPT Technology Co., Ltd.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Total Building:<\/td><td colspan=\"1\" rowspan=\"1\">12000 Square Meters<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Experience:<\/td><td colspan=\"1\" rowspan=\"1\">23 A long time (Because 1998)<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Equipments:<\/td><td colspan=\"1\" rowspan=\"1\">CNC turning, Auto-Lathes, CNC Machining Centre, Stamping Machines, CNC spring machining, cnc cuting equipment, welding equipment, Hydraulic push, CZPT polishing machine, auto-milling equipment, Driling Equipment, Heading Devices, Slotting Devices,Tapping Equipment, 44305-T9A-T03 Higher High quality Car Areas Front CV Axle Shaft Assembly for Honda JAZZ IV Fit Chamfering Machines, Grinder Devices,Polishing Machine and so on<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Testing Equipments:<\/td><td colspan=\"1\" rowspan=\"1\">3D measuring equipment, Top Gage, Coordinate Measuring Device, Hardness Tester, Video Measuring Device, Roughness Tester, Torsion Tester, Salt Spray Tester,Slide caliper, Micrometer.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Material:<\/td><td colspan=\"1\" rowspan=\"1\">Titanium Alloy, Brass, Bronze, Copper, Aluminum, Mild Steel, Stainless Steel, A366, Alloy, Carbon metal, Abdominal muscles, Personal computer, PEEK, PPS, PPS GF40, PPS GF30, POM, PET and so on.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Tratamiento de superficie:<\/td><td colspan=\"1\" rowspan=\"1\">Zinc Plating, Nickel Plating,Chrome Plating, Passivation, Hardening, Anodizing, Black Oxide Coating,Degreasing, Brushing, Electronic Sprucing, Powder Coating, Gold plating, CZPT Sharpening, PVD Coating<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Proceso de dar un t\u00edtulo:<\/td><td colspan=\"1\" rowspan=\"1\">GB \/ T19001-2016 \/ ISO9001:2015 CertificateNo.3571Q0 0571 R0S, SG S Factory Certification<\/td><\/tr><\/table> Perfil de la empresa <table><tr><td colspan=\"1\" rowspan=\"1\">Company Title:<\/td><td colspan=\"1\" rowspan=\"1\">HangZhou CZPT Technology Co., Ltd.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Total Building:<\/td><td colspan=\"1\" rowspan=\"1\">12000 Square Meters<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Experience:<\/td><td colspan=\"1\" rowspan=\"1\">23 A long time (Because 1998)<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Equipments:<\/td><td colspan=\"1\" rowspan=\"1\">CNC turning, Car-Lathes, CNC Machining Middle, Stamping Devices, WH125-6 Bike Sprocket Chain Kit For XIHU (WEST LAKE) DIS.-HONDA MOTORS CNC spring machining, cnc cuting equipment, welding device, Hydraulic push, CZPT polishing device, automobile-milling equipment, Driling Machines, Heading Equipment, Slotting Machines,Tapping Machines, Chamfering Machines, Grinder Equipment,Polishing Machine and so on<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Testing Equipments:<\/td><td colspan=\"1\" rowspan=\"1\">3D measuring device, Height Gage, Coordinate Measuring Machine, Hardness Tester, Video clip Measuring Machine, Roughness Tester, Torsion Tester, Salt Spray Tester,Slide caliper, Micrometer.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Material:<\/td><td colspan=\"1\" rowspan=\"1\">Titanium Alloy, Brass, Bronze, Copper, Aluminum, Moderate Steel, Stainless Steel, A366, Alloy, Carbon steel, Stomach muscles, Laptop, PEEK, PPS, PPS GF40, PPS GF30, POM, PET and so on.<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Surface Treatment method:<\/td><td colspan=\"1\" rowspan=\"1\">Zinc Plating, Nickel Plating,Chrome Plating, Passivation, Hardening, Anodizing, Black Oxide Coating,Degreasing, Brushing, CZPT Personalized stainless metal 35716 Silica sol investment casting and machining joint,precision casting pipe joint Electronic Polishing, Powder Coating, Gold plating, CZPT Polishing, PVD Coating<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Proceso de dar un t\u00edtulo:<\/td><td colspan=\"1\" rowspan=\"1\">GB \/ T19001-2016 \/ ISO9001:2015 CertificateNo.3571Q0 0571 R0S, SG S Factory Certificate<\/td><\/tr><\/table> Customer Opinions FAQ What is your major service?CNC machining services, Metal Stamping Services, Sheet Steel Fabrication, Customized Metal Design Support,Hydraulic Press, CNC Spring, Screws grinding components, assembly serviceWhat\u2019s the normal area treatment?Vibrant Anodizing,Passivation, Chrome, Electroplating, Sharpening, Powder Coating, Blacken, Hardening, Portray and several other remedy of the components.How do you guarantee the quality?100% Lots inspection. CZPT Staff will provide QC report for approval before shipping.We use the Peak Gage, Coordinate Measuring Device, Hardness Tester, Video clip Measuring Device, Roughness Tester, Torsion Tester, Salt Spray Tester and so on to check our goods.Can you problem the drawing?Sure, we can issue the CAD drawing and 3D drawing as for every customer\u2019s ask for or samples.What is your ask for time?1 7 days for samples, and 7-twenty five workdays for bulk productionWhat\u2019s your MOQ?1pcs, a lot more amount, more cheaper price. Why Choose CZPT Metallic <font>1.twenty first a long time in steel machining industrial.2.Various machining equipments to satisfy different metallic machining request.3.Factory price tag with high high quality ISO normal procedure.4.Sophisticated equipment(Renowned Brand name CITIZE N) machining to fulfill large tolerance(\u00b10.002) as client&#8217;s ask for.5.Prompt lead time request.6.Prompt opinions, all enquiry will be replied inside of 24 hrs.7.Wonderful status in machining business, the goods have been exported to American, Japanese, European, Australia, Center East, Africa and so on.8.Low price, tiny income by swift turnover is our business basic principle.9.100% top quality insepction to make sure the good quality for each and every device.ten. R &amp; D group to style the items according customer\u2019 Chinese NMRV 075 Worm Gearbox speed reducer s request.<\/font><\/p>\n<p>\n<h2>Tipos de splines<\/h2>\n<p>Existen cuatro tipos de estr\u00edas: involuta, de chaveta paralela, helicoidal y esf\u00e9rica. Conozca sus caracter\u00edsticas. Si tiene dudas, puede solicitar un presupuesto. Estas estr\u00edas se utilizan com\u00fanmente en la fabricaci\u00f3n de maquinaria especial, reparaciones y otras aplicaciones. La empresa CZPT Manufacturing Company fabrica estos ejes. Somos un fabricante especializado y estaremos encantados de atenderle.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_3.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>Splines involutas<\/h2>\n<p>El perfil estriado evolvente proporciona una estructura m\u00e1s r\u00edgida y duradera, y est\u00e1 disponible en diversos di\u00e1metros y con distintos n\u00fameros de estr\u00edas. Generalmente, se utilizan acero, acero al carbono o titanio como materias primas. Otros materiales, como la fibra de carbono, tambi\u00e9n pueden ser adecuados. Sin embargo, el titanio puede ser dif\u00edcil de producir, por lo que algunos fabricantes elaboran perfiles estriados con otros componentes.<br \/>Cuando se utilizan estr\u00edas en los ejes, evitan que las piezas se separen durante el funcionamiento. Estas caracter\u00edsticas las convierten en una opci\u00f3n ideal para asegurar conjuntos mec\u00e1nicos. Las estr\u00edas con ranuras curvas hacia adentro no tienen esquinas afiladas y, por lo tanto, son menos propensas a romperse o separarse durante el funcionamiento. Estas propiedades les permiten soportar operaciones de alta velocidad, como el frenado, la aceleraci\u00f3n y la inversi\u00f3n de marcha.<br \/>Un estriado macho se equipa con una cara orientada hacia el exterior, y un estriado hembra se inserta a trav\u00e9s del centro. Los dientes del estriado macho suelen tener puntas biseladas para proporcionar holgura en la zona de transici\u00f3n. Los radios y el ancho de los dientes de un estriado macho suelen ser mayores que los de un estriado hembra. Estas especificaciones se encuentran en los manuales de dise\u00f1o ANSI o DIN.<br \/>El espesor efectivo de los dientes de una estr\u00eda depende del error en el perfil de la evolvente y del error de avance. Asimismo, el espaciado entre los dientes y las chavetas de la estr\u00eda puede afectar dicho espesor. Las estr\u00edas evolventes en un eje estriado se dise\u00f1an de manera que al menos el 25 % de los dientes se engranen durante el acoplamiento, lo que resulta en una distribuci\u00f3n uniforme de la carga y el desgaste en la estr\u00eda.<\/p>\n<h2>Splines de clave paralela<\/h2>\n<p>Un eje estriado paralelo presenta una h\u00e9lice de ranuras de igual tama\u00f1o alrededor de su circunferencia. Estas ranuras suelen ser paralelas o de perfil evolvente. Las estr\u00edas minimizan las concentraciones de tensi\u00f3n en las uniones fijas y permiten el movimiento lineal y rotatorio. Las estr\u00edas pueden ser mecanizadas o laminadas en fr\u00edo. Las estr\u00edas laminadas en fr\u00edo son m\u00e1s resistentes que las mecanizadas y se utilizan con frecuencia en aplicaciones que requieren alta resistencia, precisi\u00f3n y una superficie lisa.<br \/>Un eje estriado con chavetas paralelas presenta ranuras y chavetas paralelas al eje del mismo. Este dise\u00f1o es ideal para aplicaciones donde la capacidad de carga es primordial y se requiere un movimiento suave. Un eje estriado con chavetas paralelas puede fabricarse con aceros aleados, que son aleaciones a base de hierro que tambi\u00e9n pueden contener cromo, n\u00edquel, molibdeno, cobre u otros materiales de aleaci\u00f3n.<br \/>Un eje estriado puede utilizarse para transmitir par y proporcionar antirrotaci\u00f3n cuando funciona como gu\u00eda lineal. Estos ejes tienen perfiles cuadrados que encajan con las ranuras de la pieza de acoplamiento, transmitiendo as\u00ed par y rotaci\u00f3n. Adem\u00e1s, su longitud es f\u00e1cilmente ajustable y se utilizan habitualmente en la industria aeroespacial. Su fiabilidad y resistencia a la fatiga lo convierten en una excelente opci\u00f3n para numerosas aplicaciones.<br \/>La principal diferencia entre un eje con estr\u00edas paralelas y un eje con chaveta es que el primero ofrece mayor flexibilidad. Carecen de ranuras, que reducen la capacidad de transmisi\u00f3n de par. Las estr\u00edas distribuyen la carga de manera uniforme a lo largo de los dientes del engranaje, lo que se traduce en una mayor vida \u00fatil del eje. En aplicaciones agr\u00edcolas, la vida \u00fatil del eje es fundamental. La maquinaria agr\u00edcola, por ejemplo, requiere la capacidad de funcionar a altas velocidades durante periodos prolongados.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_3.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>Splines helicoidales involutas<\/h2>\n<p>Las estr\u00edas evolventes son un dise\u00f1o com\u00fan para ejes estriados. Son el tipo m\u00e1s utilizado y se caracterizan por un espaciado uniforme entre sus dientes. Adem\u00e1s, los dientes de este dise\u00f1o son m\u00e1s cortos que los de los ejes con estr\u00edas paralelas, lo que reduce la concentraci\u00f3n de tensiones. Estas estr\u00edas se pueden usar para transmitir potencia a engranajes flotantes o fijos y reducen la concentraci\u00f3n de tensiones en la articulaci\u00f3n fija. Las estr\u00edas evolventes son el tipo m\u00e1s com\u00fan de eje estriado y se utilizan ampliamente en diversas aplicaciones en la industria automotriz, m\u00e1quinas herramienta y otros sectores.<br \/>Los ejes estriados helicoidales de perfil evolvente son ideales para aplicaciones que implican movimiento axial y rotaci\u00f3n. Permiten el acoplamiento y desacoplamiento frontal. Este dise\u00f1o tambi\u00e9n permite un di\u00e1metro mayor que el de un eje estriado paralelo. El resultado es una caja de engranajes de alta eficiencia. Adem\u00e1s de su durabilidad, las estr\u00edas tambi\u00e9n se pueden utilizar en otras aplicaciones que impliquen par y transferencia de energ\u00eda.<br \/>Se puede utilizar un nuevo modelo estad\u00edstico para determinar el n\u00famero de dientes que se acoplan para una carga determinada. Estas estr\u00edas se caracterizan por un ajuste preciso en los di\u00e1metros mayores, lo que transfiere la concentricidad del eje a la estr\u00eda hembra. La estr\u00eda macho tiene puntas biseladas para mayor holgura en la zona de transici\u00f3n. Los manuales de dise\u00f1o ANSI y DIN especifican las diferentes clases de ajuste.<br \/>El dise\u00f1o de las estr\u00edas helicoidales evolventes es similar al de los engranajes, y sus crestas o dientes se acoplan con las ranuras correspondientes de la pieza de acoplamiento. Esto permite la transmisi\u00f3n de par y rotaci\u00f3n a la pieza de acoplamiento, manteniendo la alineaci\u00f3n de ambos componentes. Se utilizan diferentes tipos de estr\u00edas en distintas aplicaciones. Las estr\u00edas pueden tener diferentes alturas de diente.<\/p>\n<h2>Ranuras esf\u00e9ricas de evolvente<\/h2>\n<p>Cuando se utilizan estr\u00edas, permiten que el eje y el cubo se acoplen uniformemente a lo largo de toda la circunferencia del eje. Gracias a la distribuci\u00f3n uniforme de los dientes, la carga que pueden transmitir es homog\u00e9nea y su posici\u00f3n se mantiene constante independientemente de la longitud del eje. Ya sea que el eje se utilice para transmitir par o potencia, las estr\u00edas son una excelente opci\u00f3n. Proporcionan m\u00e1xima resistencia y permiten movimientos lineales o rotatorios.<br \/>Existen tres tipos b\u00e1sicos de estr\u00edas: helicoidales, de corona y de bola. Las estr\u00edas de corona presentan ranuras igualmente espaciadas, con lados de perfil evolvente y paralelos. Las estr\u00edas helicoidales utilizan dientes de perfil evolvente y se emplean frecuentemente en ejes de peque\u00f1o di\u00e1metro. Las estr\u00edas de bola incorporan un rodamiento de bolas en el interior del eje estriado para facilitar el movimiento rotatorio y minimizar la concentraci\u00f3n de tensiones en las uniones fijas.<br \/>Los dos tipos de estr\u00edas se clasifican seg\u00fan las clases de ajuste ANSI. Las estr\u00edas de ra\u00edz redondeada tienen dientes que engranan a lo largo del eje longitudinal de rotaci\u00f3n. Las estr\u00edas de ra\u00edz plana tienen dientes similares, pero est\u00e1n dise\u00f1adas para optimizar la resistencia en usos a corto plazo. Ambos tipos de estr\u00edas son importantes para asegurar que el eje se alinee correctamente y no se desalinee.<br \/>El coeficiente de fricci\u00f3n del cubo es un proceso complejo. Cuando el cubo est\u00e1 descentrado, el centro se mueve de forma predecible pero irregular. Adem\u00e1s, cuando el eje est\u00e1 centrado, el centro puede oscilar entre estar centrado y descentrado. Para compensar esto, el par debe ser suficiente para mantener el eje en su eje durante todos los \u00e1ngulos de rotaci\u00f3n. Si bien las estr\u00edas de lados rectos proporcionan un centrado similar, presentan factores de carga de desalineaci\u00f3n menores.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_3.webp\" alt=\"eje estriado\" width=\"800\" \/><\/p>\n<h2>Ejes con chaveta<\/h2>\n<p>En esencia, los ejes estriados poseen dientes o crestas que encajan entre s\u00ed para transmitir el par motor. Dado que las estr\u00edas no son tan altas como los engranajes evolventes, ofrecen una transmisi\u00f3n de par uniforme. Adem\u00e1s, permiten variaciones de par y rotaci\u00f3n, y mejoran la resistencia al desgaste. Gracias a su durabilidad, los ejes estriados son muy utilizados en la industria aeroespacial, donde proporcionan mayor fiabilidad y una vida \u00fatil m\u00e1s prolongada.<br \/>Los ejes con chaveta est\u00e1n disponibles en diferentes materiales, longitudes y di\u00e1metros. En aplicaciones de transmisi\u00f3n de alta potencia, ofrecen mayor par motor y velocidad de rotaci\u00f3n. El mayor par que generan les permite transmitir potencia a la caja de engranajes. Sin embargo, no son tan duraderos como los ejes estriados, raz\u00f3n por la cual estos \u00faltimos suelen preferirse en estas aplicaciones. Si bien son m\u00e1s caros, son igualmente eficaces en la transmisi\u00f3n de par.<br \/>Los ejes con chavetas paralelas tienen perfiles y nervaduras independientes y se utilizan en aplicaciones que requieren exactitud y precisi\u00f3n. Los ejes con chavetas y estr\u00edas laminadas son m\u00e1s resistentes que los ejes con estr\u00edas cortadas y se utilizan donde la precisi\u00f3n es esencial. Estas estr\u00edas tambi\u00e9n tienen un acabado liso, lo que las convierte en una buena opci\u00f3n para aplicaciones de precisi\u00f3n. Adem\u00e1s, funcionan bien con engranajes y otros sistemas mec\u00e1nicos que requieren una transmisi\u00f3n de par precisa.<br \/>El acero al carbono es otro material utilizado para ejes estriados. Se caracteriza por su maleabilidad y su bajo contenido de carbono, lo que contribuye a un movimiento fiable. Sin embargo, si busca algo m\u00e1s duradero, considere el acero ferroso. Este tipo contiene metales como n\u00edquel, cromo y molibdeno. Es importante recordar que el acero al carbono no es el \u00fanico material a tener en cuenta.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China SF08 Customized Precision Motor Shaft Non-Standard Cnc Machining Core Stainless Steel Micro Toy     drive shaft bushing\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China SF08 Customized Precision Motor Shaft Non-Standard Cnc Machining Core Stainless Steel Micro Toy     drive shaft bushing\t\"><br \/>Editor por czh 21\/02\/2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Situation: NewWarranty: 1 YearRelevant Industries: Resorts, Garment Retailers, Creating Material Outlets, Producing Plant, Equipment Fix Stores, Food &amp; Beverage Factory, Farms, Restaurant, House Use, Retail, Meals Shop, Printing Stores, Development works\u00a0, Strength &amp; Mining, Meals &amp; Beverage Retailers, Promoting BusinessExcess weight (KG): fiveShowroom Spot: NoneMovie outgoing-inspection: Not OfferedMachinery Examination Report: Not ObtainableAdvertising and marketing Sort: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[430,1787,1584,560,1615,1702,1611,446,268,1704,455,456,1520,1110,19,566,620,1279,1521,761,762,1563,763,1446,764,2644],"class_list":["post-1080","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-china-motor","tag-cnc-drive-shaft","tag-cnc-motor","tag-cnc-shaft","tag-core-shaft","tag-drive-motor-shaft","tag-machining-cnc","tag-micro-motor","tag-motor","tag-motor-drive","tag-motor-micro","tag-motor-motor","tag-motor-shaft","tag-precision-shaft","tag-shaft","tag-shaft-cnc","tag-shaft-drive","tag-shaft-machining","tag-shaft-motor","tag-shaft-steel","tag-stainless-shaft","tag-stainless-steel-drive-shaft","tag-stainless-steel-shaft","tag-stainless-steel-shaft-precision","tag-steel-shaft","tag-toy-motor"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts\/1080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/es\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}