{"id":1059,"date":"2023-02-20T09:03:17","date_gmt":"2023-02-20T09:03:17","guid":{"rendered":"http:\/\/splineshaft.top\/china-propeller-shaft-pnfm40e-17056-fit-painier-outboard-motor-40hp-drive-shaft-bushing\/"},"modified":"2023-02-20T09:03:17","modified_gmt":"2023-02-20T09:03:17","slug":"china-propeller-shaft-pnfm40e-17056-fit-painier-outboard-motor-40hp-drive-shaft-bushing","status":"publish","type":"post","link":"https:\/\/splineshaft.top\/de\/china-propeller-shaft-pnfm40e-17056-fit-painier-outboard-motor-40hp-drive-shaft-bushing\/","title":{"rendered":"China Propeller Shaft PNFM40E-17056 fit PAINIER Outboard Motor 40HP     drive shaft bushing"},"content":{"rendered":"<p>Zustand: Neu<br \/>Garantie: Nicht verf\u00fcgbar<br \/>Relevant Industries: Manufacturing Plant, Machinery Mend Outlets, Farms, House Use, Development performs<br \/>Weight (KG): .744<br \/>Ausstellungsraum: Keiner<br \/>Video outgoing-inspection: Supplied<br \/>Equipment Test Report: Presented<br \/>Advertising Type: Hot Solution 2019<br \/>Warranty of main factors: Not Accessible<br \/>Main Parts: Gear<br \/>Framework: Spline<br \/>Materials: OCr17Ni4Cu4Nb, 20CrMnTi<br \/>Coatings: polishing<br \/>Torque Capacity: <br \/>Product Quantity: PNFM40E-17056<br \/>Teeth Quantity: 20T<br \/>Module: 1<br \/>Excess weight: 744g<br \/>Packing: 4*4*40cm<br \/>Solution name: propeller shaft<br \/>OEM: PNFM40E-17056<br \/>Hardness: 57-60<br \/>Following Warranty Support: On the web assist<br \/>Hafen: HangZhou\/ZheJiang <\/p>\n<p> <font face=\"Georgia\" color=\"#58b183\">1\u3001We have Yamaha\/Tohatsu\/Suzuki Maritime spare areas.<\/font><font face=\"Georgia\" color=\"#58b183\">2\u3001At the very same time, we are also the original provider of Parsun\/Hidea.3\u3001 In purchase to quote a lot more effectively, you should send us your amount and OEM amount or photos when you seek advice from us, thank you!4\u3001Also, if you need to have freight, please enable us know your country and zip code.<\/font> <table><tr><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Emaille<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Z<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">13T<\/font><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Modul<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">m<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">1.five<\/font><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Entire diameter<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Dee<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">\u1d1325<\/font><\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Small diameter<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">Die<\/font><\/td><td colspan=\"1\" rowspan=\"1\"><font face=\"\u9ed1\u4f53\" color=\"#865c5c\">\u1d1312<\/font><\/td><\/tr><\/table> <font><\/font><font><font><\/font><font><\/font>66T-45631-00<\/font>CLUTCH Puppy <font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\"><\/font><font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\"><\/font><font color=\"#666666\"><\/font><\/p>\n<li>66T-45560-00<br \/><\/li><\/UL><font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\"><\/font><font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\">66T-45551-00<\/font><font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\"><\/font><font color=\"#666666\" face=\"Arial, Microsoft YaHei, 5FAE\u8f6f\u96c5\u9ed1, 5B8B\u4f53, Malgun Gothic, Meiryo, sans-serif\"><\/font><font color=\"#666666\">66T-45570-00<\/font>\n<li><\/li>\n<li>outboard gears<br \/><\/li><\/UL> Organization Introduction <font face=\"Arial\"><\/font><font face=\"Arial\"><font face=\"Arial\"><\/font> Established in 2016,HangZhou gill transmission components business is a maker specialized in the study,growth andproduction of gear. We are positioned in ZHangZhoug,with handy transporttation accessibility.<\/font> <font face=\"\u5b8b\u4f53\"><\/font><font face=\"Times New Roman\"> Business formerly identified as Xihu (West Lake) Dis. HangZhou equipment manufacturing unit, was established in 1997, has 20 several years of equipment manufacturing encounter HangZhou full established of imported processing gear.<\/font><font face=\"Times New Roman\"> HangZhou gill transmission parts firm move to a new factory, recognized in 2016 .Common workshop much more than20-5 thousand square, addresses an area of far more than 15 thousand sq. meters.<\/font> Why Select Us <font>Our Services &amp; Power<\/font><font>1\u3001Our organization has been delivering outboard equipment fittings for China&#8217;s outboard machinery assembly plant for a extended time.<\/font>2\u3001We have YAMAHA, SUZUKI, TOHATSU and other outboard machinery components, as nicely as the HIDEA, PARSUN, PANIR and other outboard machinery accessories of the original factory.3\u3001 we can do personalized processing for you.<font>4\u3001The good quality of our merchandise is stable, and we have lengthy-term buyers in Russia, Spain, Africa and other places.<\/font> Related Goods Exhibition Packing&amp;Delivery Certifications FAQ <font>1. Solution ORIGIN?All of our merchandise are created in China.<\/font><font>2. Mindestbestellmenge?<\/font><font>MOQ is not the same for different merchandise.3. Supply TIME?Delivery time is dependent on the genuine orders, usually we have stock, received the deposit 7-fifteen times right after delivery.4. WHAT IS THE Package FOR Products?a. QTY much less than MOQ: neutral bundle or our box package.b. QTY much more than MOQ: our package or in accordance to client&#8217;s need.c. Shipping Mark: standard mark or according to client&#8217; SK45SR Collection Excavator Undercarriage Elements Loafer Track Team Leading Roller Sprocket Observe Bottom Roller For CZPT Digger Chassis s necessity.<\/font>\n<p>\n<h2>Analytische Ans\u00e4tze zur Absch\u00e4tzung von Kontaktdr\u00fccken in Keilwellenkupplungen<\/h2>\n<p>Eine Keilwellenkupplung ist eine mechanische Verbindung zwischen zwei rotierenden Wellen. Sie besteht aus zwei Teilen \u2013 einem Kupplungsk\u00f6rper und einem Kupplungsst\u00fcck. Beide Teile weisen Verzahnungen auf, die ineinandergreifen und Lasten \u00fcbertragen. Keilwellenkupplungen sind jedoch typischerweise \u00fcberdimensioniert, wodurch sie anf\u00e4llig f\u00fcr Materialerm\u00fcdung und statische Belastungen werden. Auch Verschlei\u00dferscheinungen k\u00f6nnen zum Ausfall der Kupplung f\u00fchren. Daher ist eine korrekte Auslegung der Keilwellenkupplung f\u00fcr eine optimale Leistung unerl\u00e4sslich.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/T_splineshaft_2.webp\" alt=\"Keilwelle\" width=\"800\" \/><\/p>\n<h2>Modellierung einer Spline-Kopplung<\/h2>\n<p>Keilwellenkupplungen erfreuen sich in der Luft- und Raumfahrtindustrie zunehmender Beliebtheit, arbeiten jedoch in einem leicht dezentrierten Zustand, was sowohl Vibrationen als auch Besch\u00e4digungen der Kontaktfl\u00e4chen verursacht. Um dieses Problem zu l\u00f6sen, bietet dieser Artikel analytische Ans\u00e4tze zur Absch\u00e4tzung der Kontaktdr\u00fccke in einer Keilwellenkupplung. Insbesondere werden analytische Ans\u00e4tze mit rein numerischen Ans\u00e4tzen verglichen, um die Vorteile des analytischen Ansatzes aufzuzeigen.<br \/>Um eine Spline-Kopplung zu modellieren, erstellen Sie zun\u00e4chst die Wissensbasis f\u00fcr diese Kopplung. Die Wissensbasis enth\u00e4lt eine Vielzahl m\u00f6glicher Spezifikationswerte, die miteinander in Beziehung stehen. Die \u00c4nderung einer Spezifikation kann eine Warnung wegen Verletzung einer anderen ausl\u00f6sen. Damit die Konstruktion g\u00fcltig ist, m\u00fcssen Sie ein Spline-Kopplungsmodell erstellen, das die vorgegebenen Spezifikationswerte erf\u00fcllt.<br \/>Nachdem Sie die Geometrie modelliert haben, m\u00fcssen Sie die Kontaktpressungen der beiden Keilwellenkupplungen eingeben. Anschlie\u00dfend bestimmen Sie die Position des Teilkreises der Keilwelle. In Abbildung 2 ist der Mittelpunkt der m\u00e4nnlichen Kupplung mit dem der weiblichen Keilwelle \u00fcberlagert. Stellen Sie sicher, dass der Eingriffsabstand der beiden Keilwellen gleich ist.<br \/>Sobald Sie die ben\u00f6tigten Daten f\u00fcr die Erstellung eines Keilwellenkupplungsmodells haben, k\u00f6nnen Sie mit der Eingabe der Spezifikationen f\u00fcr die Schnittstellenkonstruktion beginnen. Anschlie\u00dfend w\u00e4hlen Sie, ob die Innen- oder die Au\u00dfenkeilwelle optimiert werden soll. Au\u00dferdem m\u00fcssen Sie den Zahnreibungskoeffizienten angeben, der zur Bestimmung der Spannungen im Keilwellenkupplungsmodell 20 verwendet wird. Geben Sie zudem das Pilotspiel an, also den Abstand zwischen der Zahnspitze 186 eines Zahns 32 auf der einen Keilwelle und dem entsprechenden Merkmal auf der Gegenkeilwelle.<br \/>Nachdem Sie die gew\u00fcnschten Spezifikationen f\u00fcr die Au\u00dfenverzahnung eingegeben haben, k\u00f6nnen Sie die Parameter f\u00fcr die Innenverzahnung festlegen. Beispielsweise k\u00f6nnen Sie den Au\u00dfendurchmesser 154 des Hauptschnappers 54 und den Nebenschnapper 56 der Innenverzahnung eingeben. Die Werte dieser Parameter werden in farbcodierten Feldern auf dem Bildschirm 80 der Benutzeroberfl\u00e4che f\u00fcr Verzahnungseingaben und -konfiguration angezeigt. Nach der Eingabe der Parameter wird Ihnen eine geometrische Darstellung des Verzahnungskupplungsmodells 20 angezeigt.<\/p>\n<h2>Erstellung eines Spline-Kopplungsmodells 20<\/h2>\n<p>Das Spline-Kopplungsmodell 20 wird von der Produktmodellierungssoftware 10 erstellt. Die Software validiert das Spline-Kopplungsmodell anhand einer Wissensdatenbank mit konfigurationsabh\u00e4ngigen Spezifikationsbeschr\u00e4nkungen und -beziehungen. Dieser Bericht wird anschlie\u00dfend in das ANSYS-Spannungsanalyseprogramm eingegeben. Er listet die geometrischen Konfigurationen und Spezifikationswerte des Spline-Kopplungsmodells 20 f\u00fcr jedes Merkmal auf. Das Spline-Kopplungsmodell 20 wird automatisch neu erstellt, sobald die Konfiguration oder die Leistungsspezifikationen des Spline-Kopplungsmodells 20 ge\u00e4ndert werden.<br \/>Das Keilwellenkupplungsmodell 20 kann mithilfe der Produktmodellierungssoftware 10 konfiguriert werden. Der Benutzer gibt die axiale L\u00e4nge des Keilwellenpakets an, die null oder eine feste L\u00e4nge sein kann. Er gibt au\u00dferdem gegebenenfalls eine radiale Passfl\u00e4che 148 ein und w\u00e4hlt einen Wert f\u00fcr das Pilotspiel von 14,5 Grad oder 30 Grad.<br \/>Der Benutzer kann anschlie\u00dfend mit der Maus (110) das Spline-Kopplungsmodell (20) bearbeiten. Die Wissensdatenbank f\u00fcr Spline-Kopplungen enth\u00e4lt zahlreiche m\u00f6gliche Spezifikationswerte sowie die Entwurfsregel f\u00fcr Spline-Kopplungen. Versucht der Benutzer, ein Spline-Kopplungsmodell zu \u00e4ndern, wird eine Warnung \u00fcber einen Versto\u00df gegen eine andere Spezifikation angezeigt. In manchen F\u00e4llen kann die \u00c4nderung den Entwurf ung\u00fcltig machen.<br \/>Im Keilwellenkupplungsmodell 20 gibt der Benutzer zus\u00e4tzliche Leistungsanforderungen ein. Er w\u00e4hlt die Stellen, an denen das maximale Drehmoment f\u00fcr die Innen- und Au\u00dfenverzahnung 38 und 40 \u00fcbertragen wird. Die Position der maximalen Drehmoment\u00fcbertragung wird durch die Befestigungskonfiguration der Komponenten an den Wellen bestimmt. Nach der Auswahl kann der Benutzer auf \u201eWeiter\u201c klicken, um das Modell zu speichern. Eine Vorschau des Keilwellenkupplungsmodells 20 wird angezeigt.<br \/>Das Modell 20 stellt eine Keilwellenkupplung dar. Die Keilwellenspezifikationen werden in der auf der Benutzeroberfl\u00e4che des Keilwellenkupplungsmodells 20 festgelegten Reihenfolge und Anordnung eingegeben. Nach der Eingabe der Keilwellenkupplungsspezifikationen integriert die Produktmodellierungssoftware 10 diese in das Keilwellenkupplungsmodell 20. Dies ist der letzte Schritt bei der Erstellung des Keilwellenkupplungsmodells.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/C_splineshaft_2.webp\" alt=\"Keilwelle\" width=\"800\" \/><\/p>\n<h2>Analyse eines Spline-Kopplungsmodells 20<\/h2>\n<p>Die Analyse eines Keilwellenkupplungsmodells umfasst die Eingabe seiner Konfigurations- und Leistungsspezifikationen. Diese Spezifikationen k\u00f6nnen von einem anderen Computerprogramm generiert werden. Das Produktmodellierungsprogramm 10 nutzt anschlie\u00dfend seine interne Wissensbasis mit konfigurationsabh\u00e4ngigen Spezifikationsbeziehungen und -beschr\u00e4nkungen, um ein g\u00fcltiges dreidimensionales parametrisches Modell 20 zu erstellen. Dieses Modell enth\u00e4lt Informationen, die die Anzahl und Art der Keilwellenz\u00e4hne 32, Schnappverbindungen 34 und Schulterverbindungen 36 beschreiben.<br \/>Bei der Analyse einer Keilwellenkupplung enth\u00e4lt das Softwareprogramm 10 Standardwerte f\u00fcr verschiedene Spezifikationen. Das Keilwellenkupplungsmodell 20 besteht aus einer inneren Keilwelle 38 und einer \u00e4u\u00dferen Keilwelle 40. Jede Keilwelle verf\u00fcgt \u00fcber eigene Parameter wie Tiefe, Breite, L\u00e4nge und Radien. Die \u00e4u\u00dfere Keilwelle 40 besitzt ebenfalls eigene Parameter, beispielsweise ihre Ausrichtung.<br \/>Nach Auswahl dieser Parameter f\u00fchrt das Softwareprogramm verschiedene Analysen am Keilwellenkupplungsmodell 20 durch. Das Programm 10 berechnet die nominalen und maximalen Zahnlagerspannungen sowie die Dauerfestigkeit einer Keilwellenkupplung. Es ermittelt au\u00dferdem den Unterschied in der Torsionsverwindung zwischen einer Innen- und einer Au\u00dfenverzahnung. Die Ausgabedatei der Analyse ist ein Bericht mit Modellkonfigurations- und Spezifikationsdaten. Diese Ausgabedatei kann auch von anderen Computerprogrammen f\u00fcr weiterf\u00fchrende Analysen verwendet werden.<br \/>Sobald diese Parameter festgelegt sind, gibt der Benutzer die Auslegungskriterien f\u00fcr das Keilwellenkupplungsmodell 20 ein. In diesem Schritt legt er die Positionen der maximalen Drehmoment\u00fcbertragung f\u00fcr die \u00e4u\u00dfere und innere Keilwelle 38 fest. Die Position der maximalen Drehmoment\u00fcbertragung h\u00e4ngt von der Konfiguration der an den Wellen befestigten Komponenten ab. Der Benutzer kann bis zu vier verschiedene Leistungsanforderungen f\u00fcr jede Keilwelle angeben.<br \/>Die Analyseergebnisse zeigen zwei Phasen der Spline-Kopplung. In der ersten Phase kommt es zu einem starken Anstieg von Spannung und Vibration. In der zweiten Phase sinken beide Werte wieder. Die dritte Phase zeigt eine konstante Eingriffskraft zwischen 300 N und 320 N. Dieses Verhalten setzt sich \u00fcber einen l\u00e4ngeren Zeitraum fort, bis die letzte Stufe den Eingriff mit der Oberfl\u00e4che herstellt.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/B_splineshaft_2.webp\" alt=\"Keilwelle\" width=\"800\" \/><\/p>\n<h2>Fehlausrichtung einer Keilwellenkupplung<\/h2>\n<p>Ziel einer Studie war die Untersuchung der Position der resultierenden Kontaktkraft in einer Keilwellenkupplung unter konstantem Drehmoment und rotierender Fluchtungsabweichung. Die Studie nutzte numerische Methoden auf Basis der Finite-Elemente-Methode (FEM). Sie lieferte numerische Ergebnisse f\u00fcr Nennbedingungen und parallele Fluchtungsabweichung. Dabei wurden zwei Fluchtungsabweichungen \u2013 0,02 mm und 0,08 mm \u2013 bei unterschiedlichen Belastungsniveaus betrachtet.<br \/>Die Ergebnisse zeigten, dass die Fehlausrichtung zwischen den Keilwellen und Rotoren eine \u00c4nderung der Eingriffskraft des Keilwellen-Rotor-Kopplungssystems bewirkt. Dessen Dynamik wird durch die Eingriffskraft der Keilwellen bestimmt. Die Eingriffskraft einer fehlausgerichteten Keilwellenkupplung h\u00e4ngt von den Systemparametern des Rotor-Keilwellen-Kopplungssystems, dem \u00fcbertragenen Drehmoment und der dynamischen Schwingungsamplitude ab.<br \/>Trotz fehlender pr\u00e4ziser Messungen ist die Fehlausrichtung von Keilwellen ein h\u00e4ufiges Problem. Versch\u00e4rft wird dieses Problem dadurch, dass Keilwellen \u00fcblicherweise Spiel aufweisen. Dieses Spiel ist die Folge der Fehlausrichtung der Keilwelle. Die Autoren analysierten mehrere Keilwellen mit unterschiedlichen Teilkreisdurchmessern und L\u00e4ngen-\/Durchmesserverh\u00e4ltnissen.<br \/>Eine Keilwellenkupplung ist ein zweidimensionales mechanisches System mit positivem Zahnflankenspiel. Sie besteht aus Nabe und Welle und weist ein Spiel zwischen Keilwelle und Keilwellenfu\u00df auf, das gr\u00f6\u00dfer als das Zahnflankenspiel ist. Ein Formspiel verhindert den Kontakt zwischen Keilwelle und Keilwellenfu\u00df. Das Drehmoment auf die Keilwellen wird durch Reibung \u00fcbertragen.<br \/>Bei einer fehlerhaft ausgerichteten Keilwellenkupplung entsteht eine drehmomentbehaftete Schubkraft. In diesem Fall kann die Kraft das Drehmoment \u00fcbersteigen und zum Verlust der Ausrichtung des Bauteils f\u00fchren. Die bidirektionale \u00dcbertragung von Drehmoment und Schubkraft wird in der vorliegenden Studie analytisch modelliert. Der analytische Ansatz liefert L\u00f6sungen, die in den Konstruktionsprozess integriert werden k\u00f6nnen. Wenn Sie also das n\u00e4chste Mal mit einem Problem einer fehlerhaft ausgerichteten Keilwellenkupplung konfrontiert sind, sollten Sie unbedingt einen analytischen Ansatz verwenden!<br \/>In dieser Studie wird die Keilwellenkupplung unter Nennbedingungen ohne parallele Versatzverschiebung analysiert. Die ermittelten Steifigkeitswerte entsprechen der prozentualen Abweichung zwischen dem Nenn-Teilkreisdurchmesser und dem Lastangriffsdurchmesser. Die maximale prozentuale Abweichung des gemessenen Teilkreisdurchmessers betr\u00e4gt 1,60% bei einem Drehmoment von 5000 Nm. Der Teilkreiswinkel wird in die Berechnung einbezogen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l1.webp\" alt=\"China Propeller Shaft PNFM40E-17056 fit PAINIER Outboard Motor 40HP     drive shaft bushing\t\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/spline_shaft\/spline_shaft_l2.webp\" alt=\"China Propeller Shaft PNFM40E-17056 fit PAINIER Outboard Motor 40HP     drive shaft bushing\t\"><br \/>Bearbeitet von czh am 20.02.2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Condition: NewWarranty: UnavailableRelevant Industries: Manufacturing Plant, Machinery Mend Outlets, Farms, House Use, Development performsWeight (KG): .744Showroom Place: NoneVideo outgoing-inspection: SuppliedEquipment Test Report: PresentedAdvertising Type: Hot Solution 2019Warranty of main factors: Not AccessibleMain Parts: GearFramework: SplineMaterials: OCr17Ni4Cu4Nb, 20CrMnTiCoatings: polishingTorque Capacity: Product Quantity: PNFM40E-17056Teeth Quantity: 20TModule: 1Excess weight: 744gPacking: 4*4*40cmSolution name: propeller shaftOEM: PNFM40E-17056Hardness: 57-60Following Warranty Support: [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2601,430,1702,268,1704,456,1339,1520,2575,1341,1342,2246,375,19,620,1521,378],"class_list":["post-1059","post","type-post","status-publish","format-standard","hentry","category-product-catalog","tag-40hp-outboard-motor","tag-china-motor","tag-drive-motor-shaft","tag-motor","tag-motor-drive","tag-motor-motor","tag-motor-outboard","tag-motor-shaft","tag-motor-shaft-outboard","tag-outboard-motor","tag-outboard-motor-outboard","tag-outboard-shaft","tag-propeller-shaft","tag-shaft","tag-shaft-drive","tag-shaft-motor","tag-shaft-propeller"],"_links":{"self":[{"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/posts\/1059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/comments?post=1059"}],"version-history":[{"count":0,"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/posts\/1059\/revisions"}],"wp:attachment":[{"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/media?parent=1059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/categories?post=1059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/splineshaft.top\/de\/wp-json\/wp\/v2\/tags?post=1059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}